{"id":21679,"count":1,"description":"","link":"https:\/\/dimensionturistica.com\/es\/tag\/confinamiento-nacional-en-brasil\/","name":"confinamiento nacional en Brasil","slug":"confinamiento-nacional-en-brasil","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags\/21679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts?tags=21679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}