{"id":92051,"date":"2021-03-08T00:21:34","date_gmt":"2021-03-08T00:21:34","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=92051"},"modified":"2021-03-08T00:21:34","modified_gmt":"2021-03-08T00:21:34","slug":"china-niega-que-este-fabricando-una-maquina-del-tiempo-pero-tecnologia","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/china-niega-que-este-fabricando-una-maquina-del-tiempo-pero-tecnologia\/","title":{"rendered":"China niega que est\u00e9 fabricando una m\u00e1quina del tiempo, pero&#8230; | Tecnolog\u00eda"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Oficialmente, China no est\u00e1 fabricando una m\u00e1quina del tiempo. Que un academia oficial estatal lance este comunicado, ya levanta sospechas&#8230;<\/p>\n<\/p><\/div>\n<div>\n<p>El viejo sue\u00f1o de<strong> viajar en el tiempo<\/strong>, ese concepto tan propio del ser humano. Un reconocimiento inconsciente de nuestra imperfecci\u00f3n. Cometemos errores, y nuestra conciencia nos pide corregirlos. Pero no se pueden corregir los errores del pasado&#8230; \u00bfo tal vez s\u00ed? China lo har\u00e1 en un plazo de 3 a\u00f1os. O al menos eso cube un powerpoint que estas semanas ha circulado por Web&#8230;<\/p>\n<p>La rocambolesca historia se habr\u00eda quedado en otra<em> faux new<\/em> de Web (otra m\u00e1s), si no llega a ser porque hasta la mism\u00edsima <strong>Academia de las Ciencias china ha tenido que desmentir que est\u00e9 fabricando una m\u00e1quina del tiempo<\/strong>.<\/p>\n<p>La absurda trama comenz\u00f3 hace tres semanas, cuando se filtr\u00f3 en las redes sociales chinas <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/6park.news\/en\/this-company-wants-to-build-a-time-machine-of-200-million-with-a-technical-valuation-of-5-4-trillion-chinese-academy-of-sciences-refutes-rumors-news-cnbeta-com.html\">un supuesto documento estatal<\/a>, en formato powerpoint, en donde se explicaba que el Instituto de F\u00edsica de Altas Energ\u00edas de la Academia de Ciencias de China, en colaboraci\u00f3n con una empresa de tecnolog\u00eda llamada Shanxi Ruitai Expertise, <strong>estaban desarrollando una m\u00e1quina del tiempo<\/strong>. El documento explica, en detalle, todo el proceso de construcci\u00f3n y la teor\u00eda que hay detr\u00e1s:<\/p>\n<p>Seg\u00fan este powerpoint, se han invertido m\u00e1s de 30 millones de euros para comprar un terreno de 16 acres y levantar un laboratorio en donde construir &#8220;<em>un dispositivo que puede distorsionar el tiempo y el espacio, controlar el flujo del tiempo, romper la barrera del tiempo y el espacio, y puede ser ampliamente utilizado para viajes en el tiempo, viajes interestelares, extensi\u00f3n de la vida, etc.<\/em>&#8220;.<\/p>\n<p>La <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/computerhoy.com\/noticias\/life\/viajar-tiempo-es-posible-segun-matematicas-61658\" title=\"Viajar en el tiempo es posible, seg\u00fan las matem\u00e1ticas\">teor\u00eda que hay detr\u00e1s<\/a> de este dispositivo se apoya en la Teor\u00eda de la Relatividad de Einstein para <strong>crear agujeros de gusano desde los cuales se podr\u00eda viajar en el tiempo<\/strong>. El documento est\u00e1 tan convencido de su \u00e9xito que incluso apunta a unas ganancias de 838.000 millones de euros en conceptos como viajes en el tiempo privados, viajes interestelares, and so on. Y a\u00fan va m\u00e1s lejos: <strong>los primeros resultados llegar\u00edan en solo tres a\u00f1os.<\/strong><\/p>\n<div data-embed-button=\"product\" data-entity-embed-display=\"entity_reference:entity_reference_entity_view\" data-entity-embed-display-settings=\"default\" data-entity-type=\"product\" data-entity-uuid=\"88d0918b-90b5-48eb-ad53-4b4577132811\" data-langcode=\"es\" class=\"embedded-entity product default\">\n<article class=\"embedded-minicard\">\n<figure class=\"minicard-image\">\n      <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/computerhoy.com\/listas\/entretenimiento\/inventos-ciencia-ficcion-del-cine-501217\" title=\"9 inventos de ciencia-ficci\u00f3n que nos dejaron sin habla en el cine\" data-gacat=\"Tarjetas\"><\/p>\n<p>      <\/a><br \/>\n    <\/figure>\n<div class=\"inner-container\">\n<p>Ahora nos parecen lo m\u00e1s regular del mundo, pero hace 30 o 40 a\u00f1os los espectadores que acud\u00edan al cine y ve\u00edan por vez primera un tel\u00e9fono m\u00f3vil, unas gafas de realidad digital o una impresora 3D, se quedaban alucinados. Estos son los inventos de cine que nos dejaron con la boca abierta.<\/p>\n<\/p><\/div>\n<\/article>\n<\/div>\n<p>Lo que se cuenta aqu\u00ed es te\u00f3ricamente posible. El problema es que <strong>a d\u00eda de hoy es solo teor\u00eda, ciencia-ficci\u00f3n<\/strong>. No existe tecnolog\u00eda para hacer esto. Ni se espera que exista en d\u00e9cadas, si es que alguna vez se consigue.<\/p>\n<p>Adem\u00e1s el documento cita nombres de personas involucradas en el proyecto, como &#8220;<em>el Premio Nobel de F\u00edsica Gao Kun<\/em>&#8220;, que no existen. Pero entonces, \u00bfpor qu\u00e9 el Instituto de F\u00edsica de Altas Energ\u00edas de la Academia de Ciencias de China ha lanzado un comunicado desmintiendo que est\u00e9 fabricando una m\u00e1quina del tiempo, si el powerpoint se cae por s\u00ed mismo?<\/p>\n<p>En <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.yicaiglobal.com\/news\/china-state-physics-lab-denies-it-is-working-on-a-time-machine-\">el comunicado<\/a>, la Academia asegura que &#8220;<em>no es cierto que nuestro instituto y la empresa Shanxi Ruitai Technology mencionada en el art\u00edculo Development Technology Co., Ltd. y su personal hayan tenido alg\u00fan contacto o cooperaci\u00f3n, y nuestra firma no asumir\u00e1 ninguna responsabilidad legal por las p\u00e9rdidas causadas por su falsa propaganda<\/em>&#8220;.<\/p>\n<p>Lo misterioso del asunto es que <strong>la empresa Shanxi Ruitai Expertise existe<\/strong>, fue fundada en diciembre del a\u00f1o pasado por Guo Weiwei, un cient\u00edfico que lleva 13 a\u00f1os investigando los viajes en el tiempo. Y <strong>el documento en powerpoint tambi\u00e9n es actual<\/strong>: la empresa que lo ha creado asegura que es &#8220;<em>un malentendido<\/em>&#8220;, y Shanxi Ruitai Expertise ha dicho que ha roto el contrato que ten\u00eda con ella.<\/p>\n<p>\u00bfHay algo de verdad detr\u00e1s de todo esto? \u00bfO es una easy maniobra publicitaria de Shanxi Ruitai Expertise para darse a conocer?<\/p>\n<p>Lo que parece seguro es que <strong>China no est\u00e1 fabricando una m\u00e1quina del tiempo&#8230; por ahora&#8230;<\/strong><\/p>\n<\/p><\/div>\n\n<p><em> &#8221; Fuentes computerhoy.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oficialmente, China no est\u00e1 fabricando una m\u00e1quina del tiempo. Que un academia oficial estatal lance este comunicado, ya levanta sospechas&#8230; El viejo sue\u00f1o de viajar en el tiempo, ese concepto tan propio del ser humano. Un reconocimiento inconsciente de nuestra imperfecci\u00f3n. Cometemos errores, y nuestra conciencia nos pide corregirlos. Pero no se pueden corregir los [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":92052,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-92051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/92051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=92051"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/92051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/92052"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=92051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=92051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=92051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}