{"id":92046,"date":"2021-03-08T00:04:42","date_gmt":"2021-03-08T00:04:42","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=92046"},"modified":"2021-03-08T00:04:43","modified_gmt":"2021-03-08T00:04:43","slug":"denuncia-lider-nacional-de-agencias-de-viajes-alza-de-fraudes-vacacionales-durante-pandemia","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/denuncia-lider-nacional-de-agencias-de-viajes-alza-de-fraudes-vacacionales-durante-pandemia\/","title":{"rendered":"Denuncia l\u00edder nacional de agencias de viajes alza de fraudes vacacionales durante pandemia"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Canc\u00fan. \u2013 El presidente nacional de la Asociaci\u00f3n Mexicana de Agencias de Viajes (AMAV) Eduardo Paniagua Morales, manifest\u00f3 que los casos de fraude en la venta de paquetes vacacionales aumentaron considerablemente a ra\u00edz de la pandemia.<\/p>\n<p>Dijo que desafortunadamente carecen de un n\u00famero de \u201cempresas\u201d dedicadas a esta actividad il\u00edcita, pero s\u00ed conocimiento de turistas que han sido v\u00edctimas de esta situaci\u00f3n.<\/p>\n<p>Explic\u00f3 que tales \u201cempresas\u201d son entes que ni siquiera est\u00e1n en p\u00e1ginas de web nacionales, pudiendo estar pr\u00e1cticamente en cualquier parte del mundo y a pesar de que la polic\u00eda cibern\u00e9tica detecta esta pr\u00e1ctica, los timadores pueden hacer otras p\u00e1ginas y seguir con esa il\u00edcita actividad.<\/p>\n<p>\u201cLa verdad es que, aunque se hace mucho para contrarrestarlos, es muy complicado tener un porcentaje de estos fraudes, porque no pueden seguirse.<\/p>\n<p>\u201cNo hay forma de darles un rastro, ya que son defraudadores que no tienen un ente constituido, es decir, no podemos localizar sus p\u00e1ginas, no pueden localizarse sus nombres comerciales o nombres reales\u201d, reconoci\u00f3.<\/p>\n<p>Manifest\u00f3 que aquellos turistas que han llegado a ser v\u00edctimas de alg\u00fan fraude por parte de estas \u201cagencias de viaje fantasma\u201d, tienen que acudir a la Fiscal\u00eda Common de la Rep\u00fablica (FGR) o a las autoridades de sus pa\u00edses a levantar la demanda correspondiente.<\/p>\n<p>Sin embargo, Paniagua Morales afirm\u00f3 que la AMAV realiza continuamente diversas campa\u00f1as en las redes sociales, para que cuando los potenciales turistas busquen adquirir un paquete vacacional est\u00e9n m\u00e1s al pendiente.<\/p>\n<p>Sobre todo, si llegan a ver alguna promoci\u00f3n muy atractiva en web, recomendando que las personas deber\u00e1n de cotizar en por lo menos en tres sitios para que corroboren si dicha oferta es actual.<\/p>\n<p>\u201cHay ofertas que son sumamente bajas y eso hace que la gente no lo piense y las adquiera y este es uno de los principales ganchos de estos defraudadores, tambi\u00e9n la gente debe ver en la supuesta p\u00e1gina otros elementos como tel\u00e9fonos y direcciones para que eviten ser una v\u00edctima de tales estafadores\u201d concluy\u00f3.<\/p>\n<p>(Galu Comunicaci\u00f3n)<\/p>\n<\/div>\n\n<p><em> &#8221; Fuentes www.elpuntosobrelai.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Canc\u00fan. \u2013 El presidente nacional de la Asociaci\u00f3n Mexicana de Agencias de Viajes (AMAV) Eduardo Paniagua Morales, manifest\u00f3 que los casos de fraude en la venta de paquetes vacacionales aumentaron considerablemente a ra\u00edz de la pandemia. Dijo que desafortunadamente carecen de un n\u00famero de \u201cempresas\u201d dedicadas a esta actividad il\u00edcita, pero s\u00ed conocimiento de turistas [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":92047,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-92046","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/92046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=92046"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/92046\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/92047"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=92046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=92046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=92046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}