{"id":91384,"date":"2021-03-06T04:14:09","date_gmt":"2021-03-06T04:14:09","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=91384"},"modified":"2021-03-06T04:14:09","modified_gmt":"2021-03-06T04:14:09","slug":"la-provincia-resiste-al-peor-ano-del-turismo-con-el-factor-interior","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/la-provincia-resiste-al-peor-ano-del-turismo-con-el-factor-interior\/","title":{"rendered":"La provincia resiste al peor a\u00f1o del turismo con el factor interior"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<h4>Un informe de la C\u00e1tedra de Turismo de Inside de la UJA sostiene que Ja\u00e9n &#8220;amortigua mejor&#8221; el impacto negativo de la pandemia en el pa\u00eds<\/h4>\n<p>El impacto fue negativo, pero no tanto como en el conjunto regional y nacional. Es la principal conclusi\u00f3n del <strong>informe de la C\u00e1tedra de Turismo de la UJA<\/strong> acerca de c\u00f3mo soport\u00f3 el \u00e1mbito tur\u00edstico de la provincia el a\u00f1o 2020, marcado por la disaster sanitaria. Seg\u00fan el informe, Ja\u00e9n &#8220;amortigua mejor&#8221; el descalabro gracias al auge del turismo de inside entre los viajeros.<\/p>\n<p>La autor\u00eda del estudio corresponde al<strong> Sistema de Inteligencia Tur\u00edstica de la provincia de Ja\u00e9n<\/strong> (SIT-Ja\u00e9n), subvencionado por la Diputaci\u00f3n. De acuerdo con los datos, la ca\u00edda en el n\u00famero de viajero fue del 53,71% y del 49,75% en el n\u00famero de pernoctaciones.<\/p>\n<p>Los establecimientos hoteleros fueron los que m\u00e1s sufrieron la pandemia, mientras que los campings o alojamientos de turismo rural, pese a haber registrado p\u00e9rdidas en las pernoctaciones, recibieron un impacto negativo menor.<\/p>\n<p>El SIT-Ja\u00e9n ha calculado el impacto directo del turismo en la provincia para 2020, que ha superado los 67 millones de euros, lo que significa que los ingresos directos por turismo han ca\u00eddo en casi un 60%, en comparaci\u00f3n con el a\u00f1o 2019<\/p>\n<h3>DEL CONFINAMIENTO AL RESPIRO ESTIVAL<\/h3>\n<p>El informe recuerda oferta de alojamiento en la provincia se vio mermada durante gran parte del pasado a\u00f1o, cayendo a pr\u00e1cticamente cero en abril y mayo, cuando el confinamiento anul\u00f3 al sector.<\/p>\n<p>Posteriormente, la llegada del verano alivi\u00f3 al sector, que recuperaron parte de la actividad. No obstante, a partir de octubre volvieron a caer a niveles situados por debajo del 50%.<\/p>\n<p>En lo que respecta al mercado de trabajo, se produjo una ca\u00edda generalizada del empleo en todos los tipos de alojamientos tur\u00edsticos. En los establecimientos hoteleros, caracterizados por ser los que m\u00e1s private demandan, la ca\u00edda de private fue superior al 20%.<\/p>\n<p>Seg\u00fan el estudio, el descenso fue constante a lo largo de 2020 tanto en contratos fijos como temporales, siendo estos \u00faltimos los m\u00e1s afectados. El segundo trimestre present\u00f3 la mayor tasa de desempleo y, por el contrario, el tercer trimestre, coincidiendo con los meses de verano, la mayor tasa de empleo, siguiendo la tendencia de un a\u00f1o \u2018normal\u2019.<\/p>\n<h3>ESTANCIA, GASTO Y REPUTACI\u00d3N DIGITAL<\/h3>\n<p>El informe se\u00f1ala que los turistas pasan com m\u00e1ximo tres d\u00eda en la provincia y el gasto medio en la provincia por parte de los visitantes contin\u00faa entre los primeros puestos de la regi\u00f3n, con <strong>70 euros de media<\/strong>.<\/p>\n<p>Los destinos con mejor reputaci\u00f3n on-line international de la provincia son <strong>Sierra M\u00e1gina y \u00dabeda<\/strong>. Aunque lo m\u00e1s llamativo es que la calidad percibida por los turistas que se hospedan en establecimientos hoteleros de la provincia es inferior a la que muestran para establecimientos de igual categor\u00eda en destinos competidores.<\/p>\n<p>&#8220;Es una muestra clara de la necesidad de apostar por la mejora de la calidad percibida por los hu\u00e9spedes, ofertando mejores servicios y, si cabe, mejorando las instalaciones&#8221;, concluye el profesor Juan Ignacio Pulido, director de la C\u00e1tedra de Turismo de Inside de la UJA.<\/p>\n<\/div>\n<p><script>(function(d, s, id) {\n          var js, fjs = d.getElementsByTagName(s)[0];\n          if (d.getElementById(id)) return;\n          js = d.createElement(s); js.id = id;\n          js.src = \"https:\/\/connect.facebook.net\/es_ES\/sdk.js#xfbml=1&appId=lacontracronica.es&version=v2.3\";\n          fjs.parentNode.insertBefore(js, fjs);\n        }(document, 'script', 'facebook-jssdk'));<\/script><br \/>\n<br \/><\/p>\n<p><em> &#8221; Fuentes lacontradejaen.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un informe de la C\u00e1tedra de Turismo de Inside de la UJA sostiene que Ja\u00e9n &#8220;amortigua mejor&#8221; el impacto negativo de la pandemia en el pa\u00eds El impacto fue negativo, pero no tanto como en el conjunto regional y nacional. Es la principal conclusi\u00f3n del informe de la C\u00e1tedra de Turismo de la UJA acerca [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":91385,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-91384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/91384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=91384"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/91384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/91385"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=91384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=91384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=91384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}