{"id":91353,"date":"2021-03-06T00:41:23","date_gmt":"2021-03-06T00:41:23","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=91353"},"modified":"2021-03-06T00:41:24","modified_gmt":"2021-03-06T00:41:24","slug":"cancela-american-airlines-rutas-a-uruguay-y-chile","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/cancela-american-airlines-rutas-a-uruguay-y-chile\/","title":{"rendered":"Cancela American Airlines rutas a Uruguay y Chile"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><strong>American Airways<\/strong> extendi\u00f3 la suspensi\u00f3n y cancelaci\u00f3n de varios de sus servicios internacionales, entre los que se encuentran destinos como <strong>Montevideo, Uruguay y Santiago de Chile.\u00a0<\/strong><\/p>\n<p>A detalle, <strong>recortar\u00e1 la capacidad internacional de verano en aproximadamente el 10%,<\/strong> y reducir\u00e1 su oferta <strong>nacional en un 7.5% <\/strong>durante marzo, en respuesta a la baja demanda a\u00e9rea.\u00a0<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\" xml:lang=\"en\">This week we&#8217;re celebrating 50 years of enjoyable within the solar and repair to the <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/Caribbean?src=hash&amp;ref_src=twsrc%5Etfw\">#Caribbean<\/a>. Try the locations we have now been proudly serving since 1971! <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/XkkNyMtfxu\">pic.twitter.com\/XkkNyMtfxu<\/a><\/p>\n<p>\u2014 americanair (@AmericanAir) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/AmericanAir\/status\/1367206928150061084?ref_src=twsrc%5Etfw\">March 3, 2021<\/a><\/p>\n<\/blockquote>\n<p>El vuelo que une <strong>Miami con Montevideo<\/strong> se suspender\u00e1 <strong>desde el 31 de marzo y hasta el 17 de diciembre<\/strong>. Este servicio hab\u00eda sido retomado el 5 de noviembre del a\u00f1o pasado.<\/p>\n<p>Esta suspensi\u00f3n de viajes gener\u00f3 una <strong>preocupaci\u00f3n entre funcionarios del gobierno uruguayo<\/strong>, quienes expresaron que el pa\u00eds requiere las conexiones internacionales para la<strong> reactivaci\u00f3n del turismo native.\u00a0<\/strong><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"es\" xml:lang=\"es\">Hoy manifestamos nuestra preocupaci\u00f3n por la suspensi\u00f3n de los vuelos directo a Estados Unidos. El Uruguay de la submit pandemia necesita conexi\u00f3n para atraer turistas inversores y nuevos residentes. Para ello la conexi\u00f3n es imprescindible. Siempre en el camino nunca en la posada <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/ZuVWDyTnOh\">pic.twitter.com\/ZuVWDyTnOh<\/a><\/p>\n<p>\u2014 Sebastian Da Silva (@camboue) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/camboue\/status\/1367118298861633544?ref_src=twsrc%5Etfw\">March 3, 2021<\/a><\/p>\n<\/blockquote>\n<p>Adem\u00e1s de las rutas a Am\u00e9rica Latina, la aerol\u00ednea estadounidense suspender\u00e1 sus viajes\u00a0a <strong>Roma y Mil\u00e1n<\/strong> (Italia), y reducir\u00e1 sus frecuencias a <strong>Par\u00eds<\/strong> (Francia) y <strong>Madrid<\/strong> (Espa\u00f1a).\u00a0<\/p>\n<p>Por otro lado, American\u00a0<strong>reasignar\u00e1 su flota de fuselaje ancho para vuelos nacionales<\/strong>, e introducir\u00e1 una nueva operaci\u00f3n entre Chicago y Honolulu a bordo de Boeing 787.<\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><script>(function(d, s, id) {\n  var js, fjs = d.getElementsByTagName(s)[0];\n  if (d.getElementById(id)) {return;}\n  js = d.createElement(s); js.id = id;\n  js.src = \"https:\/\/connect.facebook.net\/es_LA\/all.js#xfbml=1\";\n  fjs.parentNode.insertBefore(js, fjs);\n}(document, \"script\", \"facebook-jssdk\"));<\/script><br \/>\n<br \/><\/p>\n<p><em> &#8221; Fuentes a21.com.mx &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>American Airways extendi\u00f3 la suspensi\u00f3n y cancelaci\u00f3n de varios de sus servicios internacionales, entre los que se encuentran destinos como Montevideo, Uruguay y Santiago de Chile.\u00a0 A detalle, recortar\u00e1 la capacidad internacional de verano en aproximadamente el 10%, y reducir\u00e1 su oferta nacional en un 7.5% durante marzo, en respuesta a la baja demanda a\u00e9rea.\u00a0 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":91354,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-91353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/91353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=91353"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/91353\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/91354"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=91353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=91353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=91353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}