{"id":91225,"date":"2021-03-05T20:36:43","date_gmt":"2021-03-05T20:36:43","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=91225"},"modified":"2021-03-05T20:36:43","modified_gmt":"2021-03-05T20:36:43","slug":"emite-eu-alertas-para-evitar-viajes-a-mexico-en-semana-santa","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/emite-eu-alertas-para-evitar-viajes-a-mexico-en-semana-santa\/","title":{"rendered":"Emite EU alertas para evitar viajes a M\u00e9xico en Semana Santa"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>OAXACA, Oax., 5 de marzo de 2021.- El gobierno de Estados Unidos emiti\u00f3 alertas de seguridad y salud para restringir viajes de ciudadanos de su pa\u00eds a M\u00e9xico, durante la Semana Santa 2021.<\/p>\n<figure class=\"wp-block-embed-twitter wp-block-embed is-type-rich is-provider-twitter\"\/>\n<p>Estas alertas se encuentran vigentes para todo M\u00e9xico,<br \/>\nincluyendo los destinos tur\u00edsticos oaxaque\u00f1os, como Huatulco, Puerto Escondido<br \/>\ny la ciudad de Oaxaca, entre otros.<\/p>\n<p>Por medio de un comunicado, la Embajada de Estados Unidos detall\u00f3<br \/>\nque los ciudadanos estadounidenses deben reconsiderar su viaje no esencial a<br \/>\nMexico en periodo de vacaciones de Semana Santa debido a la emergencia<br \/>\nsanitaria de Covid 19.\u00a0 <\/p>\n<p>\u201cLos casos y hospitalizaciones se mantienen altos en la<br \/>\nmayor parte de Mexico.\u00a0 Los servicios<br \/>\nconsulares, como citas de pasaportes de emergencia se encuentran limitados en<br \/>\nmuchos lugares debido a la pandemia\u201d, detall\u00f3.<\/p>\n<p>Asimismo, se\u00f1al\u00f3 que los cruces de Estados Unidos a M\u00e9xico<br \/>\npor tierra est\u00e1n restringidos a viajes esenciales hasta por lo menos el 21 de<br \/>\nmarzo de 2021. <\/p>\n<p>Para aquellos que regresan a los Estados Unidos por aire,<br \/>\nexiste como requisito presentar un examen viral negativo de Covid 19 (ant\u00edgeno<br \/>\no pcr) efectuado con no m\u00e1s de 3 d\u00edas antes de la salida de su vuelo o<br \/>\ncomprobante de recuperaci\u00f3n de Covid 19 a la aerol\u00ednea antes de abordar su<br \/>\nvuelo.\u00a0 <\/p>\n<\/div>\n<p><script>(function(d, s, id) {\n  var js, fjs = d.getElementsByTagName(s)[0];\n  if (d.getElementById(id)) return;\n  js = d.createElement(s); js.id = id;\n  js.src=\"https:\/\/connect.facebook.net\/es_LA\/sdk.js#xfbml=1&version=v3.2&appId=128492274233029&autoLogAppEvents=1\";\n  fjs.parentNode.insertBefore(js, fjs);\n}(document, 'script', 'facebook-jssdk'));<\/script><br \/>\n<br \/><\/p>\n<p><em> &#8221; Fuentes oaxaca.quadratin.com.mx &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>OAXACA, Oax., 5 de marzo de 2021.- El gobierno de Estados Unidos emiti\u00f3 alertas de seguridad y salud para restringir viajes de ciudadanos de su pa\u00eds a M\u00e9xico, durante la Semana Santa 2021. Estas alertas se encuentran vigentes para todo M\u00e9xico, incluyendo los destinos tur\u00edsticos oaxaque\u00f1os, como Huatulco, Puerto Escondido y la ciudad de Oaxaca, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":91226,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-91225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/91225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=91225"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/91225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/91226"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=91225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=91225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=91225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}