{"id":90990,"date":"2021-03-05T13:47:13","date_gmt":"2021-03-05T13:47:13","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=90990"},"modified":"2021-03-05T13:47:13","modified_gmt":"2021-03-05T13:47:13","slug":"250-destinos-del-mundo-con-el-sello-de-turismo-seguro-wttc","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/250-destinos-del-mundo-con-el-sello-de-turismo-seguro-wttc\/","title":{"rendered":"250 destinos del mundo, con el sello de Turismo Seguro WTTC"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"text-align-justify\"><span><span><span><span><span><span><img decoding=\"async\" alt=\"\" class=\"img-responsive\" height=\"640\" src=\"https:\/\/www.expreso.info\/files\/2021-03\/WTTC_Safe_Travels.jpg\" width=\"1154\"\/>El sello ya ha sido otorgado a diversos destinos, como: Argentina, Colombia, Costa Rica, Chile, Per\u00fa, Paraguay, Guatemala, Belice, Kenia, Egipto, Portugal, Sevilla, Madrid, Barcelona, Reino Unido, Jordania, Arabia Saudita, Fiji, Indonesia, Filipinas, Etiop\u00eda, entre otros.<\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p class=\"text-align-justify\"><span><span><span><span><span><span>Tras su lanzamiento en mayo del a\u00f1o pasado, el sello Secure Travels del Consejo Mundial de Viajes y Turismo, WTTC, ha sido otorgado a 250 destinos en todo el mundo.\u00a0\u00a0 <\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p class=\"text-align-justify\"><span><span><span><span><span><span>El distintivo fue desarrollado para ayudar a restaurar la confianza en los viajeros y tiene como objetivo reactivar el sector international de viajes y turismo, que ha sido severamente afectado por la pandemia. <\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p class=\"text-align-justify\"><span><span><span><span><span><span>Ha sido otorgado a diversos destinos, tales como: Argentina, Colombia, Costa Rica, Chile, Per\u00fa, Paraguay, Guatemala, Belice, Kenia, Egipto, Portugal, Sevilla, Madrid, Barcelona, Reino Unido, Jordania, Arabia Saudita, Fiji, Indonesia, Filipinas, Etiop\u00eda, as\u00ed como a diferentes entidades de\u00a0 M\u00e9xico, entre otros.\u00a0\u00a0 <\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p class=\"text-align-justify\"><span><span><span><span><span><span>El sello, ahora reconocido a nivel mundial, permite a los viajeros de negocios y de placer distinguir destinos en todo el mundo que han adoptado los protocolos estandarizados de salud e higiene para que puedan experimentar \u2018viajes seguros\u2019.\u00a0\u00a0 <\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p class=\"text-align-justify\"><span><span><span><span><span><span>Este proyecto del <a rel=\"nofollow noopener\" target=\"_blank\" href=\"http:\/\/www.wttc.org\/\">WTTC <\/a>recibi\u00f3 el respaldo de la Organizaci\u00f3n Mundial del Turismo de las Naciones Unidas, OMT, y el lanzamiento de protocolos globales para recuperar el sector de viajes y turismo ha sido adoptado por m\u00e1s de 200 directores ejecutivos, incluidos algunos de los principales grupos tur\u00edsticos del mundo.\u00a0\u00a0 <\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p class=\"text-align-justify\"><span><span><span><span><span><span>Gloria Guevara, presidenta y CEO del WTTC, asegur\u00f3 que \u2018nos enorgullece ver el gran y creciente recibimiento que ha tenido el <em>Safe Travels stamp<\/em>. Hoy son ya 250 destinos en todo el mundo que han obtenido con orgullo este distintivo global, lo que es testimonio del arduo trabajo que se ha realizado para que esta iniciativa funcione, tanto para los destinos como para los turistas\u2019.\u00a0\u00a0 <\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p class=\"text-align-justify\"><span><span><span><span><span><span>La presidenta del Consejo Mundial de Viajes y Turismo indic\u00f3 que, \u2018a medida que se acelera el lanzamiento mundial de la vacuna y las restricciones de viaje se relajen en las pr\u00f3ximas semanas, el sello ser\u00e1 un componente clave para la recuperaci\u00f3n del sector, a trav\u00e9s del restablecimiento de la confianza del viajero\u2019.\u00a0\u00a0 <\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p class=\"text-align-justify\"><span><span><span><span><span><span>Adem\u00e1s, se\u00f1al\u00f3 que el \u00e9xito del sello muestra la importancia de la coordinaci\u00f3n international para ayudar a reconstruir y reactivar el sector internacional de viajes y turismo. Los destinos con el sello se beneficiar\u00e1n de que los viajeros puedan reconocer que han adoptado los protocolos globales, fomentando el regreso de &#8220;viajes seguros&#8221; en todo el mundo.\u00a0\u00a0 <\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p class=\"text-align-justify\"><span><span><span><span><span><span>\u2018Finalmente estamos comenzando a dar un paso hacia la nueva normalidad de un mundo post-COVID, y es un honor liderar el camino para los esfuerzos de recuperaci\u00f3n coordinados a nivel mundial\u2019, asegur\u00f3 Guevara Manzo.\u00a0\u00a0 <\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p class=\"text-align-justify\"><span><span><span><span><span><span>Los protocolos del WTTC se dise\u00f1aron siguiendo las pautas de la Organizaci\u00f3n Mundial de la Salud (OMS) y el Centro para el Management y la Prevenci\u00f3n de Enfermedades (CDC), y teniendo en cuenta las mejores pr\u00e1cticas de los miembros del Consejo.\u00a0\u00a0 <\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p class=\"text-align-justify\"><span><span><span><span><span><span>Seg\u00fan el Informe de Impacto Econ\u00f3mico 2020 de WTTC, durante 2019, Viajes y Turismo fue responsable de uno de cada 10 puestos de trabajo (330 millones en whole), hizo una contribuci\u00f3n del 10,3% al PIB mundial y gener\u00f3 uno de cada cuatro de todos los nuevos puestos de trabajo.<\/span><\/span><\/span><\/span><\/span><\/span><\/p>\n<p class=\"text-align-justify\"><span><span><span><span><em><span><span>Expreso. Redacci\u00f3n. A.F<\/span><\/span><\/em><\/span><\/span><\/span><\/span><\/p>\n<\/div>\n\n<p><em> &#8221; Fuentes www.expreso.info &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sello ya ha sido otorgado a diversos destinos, como: Argentina, Colombia, Costa Rica, Chile, Per\u00fa, Paraguay, Guatemala, Belice, Kenia, Egipto, Portugal, Sevilla, Madrid, Barcelona, Reino Unido, Jordania, Arabia Saudita, Fiji, Indonesia, Filipinas, Etiop\u00eda, entre otros. Tras su lanzamiento en mayo del a\u00f1o pasado, el sello Secure Travels del Consejo Mundial de Viajes y Turismo, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":90991,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-90990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/90990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=90990"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/90990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/90991"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=90990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=90990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=90990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}