{"id":90947,"date":"2021-03-05T12:23:08","date_gmt":"2021-03-05T12:23:08","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=90947"},"modified":"2021-03-05T12:23:08","modified_gmt":"2021-03-05T12:23:08","slug":"un-surfista-disfrutaba-el-mejor-viaje-de-su-vida-cuando-una-ola-lo-dejo-al-borde-de-la-muerte","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/un-surfista-disfrutaba-el-mejor-viaje-de-su-vida-cuando-una-ola-lo-dejo-al-borde-de-la-muerte\/","title":{"rendered":"Un surfista disfrutaba el mejor viaje de su vida cuando una ola lo dej\u00f3 al borde de la muerte"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<div class=\"article-video | visual__video height_auto width_full margin_vertical_10px\"><figcaption class=\"padding_horizontal_15px margin_bottom_15px\">El surfista Billy Kemper disfrutaba el mejor viaje de su vida cuando una ola lo dej\u00f3 al borde de la muerte (Video: World Surf League)<\/figcaption><\/div>\n<p class=\"paragraph\">Billy Kemper, uno de los mejores surfistas del mundo, <b>estuvo a punto de abandonar el mar y las olas despu\u00e9s de sufrir un aparatoso accidente <\/b>que lo inmoviliz\u00f3 por varios meses.<\/p>\n<p class=\"paragraph\">Todo empez\u00f3 por la decisi\u00f3n de <b>viajar intempestivamente con rumbo a Marruecos para cazar una ola <\/b>de impulso a finales de 2019 y a principios de 2020; el desenlace fue publicado en un documental de la Liga Mundial de Surf titulado \u201cBILLY\u201d.<\/p>\n<p class=\"paragraph\">Ya para el closing de la temporada, tanto \u00e9l como sus compa\u00f1eros de equipo notaron que las olas en <b>el Pac\u00edfico Norte no ten\u00edan la potencia que necesitaban<\/b> para cerrar el a\u00f1o con fuerza, de acuerdo con el segundo cap\u00edtulo de la serie \u201cLa sesi\u00f3n de su vida sale terriblemente mal para el campe\u00f3n de Big Wave, Billy Kemper\u201d.<\/p>\n<p class=\"paragraph\">La concept principal period viajar para hacer un reel en los adentros de la costa de Marruecos, al norte de \u00c1frica, pues se acercaba<b> una tormenta por el Oc\u00e9ano Atl\u00e1ntico que pondr\u00eda el clima en un momento sin igual.<\/b><\/p>\n<div class=\"visual__image  image_container\"><img decoding=\"async\" alt=\"(Foto: IG @billykemper)\" height=\"224\" width=\"399\" src=\"https:\/\/www.infobae.com\/new-resizer\/hJsoF6_crHbTvo_MtQH4yJimAao=\/420x236\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HJKPMJZXDNEJHLCKCQDTMC7P4Q.png\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/hJsoF6_crHbTvo_MtQH4yJimAao=\/420x236\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HJKPMJZXDNEJHLCKCQDTMC7P4Q.png 420w,https:\/\/www.infobae.com\/new-resizer\/wwqFn7itaDKtmXVH5KYGctv9F5c=\/768x432\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HJKPMJZXDNEJHLCKCQDTMC7P4Q.png 768w,https:\/\/www.infobae.com\/new-resizer\/UU7HDuDfbFVOoHz01IjFlqSeFFg=\/992x558\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HJKPMJZXDNEJHLCKCQDTMC7P4Q.png 992w,https:\/\/www.infobae.com\/new-resizer\/92KVmv1rGBJ_cW9YICqIu_DCLFs=\/1200x675\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/HJKPMJZXDNEJHLCKCQDTMC7P4Q.png 1200w\" sizes=\"(min-width: 800px) 50vw, 90vw\"\/><figcaption>(Foto: IG @billykemper)<\/figcaption><\/div>\n<p class=\"paragraph\">En febrero de 2020, <b>Kemper, Koa Smith, Luke Davis y el cineasta Ar\u00e9nui Frapwell<\/b> se trasladaron a la playa elegida para encontrarse con el surfista <b>Gerome Sahyoun<\/b> y atacar las olas durante todo un d\u00eda.<\/p>\n<p class=\"paragraph\">El d\u00eda anterior a tomar las olas fue bastante productivo.<b> Pasearon por la zona, conocieron un poco de la cultura e hicieron bastantes compras<\/b> para la familia, adem\u00e1s de admirar el mar que, para entonces, ya presentaba los mejores oleajes que hab\u00edan visto, aseguran, en toda su vida.<\/p>\n<p class=\"paragraph\">Al siguiente d\u00eda, muy temprano, salieron rumbo a la playa con todo su equipo, preparados para montar<b> olas de hasta 15 metros<\/b>, seg\u00fan las descripciones que ofrece en su documental.<\/p>\n<p class=\"paragraph\">El video corr\u00eda de la mejor manera hasta que sucedi\u00f3 lo peor. <b>Billy Kemper fue arrastrado por las olas<\/b> y se estrell\u00f3 en una roca durante una de sus mejores e etapas deportivos.<\/p>\n<p class=\"paragraph\">Luego del accidente, <b>Kemper asegur\u00f3 que solamente pudo flotar, pues no pod\u00eda mover ninguna parte de su cuerpo,<\/b> incluso revel\u00f3 a las c\u00e1maras de la WFL que <b>perdi\u00f3 el conocimiento.<\/b><\/p>\n<div class=\"visual__image  image_container\"><img decoding=\"async\" alt=\"(Foto: REUTERS\/Mike Blake)\" height=\"2593\" width=\"3888\" src=\"https:\/\/www.infobae.com\/new-resizer\/5T641hSUreq0xyNMnrOrVH6QZ58=\/420x280\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CDM4QCY72UJMUJZNCW3RFT47D4.jpg\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/5T641hSUreq0xyNMnrOrVH6QZ58=\/420x280\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CDM4QCY72UJMUJZNCW3RFT47D4.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/hROmMtmihGIFJjV9tP43vBikvXw=\/768x512\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CDM4QCY72UJMUJZNCW3RFT47D4.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/UdJiQz_81sKpUxlLpZ5_i3uJ49w=\/992x661\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CDM4QCY72UJMUJZNCW3RFT47D4.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/3FqN00KxgcILZnRW42KtNv2BIfM=\/1200x800\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/CDM4QCY72UJMUJZNCW3RFT47D4.jpg 1200w\" sizes=\"(min-width: 800px) 50vw, 90vw\"\/><figcaption>(Foto: REUTERS\/Mike Blake)<\/figcaption><\/div>\n<p class=\"paragraph\">\u201cS\u00f3lo recuerdo que pensaba, \u00bfvolver\u00e9 a caminar?, no sab\u00eda lo que pasaba, si me estaba muriendo. Lo mir\u00e9 y le dije, hermano, no me dejes, tengo que irme a casa, tengo que volver\u201d, explic\u00f3 Kemper en el segundo cap\u00edtulo de su documental.<\/p>\n<p class=\"paragraph\">De acuerdo con el periodista Don Riddell de <i>movie star.land<\/i>,<b> Kemper se rompi\u00f3 la pelvis por la mitad<\/b>, pero gracias a la intervenci\u00f3n de su equipo, pudieron llevarlo a un lugar seguro en moto de agua, donde ya lo aguardaba una ambulancia.<\/p>\n<p class=\"paragraph\">Adem\u00e1s, el medio indic\u00f3 que la descripci\u00f3n del viaje en ambulancia es brutal, pues \u201cse sinti\u00f3 como el peor dolor de todos\u201d, pues cada golpe debido a la velocidad y el mal estado de la carretera en algunos tramos, pegaba directo en su pelvis<b>, la sangre, adem\u00e1s, no dejaba de brotar.<\/b><\/p>\n<p class=\"paragraph\">Sin embargo, el viaje al hospital no fue el mayor de sus problemas, pue<b>s ahora ten\u00eda que volver a los Estados Unidos<\/b> para que se le realizara la cirug\u00eda correspondiente.<\/p>\n<div class=\"visual__image  image_container\"><img decoding=\"async\" alt=\"(Foto: IG @billykemper)\" height=\"339\" width=\"464\" src=\"https:\/\/www.infobae.com\/new-resizer\/VTcjyHzpTBeNg-DGzGBhMWc8-e8=\/420x315\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/F2TDNK5SN5CGRH2EWRBKTI2RKY.png\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/VTcjyHzpTBeNg-DGzGBhMWc8-e8=\/420x315\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/F2TDNK5SN5CGRH2EWRBKTI2RKY.png 420w,https:\/\/www.infobae.com\/new-resizer\/-x0Rp38X8fY4c8zmI-8ZbGV39PI=\/768x576\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/F2TDNK5SN5CGRH2EWRBKTI2RKY.png 768w,https:\/\/www.infobae.com\/new-resizer\/ncsUKY7eN7mmTj8R2yUBYYlxHEQ=\/992x744\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/F2TDNK5SN5CGRH2EWRBKTI2RKY.png 992w,https:\/\/www.infobae.com\/new-resizer\/kpqpyR8JXdqlABP7GWO872BWaK0=\/1200x900\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/F2TDNK5SN5CGRH2EWRBKTI2RKY.png 1200w\" sizes=\"(min-width: 800px) 50vw, 90vw\"\/><figcaption>(Foto: IG @billykemper)<\/figcaption><\/div>\n<p class=\"paragraph\">Adem\u00e1s de no poder viajar m\u00e1s que arriba de una camilla, la pandemia por coronavirus hizo que varios pa\u00edses comenzaran a cerrar sus fronteras, pero una colecta entre amigos, familiares y patrocinadores le consigui\u00f3<b> un vuelo de evacuaci\u00f3n m\u00e9dica.<\/b><\/p>\n<p class=\"paragraph\">De acuerdo con <i>movie star.land<\/i>, luego de lograrse la cirug\u00eda, la recuperaci\u00f3n de Kemper ha llevado varios meses entre<b> descansos, rehabilitaciones y las medidas restrictivas sanitarias<\/b> alrededor de la pandemia por Coronavirus.<\/p>\n<p class=\"paragraph\">Sin embargo, asegur\u00f3 que aprovech\u00f3 el tiempo en tierra para <b>pensar, despejar su mente, sanar y prepararse tanto psychological como f\u00edsicamente para el regreso a una tabla de surf.<\/b><\/p>\n<p class=\"paragraph\">\u201cFue como la primera ola de toda mi vida una vez m\u00e1s, me trajo de vuelta las emociones de ser un ni\u00f1o [&#8230;] Surfear es quien soy. Sin surfear, no soy Billy\u201d, dijo al medio.<\/p>\n<p class=\"paragraph\"><b>SEGUIR LEYENDO:<\/b><\/p>\n<div class=\"text-element\"><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.infobae.com\/america\/deportes\/2021\/02\/24\/la-increible-historia-del-hombre-que-surfeo-un-tsunami-pense-que-seria-la-ultima-ola-de-mi-vida\/\">La incre\u00edble historia del hombre que surfe\u00f3 un tsunami: \u201cPens\u00e9 que ser\u00eda la \u00faltima ola de mi vida\u201d<\/a><\/div>\n<div class=\"text-element\"><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.infobae.com\/america\/deportes\/2020\/10\/27\/de-estar-al-borde-de-la-muerte-en-portugal-y-surfear-con-ballenas-en-sudafrica-a-lograr-un-record-guinness-a-solas-con-la-brasilena-que-cruza-los-limites\/\">De estar al borde de la muerte en Portugal y surfear con ballenas en Sud\u00e1frica a lograr un r\u00e9cord Guinness: a solas con la brasile\u00f1a que cruza los l\u00edmites<\/a><\/div>\n<div class=\"text-element\"><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.infobae.com\/deportes\/2020\/10\/24\/el-regreso-del-surf-la-historia-de-como-fue-el-primer-torneo-virtual-tras-una-larga-inactividad\/\">El regreso del surf: la historia de c\u00f3mo fue el primer torneo virtual tras una larga inactividad<\/a><\/div>\n<\/div>\n<p><script defer=\"\">!function(f,b,e,v,n,t,s) {if(f.fbq)return;n=f.fbq=function(){n.callMethod? n.callMethod.apply(n,arguments):n.queue.push(arguments)}; if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0'; n.queue=[];t=b.createElement(e);t.async=!0; t.src=v;s=b.getElementsByTagName(e)[0]; s.parentNode.insertBefore(t,s)}(window, document,'script', 'https:\/\/connect.facebook.net\/en_US\/fbevents.js'); fbq('init', '336383993555320'); fbq('track', 'PageView'); fbq('track', 'ViewContent');<\/script><br \/>\n<br \/><\/p>\n<p><em> &#8221; Fuentes www.infobae.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El surfista Billy Kemper disfrutaba el mejor viaje de su vida cuando una ola lo dej\u00f3 al borde de la muerte (Video: World Surf League) Billy Kemper, uno de los mejores surfistas del mundo, estuvo a punto de abandonar el mar y las olas despu\u00e9s de sufrir un aparatoso accidente que lo inmoviliz\u00f3 por varios [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":90948,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-90947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/90947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=90947"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/90947\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/90948"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=90947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=90947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=90947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}