{"id":85399,"date":"2021-02-23T05:27:38","date_gmt":"2021-02-23T05:27:38","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=85399"},"modified":"2021-02-23T05:27:38","modified_gmt":"2021-02-23T05:27:38","slug":"la-bolsa-premia-al-turismo-tras-las-buenas-noticias-de-johnson-noticias-de-hoteles-noticias-de-turismo","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/la-bolsa-premia-al-turismo-tras-las-buenas-noticias-de-johnson-noticias-de-hoteles-noticias-de-turismo\/","title":{"rendered":"La bolsa premia al turismo tras las buenas noticias de Johnson | Noticias de Hoteles, Noticias de turismo"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.preferente.com\/wp-content\/uploads\/2020\/04\/easyjet.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-299344 size-full\" src=\"https:\/\/www.preferente.com\/wp-content\/uploads\/2020\/04\/easyjet.jpg\" alt=\"\" width=\"600\" height=\"338\" srcset=\"https:\/\/www.preferente.com\/wp-content\/uploads\/2020\/04\/easyjet.jpg 600w, https:\/\/www.preferente.com\/wp-content\/uploads\/2020\/04\/easyjet-300x169.jpg 300w, https:\/\/www.preferente.com\/wp-content\/uploads\/2020\/04\/easyjet-355x200.jpg 355w, https:\/\/www.preferente.com\/wp-content\/uploads\/2020\/04\/easyjet-266x150.jpg 266w, https:\/\/www.preferente.com\/wp-content\/uploads\/2020\/04\/easyjet-133x75.jpg 133w, https:\/\/www.preferente.com\/wp-content\/uploads\/2020\/04\/easyjet-107x60.jpg 107w, https:\/\/www.preferente.com\/wp-content\/uploads\/2020\/04\/easyjet-249x140.jpg 249w, https:\/\/www.preferente.com\/wp-content\/uploads\/2020\/04\/easyjet-57x32.jpg 57w, https:\/\/www.preferente.com\/wp-content\/uploads\/2020\/04\/easyjet-577x325.jpg 577w, https:\/\/www.preferente.com\/wp-content\/uploads\/2020\/04\/easyjet-174x98.jpg 174w, https:\/\/www.preferente.com\/wp-content\/uploads\/2020\/04\/easyjet-270x152.jpg 270w\" sizes=\"(max-width: 600px) 100vw, 600px\"\/><\/a><\/p>\n<p>Aunque la rueda de prensa anunciando el closing de las restricciones a los viajes para mayo, y de todas las limitaciones a la movilidad para junio, tuvo lugar a las 19 horas, durante el d\u00eda se hab\u00edan filtrado la mayor parte de los detalles, lo cual tuvo su reflejo en Bolsa: IAG, la propietaria de British Airways, Vueling e Iberia, el fabricante de motores de aviones Rolls Royce, y otras empresas del sector como Easyjet o Tui vieron c\u00f3mo sus valores se disparaban. En todo caso, nada de esto compensa las ca\u00eddas anteriores.<\/p>\n<p>En alg\u00fan momento del d\u00eda, IAG lleg\u00f3 a subir un 7 por ciento; el fabricante de motores de avi\u00f3n \u2013ayudado, tambi\u00e9n, porque su rival Pratt &amp; Whitney est\u00e1 pasando por una disaster\u2013 subi\u00f3 un 6,5 por ciento y la cadena hotelera InterContinental Accommodations Group subi\u00f3 un 3,6 por ciento. Whitbread, el propietario de Premier Inn, una cadena low-cost de gran extensi\u00f3n con 600 hoteles en Gran Breta\u00f1a, sub\u00eda un 3,4 por ciento.<\/p>\n<p>Una noticia as\u00ed desata la euforia en todo el sector, por lo que EasyJet gan\u00f3 un 7 por ciento en el d\u00eda; Ryanair, un 4,7 y la low-cost h\u00fangara, que tambi\u00e9n cotiza en Londres, sub\u00eda un 6,7 por ciento.<\/p>\n<p>Nadie se libra de las buenas noticias: Tui subi\u00f3 un 8 por ciento, mientras Carnival, la compa\u00f1\u00eda de cruceros tambi\u00e9n subi\u00f3 otro 8 por ciento.<\/p>\n<p>Es posible que este martes vuelvan a repetirse los resultados positivos porque ayer, mientras se registraban estas subidas, las informaciones no eran muy seguras: se dec\u00eda que habr\u00eda una apertura pero en las informaciones dadas por la tarde las noticias fueron mejores: libertad complete en verano y, adem\u00e1s, excelentes datos sobre las vacunas que permiten imaginar que al menos all\u00ed donde las vacunas han llegado se puede producir una normalizaci\u00f3n relativamente eficaz.<\/p>\n<p>Paul Charles, uno de los responsables de la campa\u00f1a Save Our Summer time (SOS), que buscaba que se produjera una normalizaci\u00f3n de la actividad tur\u00edstica, dijo que \u201cesta era la noticia que el sector de viajes estaba buscando. Creo que digo la verdad si afirma que todo el mundo en el sector de los viajes est\u00e1 encantado con la claridad de este anuncio y con el marco que dice que en mayo se podr\u00e1 volar si se est\u00e1 vacunado\u201d.\u00a0<\/p>\n<p>Para entonces habr\u00e1 16 millones de vacunados que pueden ir a ver a sus familias o por cualquier otra raz\u00f3n.\u00a0<\/p>\n<p><!-- AddThis Advanced Settings above via filter on the_content --><!-- AddThis Advanced Settings below via filter on the_content --><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons above via filter on the_content --><!-- AddThis Share Buttons below via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->\t\t\t<\/div>\n\n<p><em> &#8221; Fuentes www.preferente.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque la rueda de prensa anunciando el closing de las restricciones a los viajes para mayo, y de todas las limitaciones a la movilidad para junio, tuvo lugar a las 19 horas, durante el d\u00eda se hab\u00edan filtrado la mayor parte de los detalles, lo cual tuvo su reflejo en Bolsa: IAG, la propietaria de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":85400,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-85399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/85399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=85399"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/85399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/85400"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=85399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=85399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=85399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}