{"id":85270,"date":"2021-02-22T20:38:56","date_gmt":"2021-02-22T20:38:56","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=85270"},"modified":"2021-02-22T20:38:56","modified_gmt":"2021-02-22T20:38:56","slug":"nuevo-estudio-muestra-una-mayor-disposicion-por-los-viajes-de-negocios","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/nuevo-estudio-muestra-una-mayor-disposicion-por-los-viajes-de-negocios\/","title":{"rendered":"Nuevo estudio muestra una mayor disposici\u00f3n por los viajes de negocios"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/transponder12001\"><img decoding=\"async\" class=\"aligncenter wp-image-67131 size-full\" src=\"https:\/\/i1.wp.com\/www.transponder1200.com\/wp-content\/uploads\/2021\/01\/TELEGRAM-T1200-V2-728X90.jpg?resize=728%2C90&amp;ssl=1\" alt=\"\" width=\"728\" height=\"90\" srcset=\"https:\/\/i1.wp.com\/www.transponder1200.com\/wp-content\/uploads\/2021\/01\/TELEGRAM-T1200-V2-728X90.jpg?resize=728%2C90&amp;ssl=1 728w, https:\/\/i1.wp.com\/www.transponder1200.com\/wp-content\/uploads\/2021\/01\/TELEGRAM-T1200-V2-728X90.jpg?resize=720%2C90&amp;ssl=1 720w\" data-sizes=\"(max-width: 728px) 100vw, 728px\" data-tcjp-recalc-dims=\"1\"\/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Una buena noticia para la industria a\u00e9rea, de acuerdo con un estudio reciente de <strong>World Enterprise Journey Affiliation (GBTA)<\/strong> indica que los pron\u00f3sticos que indicaban una ca\u00edda permanente de los viajes de negocios eran muy pesimistas. En realidad, la mayor\u00eda de la gente est\u00e1 dispuesta a regresar a los viajes de negocios despu\u00e9s de ser vacunados contra COVID-19, seg\u00fan el m\u00e1s reciente estudio.\u00a0<\/span><span style=\"color: #000000;\">En la encuesta realizada por GBTA y dada a conocer la semana pasada, el 79% de los encuestados dijeron sentirse \u201cmuy c\u00f3modos\u201d o \u201cc\u00f3modos\u201d viajando por negocios despu\u00e9s de ser vacunados, aunque m\u00e1s de la mitad apoyan las pruebas obligatorias antes de viajar.<\/span><\/p>\n<p><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.facebook.com\/EscuelaVitar\"><img decoding=\"async\" class=\"aligncenter wp-image-67134 size-full\" src=\"https:\/\/i1.wp.com\/www.transponder1200.com\/wp-content\/uploads\/2021\/01\/BANNER-PUBLICIDAD-VITAR-V2-728X90.jpg?resize=728%2C90&amp;ssl=1\" alt=\"\" width=\"728\" height=\"90\" srcset=\"https:\/\/i1.wp.com\/www.transponder1200.com\/wp-content\/uploads\/2021\/01\/BANNER-PUBLICIDAD-VITAR-V2-728X90.jpg?resize=728%2C90&amp;ssl=1 728w, https:\/\/i1.wp.com\/www.transponder1200.com\/wp-content\/uploads\/2021\/01\/BANNER-PUBLICIDAD-VITAR-V2-728X90.jpg?resize=720%2C90&amp;ssl=1 720w\" data-sizes=\"(max-width: 728px) 100vw, 728px\" data-tcjp-recalc-dims=\"1\"\/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Mientras actualmente los viajes corporativos est\u00e1n en niveles hist\u00f3ricos bajos, con el 64% de las empresas con suspensi\u00f3n de sus viajes dom\u00e9sticos y el 89% cancelaron o suspendieron sus viajes internacionales, la encuesta apunta a un creciente deseo de reanudar los viajes de negocios con las condiciones adecuadas. El 55% de las empresas miembros de GBTA creen que sus empleados est\u00e1n \u201cdeseosos\u201d o \u201cmuy deseosos\u201d de hacer viajes de negocios en el precise ambienta, un incremento muy significativo del 49% contra la encuesta de enero; solamente el 17% dijeron que sus empleados no quieren viajar por negocios actualmente. El 26% de las empresas dijeron que planean reanudar los viajes dom\u00e9sticos de negocios en el futuro cercano, que es una mejora del 16% contra la encuesta anterior.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Entre las razones por los reducidos viajes de negocios est\u00e1n el cierre de fronteras y las restricciones de viajes, y el 56% cube que estas restricciones y cierres incrementan la confusi\u00f3n e incertidumbre acerca de cu\u00e1ndo podr\u00e1n reanudarse los viajes de negocios.\u00a0<\/span><span style=\"color: #000000;\">El 58% de los encuestados apoya que las aerol\u00edneas requieran pruebas de vacunaci\u00f3n para volar conforme \u00e9stas est\u00e9n m\u00e1s disponibles, los europeos est\u00e1n m\u00e1s dispuestos a apoyar la prueba de vacunaci\u00f3n que los americanos, pues el 43% de ellos dicen que los cierres de fronteras y restricciones han impactado los esfuerzos de recuperaci\u00f3n de sus empresas en 2021.<\/span><\/p>\n<p><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.facebook.com\/EscuelaVitar\"><img decoding=\"async\" class=\"aligncenter wp-image-67134 size-full\" src=\"https:\/\/i1.wp.com\/www.transponder1200.com\/wp-content\/uploads\/2021\/01\/BANNER-PUBLICIDAD-VITAR-V2-728X90.jpg?resize=728%2C90&amp;ssl=1\" alt=\"\" width=\"728\" height=\"90\" srcset=\"https:\/\/i1.wp.com\/www.transponder1200.com\/wp-content\/uploads\/2021\/01\/BANNER-PUBLICIDAD-VITAR-V2-728X90.jpg?resize=728%2C90&amp;ssl=1 728w, https:\/\/i1.wp.com\/www.transponder1200.com\/wp-content\/uploads\/2021\/01\/BANNER-PUBLICIDAD-VITAR-V2-728X90.jpg?resize=720%2C90&amp;ssl=1 720w\" data-sizes=\"(max-width: 728px) 100vw, 728px\" data-tcjp-recalc-dims=\"1\"\/><\/a><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La gran mayor\u00eda apoya las pruebas obligatorias porque la gente siente que permitir\u00e1 las reuniones cara a cara, indicando la importancia que esto tiene para reanudar los viajes corporativos. Esto parece debilitar el argumento de que en el mundo submit pandemia, las empresas continuar\u00e1n confiando en las m\u00e1s baratas reuniones virtuales m\u00e1s que en el regreso de las reuniones en persona.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Hay que se\u00f1alar, sin embargo, que la encuesta no les da a las aerol\u00edneas ning\u00fan alivio a corto plazo, la gran mayor\u00eda de las empresas miembros de GBTA no han reanudado viajes internacionales y el 64% tambi\u00e9n tienen cancelados los viajes dom\u00e9sticos sin importar el lugar. Pero los programas de vacunaci\u00f3n parecen estar impulsando a las empresas y a la gente a pensar en cu\u00e1ndo (y no si) van a reanudar sus viajes de trabajo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El <strong>Director Ejecutivo interino de GBTA<\/strong>, <strong>Dave Hilfman<\/strong>, dijo:<\/span><\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Es tranquilizador escuchar tantos argumentos acerca de reanudar los viajes de negocios y un cambio de opini\u00f3n del 16 a 25% de los miembros de GBTA que han reanudado sus viajes de negocios dom\u00e9sticos en el \u00faltimo mes\u201d.<\/span><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Un reporte actualizado de la asociaci\u00f3n Airways for America (A4A), indica que las ventas de boletos corporativos en EE.U., siguen 85.7% por debajo de lo que hab\u00eda en 2019, mientras que la venta de boletos en common est\u00e1 66% por debajo, lo que muestra que los viajes corporativos todav\u00eda est\u00e1n muy por detr\u00e1s de los viajes de turismo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El Director de Ingresos de American Airways, Vasu Raja, en la presentaci\u00f3n de los resultados del cuarto trimestre, dijo que los viajes corporativos est\u00e1n entre 5 y 10% de sus niveles hist\u00f3ricos, pero que estaba muy optimista de que regresar\u00edan conforme las vacunas se vayan distribuyendo, aunque el tiempo y el crecimiento de ese regreso sigue siendo poco claro. El objetivo de American por ahora es ser tan \u00e1gil como sea posible para que al momento en que la demanda de viajes vaya regresando, puedan ofrecer la conectividad necesaria.<\/span><\/p>\n<div class=\"author_box_tabs\">\n<nav>\n<\/nav>\n<ul class=\"author_box_tabs_content\">\n<li data-content=\"bio\" class=\"selected\">\n<img decoding=\"async\" alt=\"author's avatar\" class=\"birds_box_avatar\" src=\"https:\/\/i0.wp.com\/www.transponder1200.com\/wp-content\/uploads\/2021\/01\/BIO-T1200-ERICK-HAW.png?ssl=1\" data-tcjp-recalc-dims=\"1\"\/><\/p>\n<p><span class=\"by_text\">Por:<\/span> <span class=\"h4_text\">Erick Haw Mayer<\/span><\/p>\n<p>Apasionado de la aviaci\u00f3n y la industria automotriz de toda la vida, tiene una Licenciatura en Inform\u00e1tica y un Postgrado en Comunicaci\u00f3n y R.P. Aunque tiene experiencia en empresas del rubro automotriz y en Mexicana de Aviaci\u00f3n, su vida profesional se ha dedicado m\u00e1s al periodismo especializado en todo tipo de medios impresos y electr\u00f3nicos, incluyendo la revista Avi\u00f3n Revue de Latinoam\u00e9rica.\n<\/p>\n<\/li>\n<li data-content=\"social\">\n<img decoding=\"async\" alt=\"author's avatar\" class=\"birds_box_avatar\" src=\"https:\/\/i0.wp.com\/www.transponder1200.com\/wp-content\/uploads\/2021\/01\/BIO-T1200-ERICK-HAW.png?ssl=1\" data-tcjp-recalc-dims=\"1\"\/>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<p><script>(function(d, s, id) {\n          var js, fjs = d.getElementsByTagName(s)[0];\n          if (d.getElementById(id)) return;\n          js = d.createElement(s); js.id = id;\n          js.src = \"https:\/\/connect.facebook.net\/en_US\/sdk.js#xfbml=1&appId=&version=v2.3\";\n          fjs.parentNode.insertBefore(js, fjs);\n        }(document, 'script', 'facebook-jssdk'));<\/script><br \/>\n<br \/><\/p>\n<p><em> &#8221; Fuentes www.transponder1200.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una buena noticia para la industria a\u00e9rea, de acuerdo con un estudio reciente de World Enterprise Journey Affiliation (GBTA) indica que los pron\u00f3sticos que indicaban una ca\u00edda permanente de los viajes de negocios eran muy pesimistas. En realidad, la mayor\u00eda de la gente est\u00e1 dispuesta a regresar a los viajes de negocios despu\u00e9s de ser [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-85270","post","type-post","status-publish","format-standard","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/85270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=85270"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/85270\/revisions"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=85270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=85270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=85270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}