{"id":759636,"date":"2024-03-22T19:53:49","date_gmt":"2024-03-22T19:53:49","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=759636"},"modified":"2024-03-22T19:53:49","modified_gmt":"2024-03-22T19:53:49","slug":"anatol-kitchen-once-anos-de-tradicion-culinaria-2","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/anatol-kitchen-once-anos-de-tradicion-culinaria-2\/","title":{"rendered":"Anatol Kitchen, once a\u00f1os de tradici\u00f3n culinaria"},"content":{"rendered":"<p>Bajo la direcci\u00f3n visionaria del chef Rodrigo Del Valle, este rinc\u00f3n culinario en Polanco se ha mantenido como uno de los imperdibles de la zona gracias a su innovaci\u00f3n gastron\u00f3mica y evoluci\u00f3n constante de los sabores y el concepto inspirado en la b\u00fasqueda de los ingredientes de <img decoding=\"async\" class=\"size-medium wp-image-759661 alignright\" src=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2024\/03\/1gas-1-240x300.jpg\" alt=\"\" width=\"240\" height=\"300\" srcset=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2024\/03\/1gas-1-240x300.jpg 240w, https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2024\/03\/1gas-1.jpg 600w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/>mayor calidad, para resaltar las diferentes t\u00e9cnicas internacionales que se fusionan perfectamente con el enfoque moderno y sofisticado del chef Del Valle, las cuales han llevado a este restaurante a convertirse en un santuario culinario donde los ingredientes cobran vida y los sabores narran historias.<\/p>\n<p>Conmemorando once a\u00f1os de trayectoria y siguiendo su visi\u00f3n de buscar productos con historia que los inspiren a crear y a desarrollar nuevos platillos, el chef Rodrigo ha desarrollado un men\u00fa de degustaci\u00f3n de 8 tiempos que promete ser un viaje por la trayectoria de este restaurante desde su apertura, en el que los comensales podr\u00e1s disfrutar desde los platillos que se han convertido en los cl\u00e1sicos de <img decoding=\"async\" class=\"size-medium wp-image-759662 alignright\" src=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2024\/03\/2GAS-1-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2024\/03\/2GAS-1-200x300.jpg 200w, https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2024\/03\/2GAS-1.jpg 600w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/>la carta, hasta las nuevas creaciones de la cocina de Anatol, ofreciendo una experiencia gastron\u00f3mica \u00fanica.<\/p>\n<p>Con versiones miniatura de los platillos de la carta, este imperdible men\u00fa inicia con un refrescante At\u00fan Poke, acompa\u00f1ado de un crujiente de ajonjol\u00ed negro, aguacate, naranja y nuez de la india; seguido por un estallido de sabores con un Aguachile Shimeji, entrelazado con notas de papaya y mango encurtidos. Para continuar, llega el momento de dos de los cl\u00e1sicos de la carta el Esquite de Langosta y el reconfortante Flatbread de Aguacate. La traves\u00eda sigue con el Arancini de queso roquefort, el cual junto con el queso parmesano raggiano, crea una combinaci\u00f3n que transporta a la Italia m\u00e1s aut\u00e9ntica, antes de deleitar el paladar con la frescura de la Pesca del D\u00eda, la cual llega acompa\u00f1ada de lentejas rojas org\u00e1nicas; siendo antesala del plato principal e <img decoding=\"async\" class=\"size-medium wp-image-759663 alignright\" src=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2024\/03\/4GAS-1-240x300.jpg\" alt=\"\" width=\"240\" height=\"300\" srcset=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2024\/03\/4GAS-1-240x300.jpg 240w, https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2024\/03\/4GAS-1.jpg 600w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/>imperdible de la casa, el Pollo Rostizado, acompa\u00f1ado de papas cambray y pimientos asados, sin duda estos sabores te har\u00e1n sentir la calidez aut\u00e9ntica del hogar. Pero como no hay comida sin postre, este viaje de sabores cierra<\/p>\n<p>con broche de oro al ofrecer una degustaci\u00f3n de postres que fusionan los sabores del chocolate, la cereza y el huitlacoche en una sinfon\u00eda de dulzura y sofisticaci\u00f3n.<\/p>\n<p>Con este men\u00fa Anatol busca brindar un recorrido culinario inspirado en los sabores locales hechos en casa, en el que los ingredientes frescos toman el papel de materia prima, las bases que ha tenido el restaurante desde su apertura. Cabe se\u00f1alar que algunos platillos permanecen como una constante en el men\u00fa de Anatol, mientras que otros cambian por temporada, siguiendo el flujo de las estaciones y actividades alineadas a una ciudad llena de diversidad y <img decoding=\"async\" class=\"size-medium wp-image-759664 alignright\" src=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2024\/03\/7GAS-240x300.jpg\" alt=\"\" width=\"240\" height=\"300\" srcset=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2024\/03\/7GAS-240x300.jpg 240w, https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2024\/03\/7GAS.jpg 600w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/>movimiento como lo es la Ciudad de M\u00e9xico, logrando que los comensales descubran algo nuevo en cada visita.<\/p>\n<p>Sin duda, este rinc\u00f3n culinario de Polanco promete mantenerse entre los favoritos de los comensales que buscan disfrutar de una experiencia de sabores \u00fanica e innovadora y con el men\u00fa de aniversario, el chef Del Valle deleitar\u00e1 hasta a los paladares m\u00e1s exigentes. D\u00e9jate sorprender con los sabores de Anatol y celebra a\u00f1os de sabor y tradici\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bajo la direcci\u00f3n visionaria del chef Rodrigo Del Valle, este rinc\u00f3n culinario en Polanco se ha mantenido como uno de los imperdibles de la zona gracias a su innovaci\u00f3n gastron\u00f3mica y evoluci\u00f3n constante de los sabores y el concepto inspirado en la b\u00fasqueda de los ingredientes de mayor calidad, para resaltar las diferentes t\u00e9cnicas internacionales [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":759665,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":{"source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"10","single_blog_custom":"","parallax":"1","fullscreen":"0","layout":"no-sidebar-narrow","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"bottom","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"0","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"0","show_popup_post":"1","number_popup_post":"1","show_author_box":"1","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"footnotes":""},"categories":[43],"tags":[],"class_list":["post-759636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gourmet"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/759636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=759636"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/759636\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/759665"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=759636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=759636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=759636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}