{"id":683666,"date":"2023-12-15T20:29:59","date_gmt":"2023-12-15T20:29:59","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=683666"},"modified":"2023-12-15T20:29:59","modified_gmt":"2023-12-15T20:29:59","slug":"pariente-un-guadalupe-reyes-al-estilo-michoacan","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/pariente-un-guadalupe-reyes-al-estilo-michoacan\/","title":{"rendered":"Pariente, un Guadalupe Reyes al estilo Michoac\u00e1n"},"content":{"rendered":"<p>En M\u00e9xico la temporada de fiestas decembrinas es algo que no dejamos pasar tan f\u00e1cilmente. Nuestro esp\u00edritu inquieto nos impulsa a festejar todo aquello que se pueda y el ejemplo perfecto es el marat\u00f3n Guadalupe Reyes. A partir del 12 de diciembre y hasta el 6 de enero el pa\u00eds entero se convierte en un hervidero de celebraciones con las coloridas peregrinaciones a la Bas\u00edlica de Guadalupe, las vibrantes fiestas de Nochebuena, fin de a\u00f1o y la llegada de los Reyes Magos.<\/p>\n<p>Para aquellos que buscan sumergirse en este famoso marat\u00f3n, es necesario hacer un recorrido por los platillos mexicanos m\u00e1s emblem\u00e1ticos, pues nuestra cultura culinaria ofrece opciones para todos: desde aquellos que<img decoding=\"async\" class=\" wp-image-683667 alignleft\" src=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2023\/12\/2PARIENTE-300x200.jpg\" alt=\"\" width=\"911\" height=\"607\" srcset=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2023\/12\/2PARIENTE-300x200.jpg 300w, https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2023\/12\/2PARIENTE.jpg 600w\" sizes=\"(max-width: 911px) 100vw, 911px\" \/> buscan pasar un rato en familia, hasta quienes buscan un poco de alivio despu\u00e9s de una noche de celebraciones.<\/p>\n<p>La parada perfecta es Pariente Restaurante, un sitio de comida mexicana que se especializa en la cocina de Michoac\u00e1n. En las mesas de este lugar se celebra la conexi\u00f3n que la comida crea entre las personas, porque comer es un acto de amor y de compartir. Esa calidez que se evoca con los platillos no s\u00f3lo permanece ah\u00ed, sino que trasciende tambi\u00e9n a los lazos personales. En Michoac\u00e1n los amigos y las personas cercanas se llaman entre ellos \u201cpariente\u201d, de ah\u00ed el nombre de este lugar.<\/p>\n<p>En este periodo tendr\u00e1n un men\u00fa navide\u00f1o especial que promete satisfacer todos los antojos posibles. En las bebidas no puedes perderte el tradicional ponche y el cafecito de olla que siempre se agradece, pero, por supuesto, hay m\u00e1s:<\/p>\n<p>Sopa de calabaza de Castilla con crema de rancho, chorizo y juliana de tortilla.<\/p>\n<p>Sopa Bisque de camar\u00f3n con hinojo, queso mascarpone y vino blanco.<img decoding=\"async\" class=\" wp-image-683668 alignleft\" src=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2023\/12\/1PARIENTE-300x200.jpg\" alt=\"\" width=\"908\" height=\"605\" srcset=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2023\/12\/1PARIENTE-300x200.jpg 300w, https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2023\/12\/1PARIENTE.jpg 600w\" sizes=\"(max-width: 908px) 100vw, 908px\" \/><\/p>\n<p>Carnitas de pavo con pur\u00e9 de papa a la mantequilla y ensalada de manzana.<\/p>\n<p>Tortillas y pico de gallo de manzana para taquear.<\/p>\n<p>Pesca del d\u00eda a la vizca\u00edna, papas, cebolla cambray, chiles g\u00fceros, alcaparras y aceituna.<\/p>\n<p>Sabemos que el postre tiene un lugar especial en el coraz\u00f3n, y aqu\u00ed puedes disfrutar de unos deliciosos bu\u00f1uelos con guayaba en dulce de jamaica. Lo mejor de este sitio es que la decoraci\u00f3n est\u00e1 pensada en evocar a un hogar, es r\u00fastica y c\u00e1lida, con elementos tradicionales mexicanos y mobiliario creado por artesanos de la regi\u00f3n de Michoac\u00e1n para crear un ambiente acogedor y animado.<\/p>\n<p>Navidad al estilo Pariente, tu destino para el Guadalupe Reyes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En M\u00e9xico la temporada de fiestas decembrinas es algo que no dejamos pasar tan f\u00e1cilmente. Nuestro esp\u00edritu inquieto nos impulsa a festejar todo aquello que se pueda y el ejemplo perfecto es el marat\u00f3n Guadalupe Reyes. A partir del 12 de diciembre y hasta el 6 de enero el pa\u00eds entero se convierte en un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":683669,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":{"source_name":"","source_url":"","via_name":"","via_url":"","override_template":"0","override":[{"template":"1","single_blog_custom":"","parallax":"1","fullscreen":"1","layout":"right-sidebar","sidebar":"default-sidebar","second_sidebar":"default-sidebar","sticky_sidebar":"1","share_position":"top","share_float_style":"share-monocrhome","show_share_counter":"1","show_view_counter":"1","show_featured":"1","show_post_meta":"1","show_post_author":"1","show_post_author_image":"1","show_post_date":"1","post_date_format":"default","post_date_format_custom":"Y\/m\/d","show_post_category":"1","show_post_reading_time":"0","post_reading_time_wpm":"300","show_zoom_button":"0","zoom_button_out_step":"2","zoom_button_in_step":"3","show_post_tag":"1","show_prev_next_post":"1","show_popup_post":"1","number_popup_post":"1","show_author_box":"0","show_post_related":"0","show_inline_post_related":"0"}],"override_image_size":"0","image_override":[{"single_post_thumbnail_size":"crop-500","single_post_gallery_size":"crop-500"}],"trending_post":"0","trending_post_position":"meta","trending_post_label":"Trending","sponsored_post":"0","sponsored_post_label":"Sponsored by","sponsored_post_name":"","sponsored_post_url":"","sponsored_post_logo_enable":"0","sponsored_post_logo":"","sponsored_post_desc":"","disable_ad":"0"},"jnews_primary_category":{"id":"","hide":""},"jnews_social_meta":{"fb_title":"","fb_description":"","fb_image":"","twitter_title":"","twitter_description":"","twitter_image":""},"footnotes":""},"categories":[43],"tags":[],"class_list":["post-683666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gourmet"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/683666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=683666"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/683666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/683669"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=683666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=683666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=683666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}