{"id":521087,"date":"2023-04-18T21:51:28","date_gmt":"2023-04-18T21:51:28","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=521087"},"modified":"2023-04-18T21:51:28","modified_gmt":"2023-04-18T21:51:28","slug":"el-menchito-contrata-a-como-abogada-a-mariel-colon-exdefensora-de-el-chapo-y-cantante","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/el-menchito-contrata-a-como-abogada-a-mariel-colon-exdefensora-de-el-chapo-y-cantante\/","title":{"rendered":"&#8216;El Menchito&#8217; contrata a como abogada a Mariel Col\u00f3n, exdefensora de &#8216;El Chapo&#8217; y cantante"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_181_f46\">\n<div class=\"tdb-block-inner td-fix-index here\">\n<p><strong>Ciudad de M\u00e9xico.- Mariel Col\u00f3n<\/strong>, quien formara parte de los abogados que representaron a <strong>Joaqu\u00edn \u2018Chapo\u2019 Guzm\u00e1n<\/strong>, ahora defender\u00e1 a<strong> Rub\u00e9n Oseguera Gonz\u00e1lez<\/strong>, \u2018<strong>El Menchito<\/strong>\u2018.<\/p>\n<p>La tambi\u00e9n cantante se unir\u00e1 a <strong>Arturo Hern\u00e1ndez<\/strong> en lo que ser\u00e1 una nueva estrategia para que el hijo de \u2018El Mencho\u2019, l\u00edder del <strong>C\u00e1rtel Jalisco Nueva Generaci\u00f3n<\/strong> (<strong>CJNG<\/strong>) vaya a juicio a enfrentar las acusaciones por narcotr\u00e1fico.<\/p>\n<p><!-- \/75375600\/PP_BN4_PARRAFOS_300X250 --><br \/>\n                                              <span class=\"td-adspot-title\">-Anuncio-<\/span><\/p>\n<p>Hasta el momento, Col\u00f3n no se ha involucrado de fondo en el caso, pues su primera acci\u00f3n fue la de facilitar que se admitiera a su colega, Hern\u00e1ndez, como abogado de Oseguera Gonz\u00e1lez.<\/p>\n<p>Ser\u00e1 el pr\u00f3ximo 21 de abril que se realice la pr\u00f3xima audiencia, donde determinar\u00e1n c\u00f3mo continuar\u00e1 el proceso en contra de El Menchito.<\/p>\n<p>El pasado 13 de abril, Oseguera Gonz\u00e1lez solicit\u00f3 a la jueza <strong>Beryl A. Howell <\/strong>darle tiempo y reconsiderar el acuerdo de culpabilidad al que hab\u00eda llegado. Su juicio estaba previsto para comenzar el 2 de mayo.<\/p>\n<p><!-- \/75375600\/pp_a10_300x250 --><br \/>\n                                                <span class=\"td-adspot-title\">-Anuncio-<\/span><\/p>\n<p>Con informaci\u00f3n de Milenio.<\/p>\n<\/div>\n<\/div>\n<p><script>\n!function(f,b,e,v,n,t,s)\n{if(f.fbq)return;n=f.fbq=function(){n.callMethod?\nn.callMethod.apply(n,arguments):n.queue.push(arguments)};\nif(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0';\nn.queue=[];t=b.createElement(e);t.async=!0;\nt.src=v;s=b.getElementsByTagName(e)[0];\ns.parentNode.insertBefore(t,s)}(window, document,'script',\n'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\nfbq('init', '3446853778764149');\nfbq('track', 'PageView');\n<\/script><br \/>\n<br \/><\/p>\n<p><em> \u2018 The preceding article may include information circulated by third parties \u2019 <\/em><\/p>\n<p><em> \u2018 Some details of this article were extracted from the following source proyectopuente.com.mx \u2019 <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad de M\u00e9xico.- Mariel Col\u00f3n, quien formara parte de los abogados que representaron a Joaqu\u00edn \u2018Chapo\u2019 Guzm\u00e1n, ahora defender\u00e1 a Rub\u00e9n Oseguera Gonz\u00e1lez, \u2018El Menchito\u2018. La tambi\u00e9n cantante se unir\u00e1 a Arturo Hern\u00e1ndez en lo que ser\u00e1 una nueva estrategia para que el hijo de \u2018El Mencho\u2019, l\u00edder del C\u00e1rtel Jalisco Nueva Generaci\u00f3n (CJNG) vaya [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":521088,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[43],"tags":[],"class_list":["post-521087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gourmet"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/521087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=521087"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/521087\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/521088"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=521087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=521087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=521087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}