{"id":520306,"date":"2023-04-17T03:38:48","date_gmt":"2023-04-17T03:38:48","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=520306"},"modified":"2023-04-17T03:38:48","modified_gmt":"2023-04-17T03:38:48","slug":"el-40-de-empresas-y-bancos-vinculados-a-la-deforestacion-no-toman-medidas-para-frenarla-segun-un-informe-planeta-futuro","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/el-40-de-empresas-y-bancos-vinculados-a-la-deforestacion-no-toman-medidas-para-frenarla-segun-un-informe-planeta-futuro\/","title":{"rendered":"El 40% de empresas y bancos vinculados a la deforestaci\u00f3n no toman medidas para frenarla, seg\u00fan un informe | Planeta Futuro"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div data-dtm-region=\"articulo_cuerpo\">\n<p class=\"\">Los n\u00fameros son reveladores: un tercio de las emisiones de gases de efecto invernadero procede de la deforestaci\u00f3n y la destrucci\u00f3n de ecosistemas naturales; b\u00e1sicamente, para producir <a target=\"_blank\" href=\"https:\/\/elpais.com\/planeta-futuro\/2022-07-11\/europa-baraja-eliminar-el-biodiesel-de-soja-y-palma-para-frenar-la-deforestacion-tropical.html\" rel=\"noopener\">soja, aceite de palma<\/a>, <a target=\"_blank\" href=\"https:\/\/elpais.com\/planeta-futuro\/2021-12-28\/europa-destruir-selvas-para-hacer-calzoncillos.html\" rel=\"noopener\">pulpa de madera, papel y cuero<\/a> en lugares como la Amazonia, Indonesia y \u00c1frica central. Los objetivos globales de clima, biodiversidad y desarrollo sostenible solo est\u00e1n a nuestro alcance si se frena la deforestaci\u00f3n tropical y las violaciones de derechos humanos asociadas, como el acaparamiento de tierras. Sin embargo, el 40% de las <a target=\"_blank\" href=\"https:\/\/elpais.com\/elpais\/2015\/02\/11\/ciencia\/1423644917_659682.html\" rel=\"noopener\">500 empresas e instituciones financieras con mayor riesgo de estar causando<\/a> deforestaci\u00f3n tropical no tienen ni una sola pol\u00edtica para frenarla, seg\u00fan un <a target=\"_blank\" href=\"https:\/\/forest500.org\/sites\/default\/files\/forest_500-2023_annual_report.pdf\" rel=\"noopener\">an\u00e1lisis de la organizaci\u00f3n sin \u00e1nimo de lucro brit\u00e1nica Global Canopy<\/a>, un referente en la materia que asesora a instituciones como la Uni\u00f3n Europea y el Gobierno franc\u00e9s. Entre las entidades sin compromisos para frenar la p\u00e9rdida de bosques est\u00e1 el mayor minorista europeo de calzado, <a target=\"_blank\" href=\"https:\/\/forest500.org\/search?keywords=deichmann+group\" rel=\"noopener\">Deichmann Group<\/a>; el <a target=\"_blank\" href=\"https:\/\/forest500.org\/rankings\/companies\/vw-group\" rel=\"noopener\">VW Group<\/a>, propietario de marcas de autom\u00f3vil como Volkswagen, Audi, Skoda y Lamborgini; y <a target=\"_blank\" href=\"https:\/\/forest500.org\/rankings\/financial-institutions\/blackrock\" rel=\"noopener\">BlackRock<\/a>, uno de los mayores gestores de fondos del mundo.<\/p>\n<aside class=\"a_ei\">\n<header class=\"a_ei_h _db\">M\u00e1s informaci\u00f3n<\/header>\n<\/aside>\n<p class=\"\">El informe <i>Forest 500, <\/i>publicado en febrero y que punt\u00faa bas\u00e1ndose en la informaci\u00f3n que las propias compa\u00f1\u00edas y bancos publican en sus sitios net, analiza las 350 empresas y 150 entidades financieras m\u00e1s vinculadas a la deforestaci\u00f3n en el mundo, ya sea porque producen o consumen las materias primas citadas o porque invierten y dan cr\u00e9ditos a otras compa\u00f1\u00edas. El documento hace hincapi\u00e9 en su novena edici\u00f3n en las <a target=\"_blank\" href=\"https:\/\/elpais.com\/planeta-futuro\/2022-12-16\/la-nueva-ley-europea-contra-la-deforestacion-mundial-decepciona-a-los-indigenas.html\" rel=\"noopener\">violaciones de derechos humanos<\/a> que suelen ir de la mano de la deforestaci\u00f3n: acaparamiento de tierras, amenazas a poblaciones ind\u00edgenas y locales y violencia contra l\u00edderes ambientales. \u201cEs profundamente preocupante que el 90% de empresas sin una sola pol\u00edtica sobre deforestaci\u00f3n tampoco se hayan comprometido p\u00fablicamente a combatir los abusos de derechos humanos asociados\u201d, afirma el director ejecutivo de World Cover, Niki Mardas.<\/p>\n<h3 class=\"\">De las palabras a los hechos<\/h3>\n<p class=\"\">Las pol\u00edticas corporativas son un primer paso. Luego est\u00e1 su cumplimiento. Un 29% de las empresas se ha comprometido a eliminar la deforestaci\u00f3n de todos sus productos, incluyendo el gigante de bienes de consumo Unilever. Pero solo la mitad est\u00e1 verificando si sus proveedores de materias primas cumplen de verdad, seg\u00fan la ONG.<\/p>\n<p class=\"\">Y luego est\u00e1n las promesas de lograr <a target=\"_blank\" href=\"https:\/\/www.google.com\/url?sa=t&amp;rct=j&amp;q=&amp;esrc=s&amp;source=web&amp;cd=&amp;ved=2ahUKEwjFy_mFuJf-AhVSTcAKHegqDssQFnoECBAQAQ&amp;url=https%3A%2F%2Fwww.un.org%2Fes%2Fclimatechange%2Fnet-zero-coalition&amp;usg=AOvVaw0hZdYas_cw-H67DsAKK8kD\" rel=\"noopener\">cero emisiones netas<\/a> de gases de efecto invernadero para 2050, que se han disparado en los \u00faltimos tres a\u00f1os. Seg\u00fan el an\u00e1lisis, casi la totalidad (98%) de estas pol\u00edticas van camino de estrellarse porque las empresas no est\u00e1n adoptando suficientes medidas para eliminar la deforestaci\u00f3n de sus cadenas de suministro. Entre las compa\u00f1\u00edas citadas est\u00e1n Ikea, Carrefour, Starbucks y Amazon.<\/p>\n<blockquote class=\"a_q\">\n<p>Las grandes empresas del sector alimentario y agr\u00edcola corren el riesgo de devaluarse hasta un 26% para 2030 por la emergencia clim\u00e1tica, seg\u00fan la ONU<\/p>\n<\/blockquote>\n<p class=\"\">La responsable del informe, Emma Thomson, remarca que nunca hab\u00eda sido tan f\u00e1cil actuar gracias a la cantidad de datos, herramientas de trazabilidad de materias primas y gu\u00edas como las elaboradas por la propia World Cover para <a target=\"_blank\" href=\"https:\/\/accountability-framework.org\/how-to-use-it\/resources-library\/common-methodology-for-assessment-of-progress-towards-deforestation-free-supply-chains\/\" rel=\"noopener\">empresas<\/a> e <a target=\"_blank\" href=\"https:\/\/guidance.globalcanopy.org\/roadmap\/\" rel=\"noopener\">instituciones financieras<\/a>. \u201cEl mejor momento para ponerse las pilas contra la deforestaci\u00f3n era hace 10 a\u00f1os o m\u00e1s. El segundo mejor momento es ahora\u201d, afirma. De seguir por la misma senda, la ONU estima que las grandes empresas del sector alimentario y agr\u00edcola se <a target=\"_blank\" href=\"https:\/\/climatechampions.unfccc.int\/unpriced-nature-and-climate-risk-could-wipe-off-billions\/\" rel=\"noopener\">devaluar\u00e1n hasta un 26%<\/a> para 2030, acarreando p\u00e9rdidas permanentes de la magnitud de la disaster financiera world de 2008.<\/p>\n<h3 class=\"\">Las instituciones financieras, a la cola<\/h3>\n<p class=\"\">Las empresas de todos los sectores van rezagadas, pero el sector de las finanzas va por detr\u00e1s. Un 61% de las entidades financieras no tiene ninguna pol\u00edtica contra la deforestaci\u00f3n. Ello incluye a los tres mayores gestores de activos del mundo: Vanguard, State Avenue y<a target=\"_blank\" href=\"https:\/\/forest500.org\/rankings\/financial-institutions\/blackrock\" rel=\"noopener\"> BlackRock<\/a>, que tiene a grandes bancos y multinacionales espa\u00f1olas en su cartera de inversiones. El a\u00f1o pasado, las instituciones estudiadas inyectaron 423.000 millones de euros a empresas del <i>Forest 500<\/i> que no tienen ni un solo compromiso contra la deforestaci\u00f3n.<\/p>\n<p class=\"\">Seg\u00fan el informe, solo un 11% de las instituciones financieras cuentan con pol\u00edticas contra la deforestaci\u00f3n relacionada con la soja, el aceite de palma, la pulpa de madera o el papel y cuero. Pero es que, adem\u00e1s, no todas ellas comprueban si las empresas en las que invierten las cumplen.<\/p>\n<blockquote class=\"a_q\">\n<p>Una nueva ley europea prohibir\u00e1 a las empresas importar materias primas vinculadas a tala de bosques, pero dejar\u00e1 v\u00eda libre al sector financiero<\/p>\n<\/blockquote>\n<p class=\"\">La nueva <a target=\"_blank\" href=\"https:\/\/elpais.com\/clima-y-medio-ambiente\/2022-12-06\/europa-aprueba-una-ley-pionera-en-la-lucha-contra-la-deforestacion-mundial.html\" rel=\"noopener\">ley europea contra la deforestaci\u00f3n<\/a> prohibir\u00e1 a las empresas importar materias primas vinculadas a tala de bosques, pero dejar\u00e1 v\u00eda libre a bancos, gestores de activos y fondos de pensiones. La responsable del informe, Emma Thomson, opina que la Uni\u00f3n Europea deber\u00eda incluir a las entidades financieras en dicha legislaci\u00f3n, pero para evitar los peores efectos del cambio clim\u00e1tico estas tienen que ponerse en marcha ya, sin esperar a verse obligadas. \u201cCon las pol\u00edticas de inversi\u00f3n adecuadas, las grandes instituciones financieras pueden transformar cadenas de suministro enteras; un cambio indispensable para que el mundo logre los objetivos clim\u00e1ticos, de biodiversidad y desarrollo sostenible en los pr\u00f3ximos siete a\u00f1os\u201d.<\/p>\n<h3 class=\"\">Situaci\u00f3n en Espa\u00f1a<\/h3>\n<p class=\"\">Espa\u00f1a es el <a target=\"_blank\" href=\"https:\/\/elpais.com\/planeta-futuro\/2022-07-11\/europa-baraja-eliminar-el-biodiesel-de-soja-y-palma-para-frenar-la-deforestacion-tropical.html\" rel=\"noopener\">tercer pa\u00eds<\/a> de la UE con m\u00e1s deforestaci\u00f3n importada \u2014o sea, que m\u00e1s contribuye a la deforestaci\u00f3n fuera de las fronteras del mercado com\u00fan\u2014. El informe analiza dos empresas (Grupo Inditex, Ebro Meals) y dos instituciones financieras (Banco Santander, BBVA) con sede en Espa\u00f1a, e indica que los bancos est\u00e1n entre el 11% de las entidades financieras que han adquirido compromisos respecto de la soja, el aceite de palma, la pulpa de madera o el papel y cuero. No obstante, el informe sugiere que queda mucho camino por recorrer.<\/p>\n<p class=\"\"><a target=\"_blank\" href=\"https:\/\/eur01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fforest500.org%2Fsearch%3Fkeywords%3Dsantander&amp;data=05%7C01%7Cplanetafuturo%40elpais.es%7C8ba3f5a7cfea48b15a7808db39cf758a%7Cc4fd49f3e15a44d882e2c909735d2e45%7C0%7C0%7C638167336490104927%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C3000%7C%7C%7C&amp;sdata=SXit2o17GCbkzr2v9K9AIHQsU7PW4lyR0Xwv%2BpnpF0M%3D&amp;reserved=0\" rel=\"noopener\">Banco Santander obtiene una puntuaci\u00f3n del 18%<\/a> y <a target=\"_blank\" href=\"https:\/\/eur01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fforest500.org%2Fsearch%3Fkeywords%3DBBVA&amp;data=05%7C01%7Cplanetafuturo%40elpais.es%7C8ba3f5a7cfea48b15a7808db39cf758a%7Cc4fd49f3e15a44d882e2c909735d2e45%7C0%7C0%7C638167336490104927%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C3000%7C%7C%7C&amp;sdata=nCMZ009FUsVe3FxgyhcerrQ3mlCv%2B4paxCs1PEdRpbU%3D&amp;reserved=0\" rel=\"noopener\">BBVA del 25%<\/a> (a mayor porcentaje, mejor nota). La primera entidad, que figura en el informe desde 2014 , ha mejorado sus indicadores respecto al a\u00f1o anterior. Sin embargo, la responsable de<i> Forest 500 <\/i>constata que sigue sin informar sobre las tasas de cumplimiento de sus compromisos para los cuatro productos con alto riesgo de deforestaci\u00f3n. El <a target=\"_blank\" href=\"https:\/\/forest500.org\/sites\/default\/files\/forest500_2021report.pdf\" rel=\"noopener\">informe de 2021<\/a> ya alertaba sobre esa misma cuesti\u00f3n. Seg\u00fan el documento, HSBC, Santander, Deutsche Financial institution y BNP Paribas ten\u00edan pol\u00edticas sobre deforestaci\u00f3n para por lo menos alg\u00fan producto de alto riesgo en sus carteras, pero tambi\u00e9n eran los que m\u00e1s dinero aportaban a empresas <i>Forest 500<\/i> sin ning\u00fan compromiso contra la deforestaci\u00f3n.<\/p>\n<blockquote class=\"a_q\">\n<p>Un tercio de las emisiones de gases de efecto invernadero procede de la deforestaci\u00f3n y la destrucci\u00f3n de ecosistemas; b\u00e1sicamente, para producir soja, aceite de palma, pulpa de madera, papel y cuero<\/p>\n<\/blockquote>\n<p class=\"\">Adem\u00e1s de aumentar la transparencia, la responsable de <i>Forest 500<\/i> recomienda a Banco Santander que extienda sus pol\u00edticas contra deforestaci\u00f3n y conversi\u00f3n de h\u00e1bitats a todos los ecosistemas naturales. Tambi\u00e9n lo insta a adoptar medidas robustas contra las violaciones de derechos humanos asociadas, teniendo en cuenta los derechos de los <a target=\"_blank\" href=\"https:\/\/elpais.com\/planeta-futuro\/2022-12-16\/la-nueva-ley-europea-contra-la-deforestacion-mundial-decepciona-a-los-indigenas.html\" rel=\"noopener\">pueblos ind\u00edgenas<\/a> y las comunidades locales a la tierra y a los recursos. Al BBVA tambi\u00e9n le extiende \u00e9sta \u00faltima recomendaci\u00f3n, adem\u00e1s de recomendar que fije una fecha l\u00edmite a partir de la cual sus clientes deban garantizar que sus operaciones y cadenas de suministro cumplen con los compromisos sobre deforestaci\u00f3n.<\/p>\n<p class=\"\">EL PA\u00cdS mand\u00f3 cuestionarios por correo electr\u00f3nico a las entidades espa\u00f1olas analizadas en <i>Forest 500.<\/i> Fuentes de Banco Santander evitaron comentar de forma espec\u00edfica la evaluaci\u00f3n, pero, remiti\u00e9ndose su informe anual, afirmaron que desde 2022 revisan la deforestaci\u00f3n reciente en granjas y ranchos de la Amazonia brasile\u00f1a para los que emiten pr\u00e9stamos y comprueban que no ocupen tierras ind\u00edgenas reconocidas por el Gobierno. Tambi\u00e9n revisan los criterios de sostenibilidad de clientes del sector del vacuno, la soja y la madera y que integran diversas iniciativas sobre buenas pr\u00e1cticas financieras en Brasil, aseguran. La valoraci\u00f3n de Banco Santander en <i>Forest 500<\/i> pas\u00f3 del 13% en 2021 al 18% en 2022.<\/p>\n<p class=\"\">Fuentes de BBVA destacaron su mejora en el ranquin de instituciones financieras del informe, donde ahora ocupa el octavo lugar con su puntuaci\u00f3n del 25%. Tambi\u00e9n se\u00f1alaron que BBVA est\u00e1 entre el 12% de las instituciones financieras comprometidas a ayudar a mejorar a los clientes que incumplen su <a target=\"_blank\" href=\"https:\/\/accionistaseinversores.bbva.com\/wp-content\/uploads\/2022\/10\/Marco-Ambiental-y-Social_Octubre-2022_esp.pdf\" rel=\"noopener\">pol\u00edtica contra la deforestaci\u00f3n<\/a>. Thomson celebra los avances, pero recuerda que la instituci\u00f3n financiera con mejor puntuaci\u00f3n s\u00f3lo alcanza el 50%: \u201cTodas tienen un largo camino por recorrer\u201d.<\/p>\n<p class=\"\">Inditex est\u00e1 considerada en el informe como uno de los grupos empresariales con mayor influencia del mundo en dos cadenas de suministro claves: la del cuero, que utiliza en productos como zapatos, bolsos y cinturones, y la de la pulpa de madera y papel, para hacer tejidos como la viscosa, celulosa y envoltorios. Su puntuaci\u00f3n <i>Forest 500<\/i> ha empeorado, pasando del 38% en 2020 al <a target=\"_blank\" href=\"https:\/\/forest500.org\/rankings\/companies\/inditex-sa\" rel=\"noopener\">26% en el \u00faltimo informe<\/a> (con datos de 2022). La ONG le aconseja reforzar el uso de pulpa y papel sostenibles, adoptar compromisos firmes para trazar el origen el cuero, y divulgar el cumplimiento de dichos objetivos. En 2021, <a target=\"_blank\" href=\"https:\/\/elpais.com\/planeta-futuro\/2021-12-28\/europa-destruir-selvas-para-hacer-calzoncillos.html\" rel=\"noopener\">EL PA\u00cdS inform\u00f3<\/a> sobre un an\u00e1lisis que conectaba a Inditex con proveedores de cuero causantes de deforestaci\u00f3n en la Amazonia. La compa\u00f1\u00eda, que tiene m\u00e1s de 7.000 comercios en 90 pa\u00edses, no ha respondido a las peticiones de comentario de este medio.<\/p>\n<p class=\"\">El otro grupo empresarial espa\u00f1ol en <i>Forest 500<\/i> es Ebro Meals, evaluado por ser uno de los mayores productores de alimentos del mundo. El grupo, que se dedica sobre todo a comercializar arroz y pastas, tiene una puntuaci\u00f3n de apenas el 8%. Fuentes de Ebro Meals han precisado que la empresa no utiliza aceite de palma y que en 2022 us\u00f3 456 toneladas m\u00e9tricas de soja, equivalentes al 0,02% de su consumo whole de materias primas. Lo que s\u00ed emple\u00f3 fueron 46.830 toneladas m\u00e9tricas de papel para embalajes. El papel que usa en Espa\u00f1a procede de bosques con certificados FSC (que garantizan que en el proceso se preserva la biodiversidad), aunque en el conjunto del grupo, el papel FSC solo representa un 14% del whole.<\/p>\n<p class=\"\">Fuentes corporativas afirman que, en aras de una mayor transparencia, este a\u00f1o divulgar\u00e1n informaci\u00f3n sobre desempe\u00f1o ambiental respondiendo a un cuestionario conocido como <a target=\"_blank\" href=\"https:\/\/www.cdp.net\/es\" rel=\"noopener\">CDP Forest<\/a>, dise\u00f1ado por una organizaci\u00f3n sin fines de lucro. World Cover anima a Ebro Meals a publicar m\u00e1s informaci\u00f3n sobre sus pol\u00edticas ambientales en su sitio net, adem\u00e1s de ampliar el uso de papel certificado y adoptar un compromiso contra la deforestaci\u00f3n para todos los productos de alto riesgo.<\/p>\n<p class=\"\"><i>Puedes seguir a PLANETA FUTURO en <\/i><a target=\"_blank\" href=\"https:\/\/twitter.com\/Planeta_Futuro\" rel=\"noopener\"><i>Twitter<\/i><\/a><i>, <\/i><a target=\"_blank\" href=\"https:\/\/www.facebook.com\/planetafuturoelpais\/\" rel=\"noopener\"><i>Facebook<\/i><\/a><i> e <\/i><a target=\"_blank\" href=\"https:\/\/www.instagram.com\/planetafuturo\/\" rel=\"noopener\"><i>Instagram<\/i><\/a><i>, y suscribirte <\/i><a target=\"_blank\" href=\"https:\/\/plus.elpais.com\/newsletters\/lnp\/1\/309\" rel=\"noopener\"><i>aqu\u00ed<\/i><\/a><i> a nuestra \u2018newsletter\u2019<\/i>.<\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><script async defer src=\"https:\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><br \/>\n<br \/><\/p>\n<p><em> \u2018 The preceding article may include information circulated by third parties \u2019 <\/em><\/p>\n<p><em> \u2018 Some details of this article were extracted from the following source elpais.com \u2019 <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los n\u00fameros son reveladores: un tercio de las emisiones de gases de efecto invernadero procede de la deforestaci\u00f3n y la destrucci\u00f3n de ecosistemas naturales; b\u00e1sicamente, para producir soja, aceite de palma, pulpa de madera, papel y cuero en lugares como la Amazonia, Indonesia y \u00c1frica central. Los objetivos globales de clima, biodiversidad y desarrollo sostenible [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":520307,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[43],"tags":[],"class_list":["post-520306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gourmet"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/520306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=520306"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/520306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/520307"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=520306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=520306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=520306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}