{"id":518452,"date":"2023-04-11T17:00:40","date_gmt":"2023-04-11T17:00:40","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=518452"},"modified":"2023-04-11T17:00:41","modified_gmt":"2023-04-11T17:00:41","slug":"quienes-son-los-ninos-gordos-de-la-calle-thames","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/quienes-son-los-ninos-gordos-de-la-calle-thames\/","title":{"rendered":"Qui\u00e9nes son los ni\u00f1os gordos de la calle Thames"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"com-paragraph  --capital --s\">Los llaman los due\u00f1os de la calle Thames y tienen raz\u00f3n. <strong>Germ\u00e1n Sitz y Pedro Pe\u00f1a, <\/strong>le hacen honor al t\u00edtulo por se padres de una familia compuesta de cinco eating places, todos amados por los foodies locales y los comensales del exterior.<\/p>\n<p class=\"com-paragraph   --s\">Ellos son los cooks y emprendedores detr\u00e1s de Ni\u00f1o Gordo, La Carnicer\u00eda, Chori, Paquito y Juan Pedro Caballero. Si de apariencias se trata, son el agua y el aceite. Germ\u00e1n Sitz, es un pampeano de eterno buen humor y sonrisa que suele vestir una remera que cube <em>meat<\/em> (carne). Siempre lleno de energ\u00eda, vive corriendo entre los locales o vigilando lo que pasa en su parrilla contempor\u00e1nea La Carnicer\u00eda. Adem\u00e1s, con 33 a\u00f1os, est\u00e1 casadoy tiene dos ni\u00f1os peque\u00f1os.<\/p>\n<p class=\"com-paragraph   --s\">A Pedro Pe\u00f1a se lo reconoce facilmente por la calle. El convirti\u00f3 su cuerpo en un lienzo para tatuadores y hasta lleva un cuchillo de tinta sobre su sien. El colombiano de 38 a\u00f1os suele estar acompa\u00f1ado por su perra Juana, un galgo de paso cansino, y un cigarrillo Dunhill en la mano. Es un dedicado coleccionista de zapatillas; ama los vinilos y tiene su coraz\u00f3n en Ni\u00f1o Gordo.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">Premiado en varias oportunidades, Ni\u00f1o Gordo es la estrella del d\u00fao. Adem\u00e1s de la propuesta gastron\u00f3mica, ofrece una ambientaci\u00f3n que te transporta a un planeta divertido y sabroso.<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph   --s\">Detr\u00e1s del escenario,  a Sitz lo conocen como \u201cEl ruso\u201d; y a Pe\u00f1a como \u201cEl gordo\u201d; y ambos aportan la parte financiera, administrativa y la creatividad del Grupo Thames. Juntos, son un maridaje estelar que concibi\u00f3 algunos de los restaurantes m\u00e1s emocionantes de la \u00faltima d\u00e9cada; y claro, se volvieron protagonistas de la gastronom\u00eda porte\u00f1a.<\/p>\n<p class=\"com-paragraph   --s\">Los dos cocineros son imigrantes en Buenos Aires, algo que uni\u00f3 sus antecedentes tan distintos como sus apariencias. Sitz naci\u00f3 en Rivera, un tranquilo pueblo agropecuario fundado por inmigrantes judios, rusos y polacos, y se fue a los 17 para cumplir su sue\u00f1o de ser cocinero.  Pe\u00f1a, amante del buen comer;  luego de formarse en dise\u00f1o editorial en Bogot\u00e1, decidi\u00f3 estudiar gastronom\u00eda. Como relata \u201cEl gordo\u201d, la gastronom\u00eda en Colombia, period un pasatiempo para se\u00f1oras mayores y por eso se mud\u00f3 a la Argentina. Entr\u00f3 en el Instituto Gato Dumas y comenz\u00f3 a trabajar para poder pagar las cuotas. Con Sitz se conocieron en Tipula, un restaurante que funcion\u00f3 Mart\u00ednez.<\/p>\n<p class=\"com-paragraph   --s\">\u201cEmpezamos como pares, \u00e9ramos ayudantes de cocina\u201d, cuenta Pe\u00f1a, \u201cyo hice mi carrera en Buenos Aires, mientras El Ruso viajaba a otros pa\u00edses para hacer pasant\u00edas. Termin\u00e9 como jefe de cocina y cuando \u00e9l estaba en Buenos Aires, lo llamaba porque yo siempre necesitaba gente y \u00e9l, trabajo. La rutina consist\u00eda en ganar tres mangos trabajando 16 horas por d\u00eda y volver juntos a Palermo en colectivo, cansados. Siempre hablando del futuro, y \u00e9l me dec\u00eda \u2018<em>vamos a montar un restaurante juntos<\/em>\u2019\u201d.<\/p>\n<p class=\"com-paragraph   --s\">Ambos lejos de sus casas, tambi\u00e9n los uni\u00f3 la soledad del inmigrante  \u201cEl porte\u00f1o tiene su grupo de amigos de toda la vida, y entonces los domingos nosotros no ten\u00edamos con quien almorzar;  as\u00ed que hac\u00edamos comidas familiares\u201d, recuerda Sitz. En esa mesa, se fortaleci\u00f3 su amistad.<\/p>\n<p class=\"com-paragraph   --s\"><strong>Volar juntos<\/strong><\/p>\n<p class=\"com-paragraph   --s\">A trav\u00e9s de los a\u00f1os, acumularon experiencia en diversas cocinas. Los dos pasaron por el Restaurante HG, y Pe\u00f1a se fue a hacer la apertura de Florer\u00eda Atl\u00e1ntico, el bar de Tato Giovannoni.<\/p>\n<p class=\"com-paragraph   --s\">Por su lado, Sitz le sac\u00f3 el jugo al mundo de las estrellas Michelin en el restaurant de Mart\u00edn Berasategui en el Pa\u00eds Vasco. En Buenos Aires, estuvo en La Bourgogne del Alvear Palace Resort; en Astrid &amp; Gast\u00f3n, y trabaj\u00f3 como productor gastron\u00f3mico del programa <em>Cocineros Argentinos<\/em>.<\/p>\n<p class=\"com-paragraph   --s\">En un momento, peg\u00f3 un giro de 360\u00b0. Dej\u00f3 las hornallas para vender textiles en Flores: \u201cah\u00ed aprend\u00ed a hacer negocios\u201d, cube. Fue el preludio de su rol en Grupo Thames. Cuatro a\u00f1os despu\u00e9s de volver a la gastronom\u00eda, Sitz sinti\u00f3 que algo ten\u00eda que cambiar y con Pedro ten\u00edan en claro que no quer\u00edan hacer m\u00e1s la comida de otras personas. Ah\u00ed empezaron a proyectar lo que vendr\u00eda.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">Arrancaron el gastro imperio, con un pr\u00e9stamo de la abuela y un trabajo que nunca par\u00f3. <\/span><span class=\"com-text --credit --twoxs\">ChuRk<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph   --s\">Una de las concepts de Germ\u00e1n Sitz period un native con despacho de comida para oficinistas en el Microcentro. \u201cDespu\u00e9s de haber estudiado gastronom\u00eda,\u201d cube Pe\u00f1a, \u201cabrir b\u00e1sicamente un supermercado de comidas, me parec\u00eda lo m\u00e1s est\u00fapido, entonvces nos planteamos un restaurante serio\u201d. Les parec\u00eda raro que no existiera el concepto de una parrilla contempor\u00e1nea en Buenos Aires. \u00bfPor qu\u00e9 la carne sal\u00eda sobrecocida en las parrillas del barrio? \u00bfPor qu\u00e9 no hab\u00eda una b\u00fasqueda de productos de alta calidad? La dupla quiso entonces aplicar su visi\u00f3n basada en el respeto a la prote\u00edna m\u00e1s valiosa, poner en valor la carne y aportar una mirada fresca. Quer\u00edan adem\u00e1s, atraer a los turistas. Y pese a sus nutridas trayectorias, la alta cocina no period una opci\u00f3n para ellos.<\/p>\n<p class=\"com-paragraph   --s\">\u201cTrabajar con men\u00fa por pasos nos ense\u00f1\u00f3 que ese tipo de cocina es para el ego del cocinero, nada m\u00e1s, adem\u00e1s econ\u00f3micamente nunca funcionaba\u201d, explica Pe\u00f1a. En todos los restaurantes donde estuvimos, por m\u00e1s que les fuera bien, las ganancias eran \u00ednfimas. Entonces, apostamos a revalidar un concepto y traerlo a la modernidad\u201d.<\/p>\n<p class=\"com-paragraph   --s\">Usaron como base lo que ten\u00edan; el ganado de la familia Sitz en Rivera. El pueblo, fundado por familias jud\u00edas, cre\u00f3 una cooperativa: la Sociedad Agropecuaria de Rivera, que contaba con todos los aspectos de la ganader\u00eda, tambo, engorde y frigorifico. La dupla aprovech\u00f3 esta fuente c\u00e1rnica para su visi\u00f3n de \u2018la nueva parrilla porte\u00f1a\u2019.<\/p>\n<p class=\"com-paragraph   --s\">La carne de Estancia Los Abuelos en Rivera les permit\u00eda darle una identidad fuerte al emprendimiento. Su restaurante empezaba a tomar forma. Pero los j\u00f3venes necesitaban financiar este proyecto de alguna manera, y ah\u00ed entr\u00f3 Fanny Klausner, la abuela de Sitz, con un pr\u00e9stamo.<\/p>\n<p class=\"com-paragraph   --s\">\u201cSolo ten\u00edamos esa plata y ten\u00edamos que apostarle al caballo ganador\u201d, recuerda Pe\u00f1a. \u201cPensamos: Argentina, extranjeros, el producto n\u00famero uno es la carne y hagamos algo diferente de las 2.000 parrillas de Buenos Aires. Hicimos el primer restaurante de carne\u201d.<\/p>\n<p class=\"com-paragraph   --s\">La Carnicer\u00eda abri\u00f3 en 2014 en Thames 2317 donde antes hab\u00eda una vieja parrilla de la escuela de las carnes quemadas. Inmediatamente, se destac\u00f3 por la enorme foto de media rese que cubr\u00eda una de las paredes del native, la barra frente a las brasas y los vistosos cortes con hueso que pesan 900 gramos. Su molleja caramelizada period una fiesta para los paladares porte\u00f1os. Entre chispas y humo, crearon una nueva experiencia de parrilla. Pero, mientras los comensales disfrutaban de las mejores carnes vacunas y de cocciones diferentes como los ahumados, atr\u00e1s del escenario, pasaban cosas.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">En La Carnicer\u00eda, la calidad y el cuidado del producto es lo que diferencia la propuesta de este restaurante de carnes.<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph   --s\">\u201cCuando abrimos, no contratamos a nadie porque no sab\u00edamos si \u00edbamos a poder generar plata para pagarles\u201d, cuenta Sitz, \u201cnos arregl\u00e1bamos con mi hermano Ariel y mi primo Pablo Barg en la sala; mientras nosotros est\u00e1bamos en la cocina. Unos meses despu\u00e9s contratamos a un bachero.\u201d<\/p>\n<p class=\"com-paragraph   --s\">Cada uno fue entendiendo su rol. \u201cNunca tomamos el camino f\u00e1cil para llegar al negocio exitoso\u201d, cuenta Pe\u00f1a, \u201cninguno sab\u00eda de administraci\u00f3n pero Germ\u00e1n la tom\u00f3 y yo me concentr\u00e9 en la cocina\u201d. En seis meses, La Carnicer\u00eda period el furor de los turistas y los medios. Al a\u00f1o, le devolvieron su inversi\u00f3n a la abuela Fanny. \u201cAh\u00ed dijimos; hay que hacer otro restaurante,\u201d cube Sitz.<\/p>\n<p class=\"com-paragraph   --s\"><strong>Chori-fan<\/strong><\/p>\n<p class=\"com-paragraph   --s\">Gracias a su costumbre de salir de lo com\u00fan, se les acerc\u00f3 una empresa nacional para abrir una hamburgueser\u00eda y aprovechar el increase del momento. Empezaron a conversar pero la thought no les cerraba. Quer\u00edan desarrollar un concepto apto para todo el p\u00fablico, que se pudiera replicar. Con una apuesta por la simpleza de un producto tan noble como argentino y as\u00ed naci\u00f3 Chori, la primera choripaner\u00eda connoisseur y una nueva marca de quick meals argentina, en 2016.<\/p>\n<p class=\"com-paragraph   --s\">\u201cEl chorip\u00e1n es la segunda cosa que com\u00ed cuando llegu\u00e9 a la Argentina\u201d, recuerda Pe\u00f1a, \u201cno pod\u00eda creer que en el pa\u00eds de este s\u00e1ndwich emblem\u00e1tico, no hubiera un local especializado m\u00e1s all\u00e1 de los puestos de la Costanera: Chori es nuestra interpretaci\u00f3n de la comida r\u00e1pida.\u201d<\/p>\n<p class=\"com-paragraph   --s\">Aprovechando el gran momento de las hamburgueser\u00edas estilo norteam\u00e9ricano, adaptaron el concepto y metieron el ADN argentino para abrir Chori, en Thames 1653. \u201cUsamos el pan redondo de una hamburguesa, ofrecemos toppings, y al principio hicimos los chorizos en casa hasta que la infraestructura no nos lo permiti\u00f3 m\u00e1s\u201d, cuenta Sitz. Hoy hay, adem\u00e1s del unique, franquicias en La Plata y Rosario.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">Chori, la gran thought de quick meals argentino de Pedro y Germ\u00e1n.<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph   --s\"><strong>La estrella<\/strong><\/p>\n<p class=\"com-paragraph   --s\">La vedette es Ni\u00f1o Gordo, parrilla asi\u00e1tica que debut\u00f3 en el high 100 de los premios Latin America\u2019s 50 Greatest Eating places 2022.<\/p>\n<p class=\"com-paragraph   --s\">Pedro Pe\u00f1a recorri\u00f3 Asia durante cuatro meses buscando inspiraci\u00f3n, probando comida taiwanesa, coreana, japonesa y tailandesa, road meals y alta cocina, para poder crear con esas bases un concepto argentino.<\/p>\n<p class=\"com-paragraph   --s\">\u201cVi que la cocina asi\u00e1tica pegaba fuerte en el mundo y que hab\u00eda un boom m\u00e1s all\u00e1 del sushi. Ese viaje me abri\u00f3 la cabeza y aprend\u00ed de globalizaci\u00f3n y redes sociales\u201d, cube Pe\u00f1a. \u201cEntend\u00ed que necesit\u00e1bamos un restaurante con la impronta argentina de carne, fuego y parrilla pero con el aporte de t\u00e9cnicas y productos asi\u00e1ticos. Y entend\u00ed que Ni\u00f1o Gordo ten\u00eda que ser adem\u00e1s, <em>instagrameable<\/em>\u201d.<\/p>\n<p class=\"com-paragraph   --s\">Y as\u00ed fue. La est\u00e9tica es protagonista. Todos quieren su selfie con la imperdible fachada de fondo, decorada con un enorme globo de un feliz ni\u00f1o gordo. Al entrar, cautiva la iluminaci\u00f3n predominantemente roja, los tanques de medusas, los juguetes kitsch y las mesas bajitas. Una ambientaci\u00f3n que te transporta a un planeta divertido y sabroso. Usando el modelo de La Carnicer\u00eda, hay una barra frente a las brasas, atendida por Pe\u00f1a y el chef mexicano Omar Hern\u00e1ndez, donde ejecutan otro estilo de parrilla. Un aparrilla que incorpora las t\u00e9cnicas culinarias asi\u00e1ticas. Dieron una vuelta al katsu sando, reemplazando el cerdo del cl\u00e1sico sandwich <em>y\u014dshoku<\/em> por bife de chorizo. Otro hit del men\u00fa es el tataki, lonjas crudas de bife con wasabi y shiso. La carne obviamente viene de Estancia Los Abuelos.<\/p>\n<p class=\"com-paragraph   --s\">\u201cNi\u00f1o Gordo es un gran ejemplo de c\u00f3mo hacer que el comensal se sienta c\u00f3modo y comparta nuestro mundo\u201d, cube Pe\u00f1a. Esa magia, combinada con platos ricos y una cocteler\u00eda divertida, hizo que alcancen el puesto 75 en los Latin America\u2019s 50 Greatest Eating places. Ya que le tomaron el gusto al podio, van a ir por m\u00e1s\u2014pero sin perder los objetivos: \u201ccuando los 50 Best subieron la foto del tataki, se doblaron los pedidos de ese plato\u201d, cuenta Pe\u00f1a, \u201ctambi\u00e9n es s\u00faper lindo recibir el aliento, la palmada en la espalda, en especial para los chicos que trabajan con nosotros, pero lo importante es que el local est\u00e9 lleno y genere trabajo, ese es el mejor reconocimiento\u201d.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">&#8220;Hacer un lugar instagrameble&#8221;, dijeron al pensar en Ni\u00f1o Gordo. Todos quieren la selfie con el globo. Al entrar, cautiva la iluminaci\u00f3n predominantemente roja, los tanques de medusas, los juguetes kitsch y las mesas bajitas.<\/span><span class=\"com-text --credit --twoxs\">Rodrigo Ruiz Ciancia<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph   --s\">Seg\u00fan Sitz, no hacen nada distinto de lo que hac\u00edan hace cinco a\u00f1os, solo han cambiado la manera de comunicarlo. \u201cEl mejor es quien lo cuenta mejor, nos dimos vuelta y buscamos mostrar los mismos productos, conceptos y clientes, pero ahora con un ojo sobre los 50 Best .<\/p>\n<p class=\"com-paragraph   --s\"><strong>Sorteando obst\u00e1culos<\/strong><\/p>\n<p class=\"com-paragraph   --s\">M\u00e1s all\u00e1 de los elogios, a veces hay obst\u00e1culos por superar. En 2022, dejaron dos negocios\u2014Delta en Rosario y El Dorado en Puerto Madero\u2014mientras reinventaron otros. Pero de los errores, siempre se aprende.<\/p>\n<div class=\"content-media\">\n<section role=\"button\" class=\"mod-media   \">\n<figure role=\"button\" class=\"mod-figure \"><figcaption class=\"mod-figcaption\"><span class=\"com-text --caption --twoxs\">\u201cPensamos: Argentina, extranjeros, el producto n\u00famero uno es la carne y hagamos algo diferente de las 2.000 parrillas de Buenos Aires. Hicimos el primer restaurante de carne\u201d. cube Germ\u00e1n.<\/span><\/figcaption><\/figure>\n<\/section>\n<\/div>\n<p class=\"com-paragraph   --s\">\u201cCuando vimos la oportunidad de trabajar con caf\u00e9 de especialidad en 2018, abrimos Juan Pedro Caballero como una churrer\u00eda. Pero los cubiertos eran pocos, as\u00ed que lo transformamos en una taquer\u00eda tambi\u00e9n\u201d, cuenta Sitz \u201cpara esto aprovechamos el expertise de nuestro chef mexicano Omar, lo sumamos como socio y aprendimos de cubiertos y n\u00fameros\u201d.<\/p>\n<p class=\"com-paragraph   --s\">En cuanto a los restaurantes fuera del circuito de la calle Thames, el desaf\u00edo period la presencialidad. \u201cPara que las cosas salgan bien, hay que estar. Y no pudimos f\u00edsicamente\u201d, cuenta Pe\u00f1a, \u201ctambi\u00e9n aprendimos con quien asociarnos, si no son nuestras ideas y no lo disfrutamos, vamos a fracasar\u201d.<\/p>\n<p class=\"com-paragraph   --s\">En el futuro inmediato, se viene el libro <em>Ni\u00f1o Gordo<\/em>, de Editorial Catapulta, y en octubre levantar\u00e1n la persiana de dos nuevos emprendimientos sobre Thames. Una barra de carnes para 13 comensales y un restaurante de pastas.<\/p>\n<p class=\"com-paragraph   --s\">Su creatividad les abri\u00f3 un nuevo camino, el del way of life por lo que crearon las zapatillas Ni\u00f1o en colaboraci\u00f3n con Vans.  Tambi\u00e9n 2023 les entregar\u00e1 un proyecto bien ambicioso;  una versi\u00f3n gringa de Ni\u00f1o Gordo desembarcar\u00e1 en el barrio Wynwood de Miami. Al haber aprendido de anteriores experiencias, habr\u00e1 presencialidad por periodos largos donde Pe\u00f1a liderar\u00e1 el Proyecto. \u201cDisfruto mucho compartir el cari\u00f1o que significa dar de comer. Es mi cable a tierra pero para que salga bien lo de Miami, tendremos que ir con frecuencia\u201d.<\/p>\n<section class=\"mod-trust --twoxs  --trust\"><a target=\"_blank\" href=\"https:\/\/www.lanacion.com.ar\/tema\/the-trust-project-tid68036\/\" title=\"Ir a Proyecto Trust\" class=\"com-link --twoxs\" rel=\"noopener\">Conoc\u00e9 The Trust Project<\/a><\/section>\n<\/div>\n\n<p><em> \u2018 The preceding article may include information circulated by third parties \u2019 <\/em><\/p>\n<p><em> \u2018 Some details of this article were extracted from the following source www.lanacion.com.ar \u2019 <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los llaman los due\u00f1os de la calle Thames y tienen raz\u00f3n. Germ\u00e1n Sitz y Pedro Pe\u00f1a, le hacen honor al t\u00edtulo por se padres de una familia compuesta de cinco eating places, todos amados por los foodies locales y los comensales del exterior. Ellos son los cooks y emprendedores detr\u00e1s de Ni\u00f1o Gordo, La Carnicer\u00eda, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":518453,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[43],"tags":[],"class_list":["post-518452","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gourmet"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/518452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=518452"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/518452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/518453"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=518452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=518452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=518452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}