{"id":1187778,"date":"2026-07-26T20:06:30","date_gmt":"2026-07-26T20:06:30","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=1187778"},"modified":"2026-07-27T01:12:06","modified_gmt":"2026-07-27T01:12:06","slug":"mal-olor-corporal-preocupa-a-mas-del-70-de-las-personas","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/mal-olor-corporal-preocupa-a-mas-del-70-de-las-personas\/","title":{"rendered":"MAL OLOR CORPORAL PREOCUPA A M\u00c1S DEL 70% DE LAS PERSONAS."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por Susana Canalizo, Dermat\u00f3loga egresada de la Universidad NacionalAut\u00f3noma de M\u00e9xico y Presidenta de la de la Fundaci\u00f3n Mexicana para la Dermatolog\u00eda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante d\u00e9cadas, el desodorante estuvo casi exclusivamente asociado a las axilas. Sin embargo, los cambios en los h\u00e1bitos de autocuidado y una mayor conversaci\u00f3n en torno al bienestar han comenzado a modificar la forma en que entendemos el control del mal olor corporal.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"500\" height=\"400\" data-id=\"1187779\" src=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2026\/07\/11derma.jpg\" alt=\"\" class=\"wp-image-1187779\" srcset=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2026\/07\/11derma.jpg 500w, https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2026\/07\/11derma-300x240.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Las rutinas de cuidado, la sensaci\u00f3n de frescura y la protecci\u00f3n de la piel influyen de manera significativa en la comodidad y la confianza con la que las personas enfrentan su d\u00eda a d\u00eda. No resulta extra\u00f1o, entonces, que cada vez m\u00e1s consumidoras busquen soluciones para \u00e1reas del cuerpo sensibles por el sudor, la humedad o la fricci\u00f3n, como la zona submamaria, la espalda, los muslos, las ingles o algunos pliegues de la piel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con una investigaci\u00f3n realizada por Unilever y Ter\u00e1n (2024), el 74% de las personas afirma haber experimentado preocupaci\u00f3n por el mal olor en \u00e1reas distintas a las axilas, mientras que casi la mitad se\u00f1ala que no utilizar &nbsp;los desodorantes en esas zonas porque los productos disponibles no fueron dise\u00f1ados para ese prop\u00f3sito. A ello se suma que el 35 % de las personas manifiesta inter\u00e9s en probar nuevos formatos para el cuidado de todo el cuerpo, seg\u00fan datos de Mintel (2023).<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"500\" height=\"751\" data-id=\"1187780\" src=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2026\/07\/2dove-2.jpg\" alt=\"\" class=\"wp-image-1187780\" srcset=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2026\/07\/2dove-2.jpg 500w, https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2026\/07\/2dove-2-200x300.jpg 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Estas cifras reflejan una evoluci\u00f3n en la manera de entender el cuidado personal: este deja de centrarse \u00fanicamente en ocultar el sudor para responder a necesidades particulares relacionadas con el bienestar y la protecci\u00f3n de la piel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy existe una mayor comprensi\u00f3n de que distintas zonas del cuerpo son sensibles al sudor, la humedad y la fricci\u00f3n, por lo que demandan productos para utilizarse de manera segura m\u00e1s all\u00e1 de las axilas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En respuesta a esta evoluci\u00f3n, la industria del cuidado personal ha comenzado a desarrollar soluciones m\u00e1s especializadas, capaces de combinar eficacia con protecci\u00f3n de la piel.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"500\" height=\"281\" data-id=\"1187782\" src=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2026\/07\/1dove-1.jpg\" alt=\"\" class=\"wp-image-1187782\" srcset=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2026\/07\/1dove-1.jpg 500w, https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2026\/07\/1dove-1-300x169.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las propuestas m\u00e1s recientes es All Body Deo, una l\u00ednea dise\u00f1ada por Dove para incorporarse de forma natural a la rutina diaria de autocuidado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Su f\u00f3rmula incorpora vitamina B3, glicerina y aceites nutritivos, ingredientes que contribuyen a fortalecer la barrera cut\u00e1nea, mantenerla hidratada y ayudar a proteger la piel frente a los roces y el sudor, factores que pueden ocasionar irritaci\u00f3n en zonas sensibles. Todo el portafolio ha sido dermatol\u00f3gicamente probado, es libre de alcohol y aluminio y, en el caso de la crema, cuenta adem\u00e1s con prueba ginecol\u00f3gica. Con ello, la marca ofrece una alternativa pensada para el cuidado de distintas zonas del cuerpo sin comprometer la salud cut\u00e1nea.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"500\" height=\"751\" data-id=\"1187785\" src=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2026\/07\/4dove-1.jpg\" alt=\"\" class=\"wp-image-1187785\" srcset=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2026\/07\/4dove-1.jpg 500w, https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2026\/07\/4dove-1-200x300.jpg 200w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Durante a\u00f1os, muchas mujeres sintieron que deb\u00edan elegir entre una protecci\u00f3n eficaz contra el mal olor y un producto respetuoso con la piel. Hoy, el desarrollo de f\u00f3rmulas espec\u00edficas demuestra que ambas necesidades pueden convivir en una misma rutina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Responder a necesidades que durante mucho tiempo carecieron de soluciones especializadas refleja una visi\u00f3n m\u00e1s amplia del autocuidado: una que pone en el centro el conocimiento del cuerpo, la confianza y el desarrollo de soluciones respaldadas por la ciencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Susana Canalizo, Dermat\u00f3loga egresada de la Universidad NacionalAut\u00f3noma de M\u00e9xico y Presidenta de la de la Fundaci\u00f3n Mexicana para la Dermatolog\u00eda Durante d\u00e9cadas, el desodorante estuvo casi exclusivamente asociado a las axilas. Sin embargo, los cambios en los h\u00e1bitos de autocuidado y una mayor conversaci\u00f3n en torno al bienestar han comenzado a modificar la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1187786,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":{"format":"standard"},"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[144872,39],"tags":[],"class_list":["post-1187778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fashion","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/1187778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=1187778"}],"version-history":[{"count":1,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/1187778\/revisions"}],"predecessor-version":[{"id":1187787,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/1187778\/revisions\/1187787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/1187786"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=1187778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=1187778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=1187778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}