{"id":117474,"date":"2021-04-28T21:52:29","date_gmt":"2021-04-28T21:52:29","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=117474"},"modified":"2021-04-28T21:52:29","modified_gmt":"2021-04-28T21:52:29","slug":"el-infierno-que-pasan-los-inmigrantes-en-las-guaridas-de-los-coyotes-noticias-univision-criminalidad","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/el-infierno-que-pasan-los-inmigrantes-en-las-guaridas-de-los-coyotes-noticias-univision-criminalidad\/","title":{"rendered":"El infierno que pasan los inmigrantes en las guaridas de los coyotes | Noticias Univision Criminalidad"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div id=\"article-chunks\">\n<div class=\"\">\n<p>En solo 24 horas, agentes de la Patrulla Fronteriza detectaron a mediados de abril siete casas de seguridad usadas por <b><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.univision.com\/noticias\/inmigracion\/coyotes-mentirosos-dice-guatemalteca-que-termino-expulsada-mexico\">organizaciones dedicadas al tr\u00e1fico de inmigrantes <\/a><\/b>en Laredo, Texas. All\u00ed ten\u00edan hacinados a un complete de <b>112 indocumentados,<\/b> casi todos originarios de M\u00e9xico y Centroam\u00e9rica.<\/p>\n<\/div>\n<div class=\"\">\n<p>Operativos como este ocurren a menudo en Laredo, que es considerado uno de los principales centros de operaciones de los coyotes dentro de Estados Unidos. En esa ciudad que colinda con Nuevo Laredo (M\u00e9xico), <b>m\u00e1s de 1,200 inmigrantes<\/b> fueron detenidos en esos escondites del 1 de octubre de 2020 al pasado 27 de enero, <b>un aumento del 436%<\/b> comparado al mismo per\u00edodo del a\u00f1o fiscal anterior.<\/p>\n<\/div>\n<div class=\"\">\n<p>En esos lugares los indocumentados pasan varios d\u00edas, a veces sin agua potable, electricidad, ni comida. Pero no es lo \u00fanico que preocupa a las agencias del orden. Secuestros, <b><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.cbp.gov\/newsroom\/local-media-release\/alleged-rape-victim-among-46-immigrants-rescued-stash-house-rio-grande#\">violaciones<\/a><\/b> y robos siguen ocurriendo en esas guaridas, seg\u00fan reportes de la Patrulla Fronteriza.<\/p>\n<\/div>\n<div class=\"\">\n<p>Este martes, Alejandro Mayorkas, secretario de Seguridad Nacional (DHS), anunci\u00f3 una nueva operaci\u00f3n enfocada en organizaciones transnacionales que participan en el tr\u00e1fico de personas, advirtiendo que durante el a\u00f1o 2020 agentes fronterizos localizaron a <b>250 inmigrantes que murieron durante su viaje al norte.<\/b><\/p>\n<\/div>\n<div class=\"\">\n<p>El funcionario indic\u00f3 que no solo buscan arrestar a los gu\u00edas en el desierto, sino <b>golpear la estructura de sus c\u00e9lulas criminales.<\/b> Las acciones que realizar\u00e1n incluyen revocar documentos de viaje, suspender entidades comerciales y congelar cuentas bancarias y otros activos financieros vinculados a esos grupos.<\/p>\n<\/div>\n<div class=\"\">\n<p>\u201cTenemos la intenci\u00f3n de interrumpir todas las facetas de la red log\u00edstica que estas organizaciones utilizan para tener \u00e9xito\u201d, dijo Mayorkas en un comunicado.<\/p>\n<\/div>\n<p><h3 class=\"cms-H3-H3\">Secuestros a punta de pistola<\/h3>\n<\/p>\n<div class=\"\">\n<p><b><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.justice.gov\/usao-sdtx\/pr\/human-smugglers-sentenced-after-harboring-and-threatening-individuals-gun\">Baylee Lugo,<\/a><\/b> un coyote de 21 a\u00f1os, fue condenado en marzo a m\u00e1s de tres a\u00f1os de prisi\u00f3n por secuestrar a punta de pistola a cuatro indocumentados que hicieron una escala en Texas. La acusaci\u00f3n se\u00f1ala que en julio de 2020 el joven los retuvo en un lodge en Pharr, les rob\u00f3 sus celulares y el poco dinero que ten\u00eda, y <b>llam\u00f3 a sus familiares para pedirles un rescate. <\/b><\/p>\n<\/div>\n<div class=\"\">\n<p>Un reciente <b><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.cbp.gov\/frontline\/cbp-fights-human-smuggling-and-stash-houses\">informe<\/a><\/b> de la Oficina de Aduanas y Management Fronterizo (CBP) se\u00f1ala que, mientras est\u00e1n bajo el resguardo de estas bandas, los inmigrantes a menudo son retenidos por la fuerza y terminan pagando cuotas m\u00e1s altas.<\/p>\n<\/div>\n<div class=\"\">\n<p>\u201cMuchas veces los traficantes extorsionan pidiendo m\u00e1s dinero solo para tener a su \u2018cargamento humano\u2019 en p\u00fatridas condiciones insalubres. No pueden escapar porque a menudo est\u00e1n encerrados\u201d, dijo Kenneth Kroupa, supervisor de la Patrulla Fronteriza, citado en el reporte.<\/p>\n<\/div>\n<div class=\"\">\n<p>En el sureste de Texas, la franja que colinda con el estado mexicano de Tamaulipas, las autoridades han encontrado m\u00e1s casas operadas por \u2018polleros\u2019, como tambi\u00e9n les dicen. En el a\u00f1o fiscal 2020, que abarc\u00f3 del 1 de octubre de 2019 al pasado 30 de septiembre, agentes federales hallaron un complete de <b>397 escondites<\/b> en toda la frontera, de los cuales <b>103 estaban en Laredo y 141 en Edinburg. <\/b><\/p>\n<\/div>\n<div class=\"\">\n<p>La CBP asegura que el problema es mayor en esas ciudades texanas por la falta de una barrera f\u00edsica que detenga los cruces ilegales y porque <b>\u201cuna organizaci\u00f3n criminal internacional bien arraigada\u201d opera al otro lado de la frontera. <\/b><\/p>\n<\/div>\n<div class=\"\">\n<p>\u201cTradicionalmente han tenido control sobre esa \u00e1rea y el contrabando de extranjeros es un esfuerzo sumamente rentable para ellos\u201d, advirti\u00f3 Hudak.<\/p>\n<\/div>\n<p><h3 class=\"cms-H3-H3\">Vinculados a los carteles<\/h3>\n<\/p>\n<div class=\"\">\n<p><b><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.ice.gov\/news\/releases\/hsi-laredo-probe-results-more-5-year-sentence-convicted-felon-harboring-noncitizens\">Noe Garza<\/a><\/b> period operador de un grupo dedicado a esa actividad prison. Tiene 46 a\u00f1os y desde la adolescencia fue engrosando su historia prison. El caso m\u00e1s reciente ocurri\u00f3 el 28 de febrero de 2020, cuando la Polic\u00eda le orden\u00f3 que detuviera su auto y este huy\u00f3 protagonizando una persecuci\u00f3n.<\/p>\n<\/div>\n<div class=\"\">\n<p>Lo capturaron poco despu\u00e9s y termin\u00f3 confesando que estaba a cargo de una casa en Edingurg, en la cual recib\u00eda a inmigrantes. Tambi\u00e9n coordinaba sus viajes hacia otros estados. Al llegar al lugar, agentes federales <b>rescataron a cinco indocumentados<\/b> y confiscaron dos armas de fuego. Garza ten\u00eda otra arma en el coche. A finales de marzo <b>lo sentenciaron a m\u00e1s de cinco a\u00f1os de c\u00e1rcel. <\/b><\/p>\n<\/div>\n<div class=\"\">\n<p>Se sabe que los carteles est\u00e1n involucrados en el tr\u00e1fico humano o les pagan derecho de piso. Uno de ellos es el de <b><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.univision.com\/temas\/cartel-de-sinaloa\">Sinaloa; <\/a><\/b>otro es el del <b><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.univision.com\/noticias\/inmigracion\/decian-que-si-no-pagabamos-al-nino-le-iban-a-sacar-los-organos-la-angustia-de-una-madre-migrante-secuestrada-por-el-cartel-del-golfo\">Golfo.<\/a><\/b> Por eso no es extra\u00f1o que confisquen droga y armas de fuego en los sitios donde esconden a los indocumentados.<\/p>\n<\/div>\n<p><iframe height=\"0\" srcdoc=\"&lt;blockquote class=&quot;twitter-tweet&quot;&gt;&lt;p lang=&quot;en&quot; dir=&quot;ltr&quot;&gt;RGV Sector agents and law enforcement partners shut down five stash houses resulting in the apprehension of 69 illegal aliens. &lt;br&gt;&lt;br&gt;Since October, approximately 3,400 illegal aliens have been apprehended.&lt;a href=&quot;https:\/\/twitter.com\/CBPRGV?ref_src=twsrc%5Etfw&quot;&gt;@CBPRGV&lt;\/a&gt; &lt;a href=&quot;https:\/\/t.co\/iO5ytLHSg1&quot;&gt;pic.twitter.com\/iO5ytLHSg1&lt;\/a&gt;&lt;\/p&gt;&amp;mdash; Chief Patrol Agent Brian Hastings (@USBPChiefRGV) &lt;a href=&quot;https:\/\/twitter.com\/USBPChiefRGV\/status\/1380573759380332557?ref_src=twsrc%5Etfw&quot;&gt;April 9, 2021&lt;\/a&gt;&lt;\/blockquote&gt;&#10;&lt;script async src=&quot;https:\/\/platform.twitter.com\/widgets.js&quot; charset=&quot;utf-8&quot;&gt;&lt;\/script&gt;&#10;\" scrolling=\"no\" title=\"socialEmbed-twitter\" class=\"sc-1samzfd-1 eqhtlM\"><\/iframe><\/p>\n<div class=\"\">\n<p>Una pr\u00e1ctica com\u00fan de los coyotes es <b>quitarles los celulares a los inmigrantes <\/b>para evitar que le llamen a la polic\u00eda o a sus familiares cuando est\u00e1n en apuros.<\/p>\n<\/div>\n<div class=\"\">\n<p>De esa manera, un grupo de 46 indocumentados logr\u00f3 que los liberaran de una propiedad en Edinburg durante el verano de 2016. Uno de ellos marc\u00f3 al 911 para reportar que \u00e9l y varias personas <b>estaban detenidos en contra de su voluntad.<\/b> La Polic\u00eda de Pharr encontr\u00f3 all\u00ed a decenas de inmigrantes de M\u00e9xico, El Salvador, Guatemala y Honduras.<\/p>\n<\/div>\n<div class=\"\">\n<p>\u201cUna de las inmigrantes, una ciudadana salvadore\u00f1a, afirm\u00f3 que fue violada por dos traficantes que grabaron el acto en una tableta iPad\u201d, de acuerdo con <b><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.cbp.gov\/newsroom\/local-media-release\/alleged-rape-victim-among-46-immigrants-rescued-stash-house-rio-grande#\">un comunicado<\/a><\/b> de la CBP.<\/p>\n<\/div>\n<p><h3 class=\"cms-H3-H3\">\u201cNos tra\u00edan una pizza al d\u00eda\u201d<\/h3>\n<\/p>\n<div class=\"\">\n<p>A pesar de los constantes operativos de la Patrulla Fronteriza y polic\u00edas locales, los coyotes siguen operando a sus anchas en Edinburg, que est\u00e1 cerca de la ciudad mexicana de Reynosa, Tamaulipas.<\/p>\n<\/div>\n<div class=\"\">\n<p>Hace dos meses, los coyotes perdieron una de sus guaridas en esa zona. La Polic\u00eda de Pharr investig\u00f3 el lugar y pidi\u00f3 ayuda a la Patrulla Fronteriza. Al ingresar a la vivienda encontraron a <b><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.cbp.gov\/newsroom\/local-media-release\/agents-discover-71-illegal-aliens-stash-houses-rio-grande-valley-texas\">71 indocumentados,<\/a><\/b> incluyendo tres ni\u00f1os que viajaban solos. Todos eran de M\u00e9xico y de Centroam\u00e9rica.<\/p>\n<\/div>\n<div class=\"\">\n<p><b>\u201cNo les importa la gente\u201d,<\/b> dijo Oscar Joanicot, supervisor de la Patrulla Fronteriza en Yuma (Arizona) y quien es mencionado en el reporte de la CBP. \u201cCuando hablas con estos indocumentados dicen: &#8216;Nos tra\u00edan una pizza una vez al d\u00eda o algo as\u00ed&#8217;. Les dan lo m\u00ednimo, porque (los coyotes) no quieren pagar la comida de sus ganancias\u201d, agreg\u00f3.<\/p>\n<\/div>\n<div class=\"\">\n<p>En Yuma descubrieron 8 viviendas usadas para ese fin el a\u00f1o pasado.<\/p>\n<\/div>\n<p><h3 class=\"cms-H3-H3\">Escondites en vecindarios poblados<\/h3>\n<\/p>\n<div class=\"\">\n<p>En San Diego, California, pocas veces encuentran casas repletas de inmigrantes, pues lo com\u00fan es llevar directamente a los \u201cclientes\u201d hasta Los \u00c1ngeles y luego a sus destinos finales, de acuerdo con la CBP.<\/p>\n<\/div>\n<div class=\"\">\n<p>\u201cSol\u00edan pagar alrededor de 200 d\u00f3lares por persona para cruzar, as\u00ed que empacaban a tantos como pod\u00edan en un auto\u201d, explic\u00f3 Mark Hansen, supervisor de la CBP en San Diego.<\/p>\n<\/div>\n<div class=\"\">\n<p>\u201cAhora, est\u00e1n pagando 8,000 d\u00f3lares o m\u00e1s por persona, as\u00ed que vale la pena enviar a una persona de Los \u00c1ngeles a recoger a una o dos personas. As\u00ed que no hay necesidad de ir a un escondite\u201d, agreg\u00f3.<\/p>\n<\/div>\n<div class=\"\">\n<p>Los agentes fronterizos han notado que los coyotes ya no dejan a los indocumentados en escondites localizados en zonas remotas, sino <b>en barrios poblados.<\/b> A veces los colocan en casas m\u00f3viles dentro de una propiedad. Son los propios vecinos quienes los denuncian a la Polic\u00eda.<\/p>\n<\/div>\n<div class=\"\">\n<p>Una de esas llamadas fue atendida por la Patrulla Fronteriza y la Polic\u00eda de Laredo durante la noche del pasado 15 de abril. El denunciante los condujo hasta una residencia en el sur de Laredo. Al registrar una casa m\u00f3vil en p\u00e9simas condiciones, encontraron a <b><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.cbp.gov\/newsroom\/local-media-release\/laredo-sector-border-patrol-and-law-enforcement-partners-apprehend\">87 inmigrantes<\/a><\/b> de M\u00e9xico, Guatemala y El Salvador.<\/p>\n<\/div>\n<div class=\"\">\n<p>Eran tantos, que los sentaron en el suelo y formaron cuatro filas para que todos salieran en una foto. Nadie mir\u00f3 hacia el agente que captur\u00f3 la imagen.<\/p>\n<\/div>\n<div class=\"_3Z6x4 _1VnBC\">\n<div class=\"_1Bqzp\">\n<h2\/>\n<div class=\"_1wC8p\">\n<div class=\"_3F4l9\">\n<div class=\"_2MFxX\"><img decoding=\"async\" alt=\"Loading\" src=\"https:\/\/www.univision.com\/_next\/static\/images\/loader.049052d69532981b9be0f9f945c41551.svg\" class=\"_3W1HL\"\/><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<p><em> &#8221; Fuentes www.univision.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En solo 24 horas, agentes de la Patrulla Fronteriza detectaron a mediados de abril siete casas de seguridad usadas por organizaciones dedicadas al tr\u00e1fico de inmigrantes en Laredo, Texas. All\u00ed ten\u00edan hacinados a un complete de 112 indocumentados, casi todos originarios de M\u00e9xico y Centroam\u00e9rica. Operativos como este ocurren a menudo en Laredo, que es [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[40],"tags":[],"class_list":["post-117474","post","type-post","status-publish","format-standard","hentry","category-industria"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/117474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=117474"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/117474\/revisions"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=117474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=117474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=117474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}