{"id":1153523,"date":"2026-05-13T20:41:06","date_gmt":"2026-05-13T20:41:06","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=1153523"},"modified":"2026-05-13T20:41:06","modified_gmt":"2026-05-13T20:41:06","slug":"farmacias-del-ahorro-apunta-a-liberar-100-mil-horas-operativas-con-gemini-enterprise-en-12-meses","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/farmacias-del-ahorro-apunta-a-liberar-100-mil-horas-operativas-con-gemini-enterprise-en-12-meses\/","title":{"rendered":"Farmacias del Ahorro apunta a liberar 100 mil horas operativas con Gemini Enterprise en 12 meses"},"content":{"rendered":"\n<p>Farmacias del Ahorro present\u00f3 \u201cPotencIA\u201d, este programa nace para trascender y convertirse en un aliado integral de bienestar, transformando la experiencia de compra y atenci\u00f3n al cliente: al automatizar y redise\u00f1ar la operaci\u00f3n, impulsado por Gemini Enterprise, una plataforma integral que se conecta a cada trabajador con la mejor de la IA de Google a trav\u00e9s de una interfaz de chat intuitiva que act\u00faa como una \u00fanica puerta de entrada para el uso de IA en el trabajo, con esto eliminamos las barreras administrativas que consumen tiempo valioso. Esto nos permite evolucionar hacia un servicio m\u00e1s \u00e1gil y personalizado.<\/p>\n\n\n\n<p>El programa se estructura en tres etapas de madurez tecnol\u00f3gica, que ser\u00e1n desarrolladas en 12 meses, liberando cerca de 100,000 horas para que los equipos puedan enfocarse en proyectos de mayor impacto, permitiendo que las personas desarrollen nuevas habilidades y competencias digitales al trabajar con IA. Seg\u00fan Santos Arce, Director Ejecutivo de Experiencia del Cliente e Innovaci\u00f3n, esta evoluci\u00f3n busca que los colaboradores trasciendan las tareas manuales para liderar proyectos de alto impacto.<\/p>\n\n\n\n<p>Este despliegue responde a un diagn\u00f3stico de la compa\u00f1\u00eda que identific\u00f3 una oportunidad de escalabilidad en la adopci\u00f3n de inteligencia artificial, as\u00ed como en el uso de agentes y el desarrollo de habilidades clave como el prompting. La integraci\u00f3n de Gemini Enterprise busca cerrar esta brecha, democratizando el acceso a herramientas de productividad avanzada en \u00e1reas como Recursos Humanos, Tecnolog\u00edas de la Informaci\u00f3n, Marketing, experiencia de cliente y la gesti\u00f3n de su e-commerce.<\/p>\n\n\n\n<p>\u201cCon el programa PotencIA, estamos poniendo en el centro la experiencia de nuestros clientes, tanto internos como externos. Hacia afuera, buscamos habilitar modelos personalizados que nos acerquen m\u00e1s a sus necesidades. Hacia adentro, el objetivo es potenciar la eficiencia y productividad, liberando a nuestros colaboradores de tareas operativas para que puedan enfocarse en funciones de mayor valor estrat\u00e9gico. Se trata de una evoluci\u00f3n en la que la tecnolog\u00eda y el talento humano se combinan para fortalecer nuestro liderazgo en el sector salud\u201d, mencion\u00f3 Hern\u00e1n Garza, Head of AI en Farmacias del Ahorro<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"500\" height=\"267\" data-id=\"1153524\" src=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2026\/05\/4AHORRO.jpg\" alt=\"\" class=\"wp-image-1153524\" srcset=\"https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2026\/05\/4AHORRO.jpg 500w, https:\/\/dimensionturistica.com\/es\/wp-content\/uploads\/2026\/05\/4AHORRO-300x160.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Para alcanzar estos objetivos, la compa\u00f1\u00eda dise\u00f1\u00f3 una ruta dividida en tres etapas de madurez tecnol\u00f3gica. La primera fase se llevar\u00e1 a cabo durante el primer semestre del 2026 y se enfocar\u00e1 en productividad individual, con capacitaciones a los empleados y generaci\u00f3n de resultados r\u00e1pidos. El objetivo es construir una cultura de IA que optimice el tiempo y fortalezca la toma de decisiones.<\/p>\n\n\n\n<p>La segunda etapa se centrar\u00e1 en escalar la adopci\u00f3n de IA hacia toda la organizaci\u00f3n, pasando de la capacitaci\u00f3n a la implementaci\u00f3n. Aqu\u00ed, el foco cambia de uso individual a eficiencia por equipos, mediante el desarrollo e integraci\u00f3n de agentes para automatizar procesos clave.<\/p>\n\n\n\n<p>El \u00faltimo tramo se enfocar\u00e1 en transformar a fondo la operaci\u00f3n mediante IA, redise\u00f1ando procesos cr\u00edticos de back-office y desplegando proyectos estrat\u00e9gicos a gran escala. En esta etapa, Farmacias del Ahorro adoptar\u00e1 un enfoque AI-first en pol\u00edticas internas y datos, es decir, reescribir\u00e1n sus reglas y manuales internos para que funcionen directamente con IA. Consolidar\u00e1 capacidades a trav\u00e9s de un Centro de Excelencia y extender\u00e1 el uso de herramientas en la operaci\u00f3n. Todo esto con el objetivo de integrar la IA de forma transversal, generar eficiencia sostenible y construir una ventaja competitiva a largo plazo.<\/p>\n\n\n\n<p>&#8220;La tecnolog\u00eda de nube y la IA generativa est\u00e1n redefiniendo la productividad en el sector del retail y de salud. Al integrar Gemini Enterprise, Farmacias del Ahorro no s\u00f3lo optimizar\u00e1 sus procesos, sino que habilitar\u00e1 una cultura de innovaci\u00f3n donde la tecnolog\u00eda act\u00faa como un multiplicador de las capacidades humanas con foco en resultados concretos&#8221;, coment\u00f3 Julio Vel\u00e1zquez, Director General de Google Cloud M\u00e9xico.<\/p>\n\n\n\n<p>Para asegurar un uso responsable y efectivo de la tecnolog\u00eda, la farmac\u00e9utica instaur\u00f3 un Consejo de IA. Este \u00f3rgano de gobernanza cuenta con l\u00edderes de todas las unidades de negocio para supervisar la estrategia, medir resultados y asegurar que la adopci\u00f3n tecnol\u00f3gica responda a las prioridades de la empresa. Adem\u00e1s, permitir\u00e1 establecer m\u00e9tricas claras de retorno de inversi\u00f3n y control de riesgos en el uso de IA.<\/p>\n\n\n\n<p>Con este despliegue, Farmacias del Ahorro busca que la mayor parte de sus colaboradores use herramientas de inteligencia artificial en su trabajo diario hacia finales del 2026, consolidando una organizaci\u00f3n donde la tecnolog\u00eda funciona como un asistente que permite a los colaboradores enfocarse en el cuidado de la salud de los mexicanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Farmacias del Ahorro present\u00f3 \u201cPotencIA\u201d, este programa nace para trascender y convertirse en un aliado integral de bienestar, transformando la experiencia de compra y atenci\u00f3n al cliente: al automatizar y redise\u00f1ar la operaci\u00f3n, impulsado por Gemini Enterprise, una plataforma integral que se conecta a cada trabajador con la mejor de la IA de Google a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1153525,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[40],"tags":[],"class_list":["post-1153523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industria"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/1153523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=1153523"}],"version-history":[{"count":1,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/1153523\/revisions"}],"predecessor-version":[{"id":1153526,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/1153523\/revisions\/1153526"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/1153525"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=1153523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=1153523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=1153523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}