{"id":109470,"date":"2021-04-08T03:22:40","date_gmt":"2021-04-08T03:22:40","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=109470"},"modified":"2021-04-08T03:22:40","modified_gmt":"2021-04-08T03:22:40","slug":"reino-unido-sin-certidumbre-no-habra-despegue-turistico-noticias-de-agencias-de-viajes-rss1","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/reino-unido-sin-certidumbre-no-habra-despegue-turistico-noticias-de-agencias-de-viajes-rss1\/","title":{"rendered":"Reino Unido: sin certidumbre no habr\u00e1 despegue tur\u00edstico | Noticias de Agencias de viajes, rss1"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.preferente.com\/wp-content\/uploads\/2021\/02\/reino-unido.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-307100 size-full\" src=\"https:\/\/www.preferente.com\/wp-content\/uploads\/2021\/02\/reino-unido.jpg\" alt=\"\" width=\"600\" height=\"382\" srcset=\"https:\/\/www.preferente.com\/wp-content\/uploads\/2021\/02\/reino-unido.jpg 600w, https:\/\/www.preferente.com\/wp-content\/uploads\/2021\/02\/reino-unido-300x191.jpg 300w, https:\/\/www.preferente.com\/wp-content\/uploads\/2021\/02\/reino-unido-314x200.jpg 314w, https:\/\/www.preferente.com\/wp-content\/uploads\/2021\/02\/reino-unido-236x150.jpg 236w, https:\/\/www.preferente.com\/wp-content\/uploads\/2021\/02\/reino-unido-118x75.jpg 118w, https:\/\/www.preferente.com\/wp-content\/uploads\/2021\/02\/reino-unido-94x60.jpg 94w, https:\/\/www.preferente.com\/wp-content\/uploads\/2021\/02\/reino-unido-220x140.jpg 220w, https:\/\/www.preferente.com\/wp-content\/uploads\/2021\/02\/reino-unido-50x32.jpg 50w, https:\/\/www.preferente.com\/wp-content\/uploads\/2021\/02\/reino-unido-510x325.jpg 510w, https:\/\/www.preferente.com\/wp-content\/uploads\/2021\/02\/reino-unido-174x111.jpg 174w, https:\/\/www.preferente.com\/wp-content\/uploads\/2021\/02\/reino-unido-270x172.jpg 270w\" sizes=\"(max-width: 600px) 100vw, 600px\"\/><\/a><\/p>\n<p>La potente industria tur\u00edstica emisora de Reino Unido pide a su gobierno mayor certidumbre para poder planificar la reanudaci\u00f3n de los viajes al extranjero. Aunque agradece el anuncio del primer ministro, Boris Johnson, quien el pasado 5 de abril confirm\u00f3 que se podr\u00e1 viajar a partir del 17 de mayo, considera insuficiente la informaci\u00f3n facilitada (<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.preferente.com\/noticias-de-transportes\/noticias-de-aerolineas\/los-britanicos-libres-para-viajar-desde-el-17-de-mayo-308361.html\">Los brit\u00e1nicos, libres para viajar desde el 17 de mayo<\/a>).<\/p>\n<p>En palabras del presidente ejecutivo de la Asociaci\u00f3n Brit\u00e1nica de Agencias de Viajes (ABTA), Mark Tanzer, el despegue tur\u00edstico solo se producir\u00e1 si se crea \u201cun sistema m\u00e1s estable que evite la situaci\u00f3n del verano pasado, cuando los viajes a muchos destinos se activaron y desactivaron r\u00e1pidamente\u201d (<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.preferente.com\/analisis\/alemania-versus-uk-eficacia-y-cordura-frente-a-bandazos-incomprensibles-302240.html\">Alemania versus UK: eficacia y cordura frente a bandazos incomprensibles<\/a>).<\/p>\n<p>Como revel\u00f3 entonces este digital, los bandazos del Ejecutivo de Johnson, imponiendo vetos a destinos de la noche a la ma\u00f1ana, sumi\u00f3 en el caos a los actores tur\u00edsticos del pa\u00eds. Esta pol\u00edtica arras\u00f3 con las pocas esperanzas de salvar la campa\u00f1a estival y tuvo un efecto devastador en la ya de por s\u00ed maltrecha industria tur\u00edstica emisora, que sufri\u00f3 un aluvi\u00f3n de cancelaciones.<\/p>\n<p>Por todo ello, ABTA considera \u201cvital\u201d que el gobierno de Reino Unido \u201caclare c\u00f3mo funcionar\u00e1 la transici\u00f3n entre los niveles verde, \u00e1mbar y rojo, tanto para ayudar a las empresas de viajes a planificar con anticipaci\u00f3n como para brindar tranquilidad a los viajeros\u201d. \u201cLos destinos no deben cerrarse repentinamente\u201d, exclama su presidente.<\/p>\n<p>En esta l\u00ednea, reclama que se permita viajar con whole libertad a aquellos destinos con riesgo bajo de Covid-19. \u201cEn la actualidad, el coste de las pruebas es un impedimento para muchos viajeros de Reino Unido, por lo que el Gobierno debe garantizar que las pruebas solo se requieran cuando el riesgo para la salud p\u00fablica lo justifique y que exista un r\u00e9gimen rentable y eficiente\u201d, concluye.<\/p>\n<p>Como public\u00f3 <em>preferente.com<\/em>, un informe de IATA revel\u00f3 que una familia de cuatro personas que pretenda desplazarse desde Reino Unido a Canarias tendr\u00eda que hacerse 16 pruebas PCR, con un coste whole de 1.600 libras o 1.850 euros. Es un 160% m\u00e1s de lo que valen los cuatro billetes de avi\u00f3n, por lo que la exigencia de las mismas \u201caltera por completo la inversi\u00f3n necesaria para viajar\u201d (<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.preferente.com\/rss1\/los-test-de-antigenos-validos-para-todo-salvo-el-turismo-308259.html\">Los test de ant\u00edgenos, v\u00e1lidos para todo salvo el turismo<\/a>).<\/p>\n<p><!-- AddThis Advanced Settings above via filter on the_content --><!-- AddThis Advanced Settings below via filter on the_content --><!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons above via filter on the_content --><!-- AddThis Share Buttons below via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->\t\t\t<\/div>\n\n<p><em> &#8221; Fuentes www.preferente.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La potente industria tur\u00edstica emisora de Reino Unido pide a su gobierno mayor certidumbre para poder planificar la reanudaci\u00f3n de los viajes al extranjero. Aunque agradece el anuncio del primer ministro, Boris Johnson, quien el pasado 5 de abril confirm\u00f3 que se podr\u00e1 viajar a partir del 17 de mayo, considera insuficiente la informaci\u00f3n facilitada [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":84317,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-109470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/109470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=109470"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/109470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/84317"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=109470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=109470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=109470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}