{"id":109428,"date":"2021-04-08T01:09:35","date_gmt":"2021-04-08T01:09:35","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=109428"},"modified":"2021-04-08T01:09:35","modified_gmt":"2021-04-08T01:09:35","slug":"es-un-impacto-emocional-muy-grande","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/es-un-impacto-emocional-muy-grande\/","title":{"rendered":"\u201cEs un impacto emocional muy grande\u201d"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>\t\t\t\t\t\t\t\t\t<noscript><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/ads.e-planning.net\/ei\/3\/4d3e\/Notas\/Notas_AB1?it=i&amp;rnd=$RANDOM\"><img decoding=\"async\" width=\"300\" height=\"250\" alt=\"e-planning.net ad\" src=\"https:\/\/ads.e-planning.net\/eb\/3\/4d3e\/Notas\/Notas_AB1?o=i&amp;rnd=$RANDOM\" border=\"0\"\/><\/a><\/noscript>    <\/p>\n<p>El rumor circulaba desde hace unos d\u00edas en las calles de Bariloche y esta tarde se confirm\u00f3. <strong>El presidente Alberto Fern\u00e1ndez dispuso la suspensi\u00f3n de los viajes de egresados como una de las restricciones para tratar de frenar el incremento de contagios por covid-19 <\/strong>como consecuencia de la segunda ola del nuevo coronavirus en el pa\u00eds.<\/p>\n<div class=\"wp-block-lazyblock-leer-mas lazyblock-leer-mas-Z2aC4gk\">\n<article class=\"news news--summary news--55-81\">\n<figure class=\"news__media\">\n\t\t\t\t\t<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.rionegro.com.ar\/aguardan-el-dnu-para-saber-si-se-cancelan-todos-los-viajes-de-egresados-1759853\/\" title=\"Bariloche: aguardan el DNU para saber si se cancelan todos los viajes de egresados\"><br \/>\n\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.rionegro.com.ar\/wp-content\/uploads\/2021\/04\/Estudiantes-Catedral.jpg?w=650&amp;h=350\" width=\"215\" height=\"120\" alt=\"\"\/><br \/>\n\t\t\t\t\t<\/a><br \/>\n\t\t\t\t<\/figure>\n<\/article>\n<\/div>\n<p>El anunci\u00f3 confirm\u00f3 el escenario dif\u00edcil, <strong>pero caus\u00f3 m\u00e1s preocupaci\u00f3n que el Presidente no adelantara ning\u00fan tipo de asistencia econ\u00f3mica <\/strong>para uno de los sectores que mueven la econom\u00eda de Bariloche.<\/p>\n<p><strong>\u201cPor supuesto que lo ven\u00edamos especulando y era una posibilidad y, obviamente, que priorizamos la salud por sobre todas las cosas\u201d<\/strong>, sostuvo esta tarde de mi\u00e9rcoles el secretario de la Asociaci\u00f3n de Turismo Estudiantil (Ateba) de Bariloche, N\u00e9stor Denoya.<\/p>\n<p>Plante\u00f3 que el Presidente anunci\u00f3 un cierre durante las pr\u00f3ximas tres semanas, pero advirti\u00f3 que despu\u00e9s hay que arrancar otra vez a reorganizar todo. <strong>\u201cNosotros suponemos que van a ser dos meses para organizar otra vez todo\u201d, estim\u00f3.<\/strong><\/p>\n<p><strong>\u201cEl impacto es muy grande, emocional, porque pens\u00e1bamos que la conferencia del Presidente ven\u00eda con alg\u00fan tipo de ayuda\u201d<\/strong>, coment\u00f3 Denoya tras escuchar el mensaje del Presidente.<\/p>\n<p><strong>\u201cEn eso nos vamos a juntar ma\u00f1ana con la gobernadora (Arabela Carreras) y le vamos a expresar la enorme preocupaci\u00f3n, <\/strong>porque las empresas en este a\u00f1o (de pandemia) han consumido todos los ahorros, igual que las personas\u201d, afirm\u00f3. \u201cAs\u00ed que <strong>estamos casi sin espaldas para encarar esta baja temporada\u201d, asegur\u00f3. Record\u00f3 que el turismo estudiantil dependen unas 4.500 familias de Bariloche.<\/strong><\/p>\n<p>El a\u00f1o pasado estaba previsto que unos 100.000 estudiantes viajaran a Bariloche. Pero arrib\u00f3 un 15 por ciento, seg\u00fan Denoya. \u201cEsper\u00e1bamos a much\u00edsimos grupos en abril, mayo y junio, que iba a ayudar a pasar la temporada baja\u201d, coment\u00f3.<\/p>\n<p>Y asever\u00f3 en que el sector del turismo estudiantil respet\u00f3 estrictamente los protocolos. Respecto a los egresados que regresan contagiados a sus ciudades de origen, manifest\u00f3 que el turismo estudiantil \u201ces el \u00fanico segmento que se testea. Si agarr\u00e1s un avi\u00f3n y se testea a 200, 100 pasajeros tienen Covid\u201d. \u201cEn las \u00faltimas horas, tres micros volvieron a C\u00f3rdoba sin ning\u00fan contagiado. Quiere decir que la burbuja funciona\u201d, destac\u00f3.<\/p>\n<p>\t\t\t\t\t\t\t\t\t<br class=\"clear\"\/><\/p>\n<p>\t\t\t\t\t\t\t<!--\n\n<div id=\"suscribe_widget\"><\/div>\n\n --><\/p>\n<div class=\"modulo-news-nota-inferior\">\n<p><b>SUSCRIBITE A NOTICIAS DIARIAS <\/b><br \/>Todos los d\u00edas un correo con las noticias m\u00e1s importantes del d\u00eda.<\/p>\n<p>\t\t<iframe loading=\"lazy\" width=\"100%\" height=\"130\" src=\"https:\/\/especiales-rionegro.s3.amazonaws.com\/news\/form-landing-noticias-diarias.html\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"\"><\/iframe>\n\t\t\t<\/div><\/div>\n<p><script type=\"text\/javascript\">\n\t\t\t(function(d, s, id) {var js, fjs = d.getElementsByTagName(s)[0];if (d.getElementById(id)) return;js = d.createElement(s); js.id = id;js.src=\"https:\/\/connect.facebook.net\/es_ES\/sdk.js#xfbml=1&version=v3.0&appId=1410314005864209&autoLogAppEvents=1\";fjs.parentNode.insertBefore(js, fjs);}(document, 'script', 'facebook-jssdk'));\n\t\t<\/script><br \/>\n<br \/><\/p>\n<p><em> &#8221; Fuentes www.rionegro.com.ar &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El rumor circulaba desde hace unos d\u00edas en las calles de Bariloche y esta tarde se confirm\u00f3. El presidente Alberto Fern\u00e1ndez dispuso la suspensi\u00f3n de los viajes de egresados como una de las restricciones para tratar de frenar el incremento de contagios por covid-19 como consecuencia de la segunda ola del nuevo coronavirus en el [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":109429,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-109428","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/109428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=109428"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/109428\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/109429"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=109428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=109428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=109428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}