{"id":109366,"date":"2021-04-07T23:22:31","date_gmt":"2021-04-07T23:22:31","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=109366"},"modified":"2021-04-07T23:22:31","modified_gmt":"2021-04-07T23:22:31","slug":"covid-19-suspenden-viajes-de-egresados-y-de-grupos-turisticos","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/covid-19-suspenden-viajes-de-egresados-y-de-grupos-turisticos\/","title":{"rendered":"COVID-19: suspenden viajes de egresados y de grupos tur\u00edsticos"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Frente a la segunda ola de <strong>coronavirus<\/strong>, el presidente<strong> <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/politica\/detras-de-escena-como-grabo-el-mensaje-alberto-fernandez.phtml\">Alberto Fern\u00e1ndez<\/a><\/strong> tom\u00f3 una serie de medidas para frenar el crecimiento de los casos en el territorio argentino. Entre ellas, se decidi\u00f3 suspender para todo el pa\u00eds\u00a0los viajes de egresados, los viajes grupales y tambi\u00e9n de grupos tur\u00edsticos<\/p>\n<p>Este mi\u00e9rcoles 7 de abril, por segundo d\u00eda consecutivo, se confirm\u00f3 un nuevo <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/actualidad\/la-segunda-ola-de-covid-bate-records-con-mas-de-22-mil-contagios-en-un-dia.phtml\">r\u00e9cord de casos diarios<\/a>: se registraron 22.039 personas que contrajeron la enfermedad y 199 fellecidos. En ese contexto, pasadas las 18 horas, el jefe de Estado comunic\u00f3 las medidas a implementarse desde este viernes 9 de abril, d\u00eda en que vence el precise Decreto de Necesidad y Urgencia.<\/p>\n<p>&#8220;Decidimos tomar medidas espec\u00edficas teniendo en cuenta lo que sabemos del comportamiento del virus.\u00a0Por eso hemos decidido tomar algunas medidas para todo el pa\u00eds y otras espec\u00edficas que alcanzar\u00e1n a zonas de mediano y alto riesgo epidemiol\u00f3gico&#8221;, anunci\u00f3 el jefe de Estado desde la residencia de Olivos, donde se encuentra aislado tras dar positivo de covid el pasado s\u00e1bado.<\/p>\n<p class=\"destacadoNota\"><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/actualidad\/alberto-fernandez-anuncia-nuevas-restricciones-para-frenar-segunda-ola-covid.phtml\">Las 8 restricciones que anunci\u00f3 Alberto Fern\u00e1ndez para frenar el COVID\u00a0<\/a><\/p>\n<p>Tras desaconsejar semanas atr\u00e1s las salidas al exterior por motivos no esenciales,\u00a0Fern\u00e1ndez dijo hoy en su anuncio que\u00a0&#8220;cayeron un\u00a057 por ciento de las reservas que se hab\u00edan hecho para salir del pa\u00eds&#8221;.\u00a0Desde el 27 de marzo pasado,\u00a0se\u00a0suspendieron adem\u00e1s\u00a0los vuelos procedentes de\u00a0Brasil, Chile y M\u00e9xico, y se comenz\u00f3 a testear a todos los turistas que ingresaban al pa\u00eds.<\/p>\n<p>Seg\u00fan <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/actualidad\/en-ezeiza-y-aeroparque-ya-se-testeo-a-mas-de-11-mil-turistas.phtml\">datos de Migraciones<\/a> sobre los resultados de los testeos realizados a turistas en el Aeropuerto de Ezeiza y en Aeroparque, al d\u00eda de ayer -6 de abril- se registraron en complete 51 casos positivos de coronavirus: se trata de 47 casos en Ezeiza y 4 en Aeroparque. En complete, en Ezeiza se teste\u00f3 a 9.800 personas entre el 27 de marzo y el 6 de abril, mientras que en Aeroparque se someti\u00f3 un take a look at de ant\u00edgenos por coronavirus a 1.495 personas, un complete de 11.295.<\/p>\n<p class=\"destacadoNota\"><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.perfil.com\/noticias\/actualidad\/en-ezeiza-y-aeroparque-ya-se-testeo-a-mas-de-11-mil-turistas.phtml\">En los operativos de Ezeiza y Aeroparque ya se teste\u00f3 a m\u00e1s de 11 mil turistas\u00a0<\/a><\/p>\n<h2>Las medidas anunciadas por Alberto Fern\u00e1ndez<\/h2>\n<ul>\n<li>Se suspenden para todo el pa\u00eds los viajes grupales de Egresados y Egresadas, de Estudio y de Grupos Tur\u00edsticos.<\/li>\n<\/ul>\n<p>En las zonas del pa\u00eds consideradas de mediano riesgo epidemiol\u00f3gico y sanitario, dijo el Gobierno, es facultad y responsabilidad de gobernadores y gobernadoras adoptar en forma temprana medidas que disminuyan la circulaci\u00f3n para prevenir los contagios.\u00a0<\/p>\n<p>En las zonas del pa\u00eds donde hay<strong> mayor riesgo epidemiol\u00f3gico<\/strong> y sanitario, se tomar\u00e1n adem\u00e1s las siguientes medidas:<\/p>\n<ul>\n<li>Se suspenden actividades sociales en domicilios particulares.<\/li>\n<li>Se suspenden reuniones sociales en espacios p\u00fablicos al aire libre de m\u00e1s de 20 personas.<\/li>\n<li>Se suspenden actividades de On line casino, Bingo, Discotecas o cualquier sal\u00f3n de fiestas.<\/li>\n<li>Se suspende la pr\u00e1ctica recreativa de cualquier deporte en lugares cerrados donde participen m\u00e1s de 10 personas.<\/li>\n<li>Se establece el cierre de los bares y restaurantes a partir de las 23hs.<\/li>\n<li>Se proh\u00edbe la circulaci\u00f3n entre las 00.00 y las 06.00 de la ma\u00f1ana de cada d\u00eda.<\/li>\n<li>En el AMBA s\u00f3lo podr\u00e1n usar el transporte p\u00fablico de pasajeros trabajadores considerados esenciales, toda la comunidad educativa y aquellos que ya fueron expresamente autorizados.<\/li>\n<\/ul>\n<p>Seg\u00fan las jurisdicciones, las autoridades podr\u00e1n solo ampliar estos horarios en funci\u00f3n de las especificidades de cada lugar. Las nuevas medidas de cuidado estar\u00e1n vigentes desde las 0 horas de este viernes 9 de abril hasta el 30 de abril.\u00a0<\/p>\n<p><em>AG CP<\/em><\/p>\n<div class=\"noticias-relacionadas\">\n<p>Tambi\u00e9n te puede interesar<\/p>\n<\/div>\n<\/div>\n<p><script type=\"5dd95e68a7b8afac69e33d31-text\/javascript\">\n                !function(f,b,e,v,n,t,s)\n                {if(f.fbq)return;n=f.fbq=function(){n.callMethod?\n                    n.callMethod.apply(n,arguments):n.queue.push(arguments)};\n                    if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0';\n                    n.queue=[];t=b.createElement(e);t.async=!0;\n                    t.src=v;s=b.getElementsByTagName(e)[0];\n                    s.parentNode.insertBefore(t,s)}(window, document,'script',\n                    'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n                window.paywallConfig.facebook_pixel=\"1000228364089342\"\n            <\/script><script type=\"5dd95e68a7b8afac69e33d31-text\/javascript\">(function(d, s, id) {\n\t\tvar js, fjs = d.getElementsByTagName(s)[0];\n\t\tif (d.getElementById(id)) return;\n\t\tjs = d.createElement(s); js.id = id;\n\t\tjs.src=\"https:\/\/connect.facebook.net\/es_LA\/sdk.js#xfbml=1&version=v3.1\";\n\t\tfjs.parentNode.insertBefore(js, fjs);\n\t}(document, 'script', 'facebook-jssdk'));<\/script><br \/>\n<br \/><\/p>\n<p><em> &#8221; Fuentes www.perfil.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frente a la segunda ola de coronavirus, el presidente Alberto Fern\u00e1ndez tom\u00f3 una serie de medidas para frenar el crecimiento de los casos en el territorio argentino. Entre ellas, se decidi\u00f3 suspender para todo el pa\u00eds\u00a0los viajes de egresados, los viajes grupales y tambi\u00e9n de grupos tur\u00edsticos Este mi\u00e9rcoles 7 de abril, por segundo d\u00eda [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":109367,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-109366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/109366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=109366"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/109366\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/109367"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=109366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=109366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=109366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}