{"id":109257,"date":"2021-04-07T20:06:42","date_gmt":"2021-04-07T20:06:42","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=109257"},"modified":"2021-04-07T20:06:42","modified_gmt":"2021-04-07T20:06:42","slug":"grupos-criminales-asedian-con-retenes-a-comunidades-wixarikas","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/grupos-criminales-asedian-con-retenes-a-comunidades-wixarikas\/","title":{"rendered":"Grupos criminales asedian con retenes a comunidades Wix\u00e1rikas"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Para conseguir alimento, gasolina y art\u00edculos de primera necesidad, los pobladores de San Andr\u00e9s Cohamiata deben de conducir durante tres horas y llegar al municipio de Huejuquilla el Alto. Pero desde hace un mes, intentan sobrevivir con los v\u00edveres que tienen, pues temen salir y pasar por los<strong> retenes de grupos criminales.<\/strong><\/p>\n<p>Los\u00a0 retenes son dos y se instalaron desde finales de 2020. Los del primero, se presentan como integrantes del C\u00e1rtel Jalisco Nueva Generaci\u00f3n. En el segundo del C\u00e1rtel de Sinaloa. Entre ambos hay una distancia de kil\u00f3metros, pero los pobladores temen que en la lucha de estos c\u00e1rteles por apoderarse del territorio les roben, desaparezcan, violen, maten o los obliguen a hacer trabajo forzado.<\/p>\n<p>Ent\u00e9rate: <em><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.animalpolitico.com\/2018\/05\/disputa-territorial-ganaderos-wixarikas-bloqueos-y-cierre-de-escuelas-eleccion\/\">Disputa territorial entre ganaderos y wix\u00e1rikas genera bloqueos, cierre de escuelas y pone en riesgo la elecci\u00f3n<\/a><\/em><\/p>\n<p>El sitio es asediado por ambos grupos criminales pues es la \u00fanica v\u00eda terrestre de paso del sitio para llegar desde la Zona Wix\u00e1rika hacia Guadalajara y a su vez para llegar a los l\u00edmites con Nayarit, Zacatecas y Durango.<\/p>\n<p>Si controlan el camino, controlan la zona. Por eso el temor. Si los grupos criminales no les dejan pasar, no vuelven a regresar a sus casas. Si no les dejan salir, no tiene c\u00f3mo surtir sus necesidades b\u00e1sicas.<\/p>\n<p>\u201cNo hablamos de dos, tres, cuatro personas (en esos retenes), son de 20 a 25 veh\u00edculos, con gente armada, as\u00ed parecido como al Ej\u00e9rcito. Ah\u00ed si, pues ni como \u2026 te revisan el celular, te hacen preguntas, te dicen que si viste gente armada, pues uno por miedo dice que si, o no, no sabes que decir, y si ya no concuerda la informaci\u00f3n te intimidan\u201d, comenta un testigo a quien llamaremos Luis por razones de seguridad.<\/p>\n<p>Los pobladores cuentan a <em>Animal Pol\u00edtico<\/em> que es una situaci\u00f3n que conoce el gobierno. \u201cEn enero, vino un funcionario de gobierno con dos patrullas del Estado y obviamente vieron esto, pero no hicieron nada\u201d, cube Luis.<\/p>\n<p>Tambi\u00e9n en febrero robaron el autom\u00f3vil donde los m\u00e9dicos de la Secretar\u00eda de Salud se desplazaban para atender emergencias y llegar a la comunidad. Por eso,<strong> los m\u00e9dicos tienen semanas sin ir a San Andr\u00e9s.<\/strong> \u201cEste es el tercer veh\u00edculo que grupos criminales les quitan a los m\u00e9dicos, pero no se hace nada y obviamente s\u00ed se reporta\u201d, detalla Luis.<\/p>\n<h2><strong>Wixarikas temen denunciar\u00a0<\/strong><\/h2>\n<p>Cansados de la situaci\u00f3n, los pobladores decidieron denunciar ante la Comisi\u00f3n Estatal de Derechos Humanos de Jalisco el pasado 18 de marzo.<\/p>\n<p>La raz\u00f3n de porqu\u00e9 solo lo hicieron ante una comisi\u00f3n que s\u00f3lo puede pronunciarse y recomendar, pero no ejercer acciones en concreto, fue porque temen exponer el caso ante las autoridades, y que estos, est\u00e9n coludidos con los grupos criminales.<\/p>\n<p>\u201cNo sabemos realmente lo que sucede, el gobierno (sabe y) no hace nada, y pues, en vez de denunciar a los delincuentes, nos vamos a ir a denunciar a nosotros mismos, es la inseguridad que tenemos hacia los municipales, hacia lo estatal, \u00bfpor qu\u00e9 no fuimos directo a la Fiscal\u00eda o a la Secretar\u00eda General de Gobierno? Pues por miedo a que nos pase algo\u201d, comenta Luis.<\/p>\n<h2><strong>Una polic\u00eda desarmada <\/strong><\/h2>\n<p>La concept que tienen los pobladores sobre la posibilidad de que las autoridades est\u00e1n coludidas con grupos criminales no es fortuita.<\/p>\n<p>El pasado 26 de febrero, la polic\u00eda de Mezquitic -municipio a donde pertenece la comunidad de San Andr\u00e9s Cohamiata- fue desarmada. La Fiscal\u00eda Estatal explic\u00f3 que se debe a una presunta participaci\u00f3n de sus elementos en diversos delitos.<\/p>\n<p>El comisario y otros tres elementos est\u00e1n vinculados a proceso, pues se aportaron pruebas sobre su presunta partici\u00f3n en la desaparici\u00f3n forzada y homicidio de tres personas en septiembre de 2020.<\/p>\n<p>Tambi\u00e9n se les relaciona con la desaparici\u00f3n de \u00c1lvaro Madera, precandidato a la alcald\u00eda de Mezquitic, que fue interceptado el pasado 4 de febrero, cuando se dirig\u00eda a Huejuquilla el Alto.<\/p>\n<p>Adem\u00e1s, hay otros tres elementos que est\u00e1n detenidos por su possible relaci\u00f3n con el delito de secuestro agravado.<\/p>\n<h2><strong>Una recomendaci\u00f3n de la defensor\u00eda <\/strong><\/h2>\n<p>El 18 de marzo la CEDHJ\u00a0 recibi\u00f3 el reporte de que estaban suspendidos los servicios m\u00e9dicos, de seguridad y de apoyo de programas sociales en la comunidad.<\/p>\n<p>Un d\u00eda despu\u00e9s la defensor\u00eda hizo un llamado donde ped\u00eda seguridad para los pobladores por parte de la Secretar\u00eda de Seguridad P\u00fablica, el regreso de private m\u00e9dico de la Secretar\u00eda de Salud Jalisco a la comunidad, y alternativas de registro para que no se pierdan los apoyos de programas sociales.<\/p>\n<p>Los pobladores reconocieron que tras el pronunciamiento de la defensor\u00eda lleg\u00f3 la Guardia Nacional al sitio, pero a los pocos d\u00edas se fue y se quedaron solos.<\/p>\n<p>La polic\u00eda municipal solo va a San Andr\u00e9s Cohamiata a solicitud expresa. Tienen que hacerles llegar un oficio para pedir rondines de vigilancia o llamar de un tel\u00e9fono en caso de emergencia.<\/p>\n<p>Los m\u00e9dicos siguen sin desplazarse a los centros de salud. En el lugar permanecen los enfermeros de la comunidad, pero no pueden atender a los pacientes que llegan con enfermedades o complicaciones m\u00e9dicas y desplazarse implicar\u00eda un traslado de hasta 7 horas.<\/p>\n<p>Sobre los apoyos sociales federales, como el est\u00edmulo a personas de la tercera edad y la beca Benito Ju\u00e1rez est\u00e1n suspendidas de momento. En el caso de los apoyos locales y estatales se trabajan a trav\u00e9s de web, pero los pobladores aseguran que las ayudas no pueden llegar a todos.<\/p>\n<p>Aldo Reynoso, tercer visitador de la Comisi\u00f3n explica que \u201ctambi\u00e9n parte del problema es que, en la ruta, pueden iniciar enfrentamientos. Ese es el detalle, si logras pasar, te vas a quedar en San Andr\u00e9s porque te va a dar miedo regresar\u201d.<\/p>\n<h2><strong>Una violencia m\u00e1s cercana<\/strong><\/h2>\n<p>Los mismos pobladores reconocen que no es el primer ret\u00e9n que han sufrido a manos de grupos criminales. Entre los a\u00f1os 2010\u00a0 y 2011 tambi\u00e9n lo vivieron por parte de los Zetas, pero reconocen que el grupo prison nunca accedi\u00f3 a la comunidad como sucede ahora.<\/p>\n<p>Incluso part\u00edcipes de proyectos sociales reconocieron que en 2013, camino a la comunidad tuvieron una revisi\u00f3n a manos de un grupo armado, lo que les desmotiv\u00f3 a llegar a su destino. Finalmente, por miedo a que sucediera lo mismo este mes, decidieron no dirigirse a la comunidad.<\/p>\n<p>\u201cAhora tenemos conocimiento que en la noche se insertan en la comunidad (de San Andr\u00e9s) para resguardarse cuando tienen enfrentamientos, y si bien no estamos con ninguno de ellos, no queremos que en una de esas pase un fuego atravesado\u201d comenta otro de los testigos.<\/p>\n<p>Para los grupos criminales es f\u00e1cil insertarse, pues San Andr\u00e9s Cohamiata est\u00e1 compuesto por 21 peque\u00f1as comunidades, a las que llaman comisar\u00edas y que atraviesan largas distancias donde puede no existir ni luz.<\/p>\n<h2><strong>Un territorio de amapola<\/strong><\/h2>\n<p>Desde 2018, la Fuerza \u00danica Regional report\u00f3\u00a0 la presencia de sembrados de amapola en la Zona Wix\u00e1rika, en concreto en la comunidad de San Andr\u00e9s Cohamiata.<\/p>\n<p>El aseguramiento fue uno de los m\u00e1s grandes de ese a\u00f1o y ocurri\u00f3 en la Comisar\u00eda de Los Lobos. Ah\u00ed encontraron 13 sembrad\u00edos con 861 mil 800 plantas de amapola, que representaban m\u00e1s de la d\u00e9cima parte de todo lo hallado en lo que va del a\u00f1o.<\/p>\n<div class=\"ap_single_fondea_text\">Lo que hacemos en Animal Pol\u00edtico requiere de periodistas profesionales, trabajo en equipo, mantener di\u00e1logo con los lectores y algo muy importante: independencia. T\u00fa puedes ayudarnos a seguir. S\u00e9 parte del equipo.<br \/>\n<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.animalpolitico.com\/suscribete\">Suscr\u00edbete a Animal Pol\u00edtico<\/a>, recibe beneficios y apoya el periodismo libre.<\/p>\n<p><span style=\"font-weight: 600!important;\">#YoSoyAnimal<\/span><\/p>\n<\/div>\n<\/div>\n\n<p><em> &#8221; Fuentes www.animalpolitico.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para conseguir alimento, gasolina y art\u00edculos de primera necesidad, los pobladores de San Andr\u00e9s Cohamiata deben de conducir durante tres horas y llegar al municipio de Huejuquilla el Alto. Pero desde hace un mes, intentan sobrevivir con los v\u00edveres que tienen, pues temen salir y pasar por los retenes de grupos criminales. Los\u00a0 retenes son [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":109258,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-109257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/109257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=109257"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/109257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/109258"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=109257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=109257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=109257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}