{"id":108718,"date":"2021-04-06T23:06:59","date_gmt":"2021-04-06T23:06:59","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=108718"},"modified":"2021-04-06T23:06:59","modified_gmt":"2021-04-06T23:06:59","slug":"personas-con-2-dosis-de-vacuna-pueden-volver-a-viajar","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/personas-con-2-dosis-de-vacuna-pueden-volver-a-viajar\/","title":{"rendered":"Personas con 2 dosis de vacuna pueden volver a viajar"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"\"> De acuerdo con los CDC, cerca de 100 millones de personas en Estados Unidos, o alrededor del 30% de la poblaci\u00f3n, han recibido al menos una dosis de la vacuna contra el coronavirus. Se considera que una persona est\u00e1 totalmente vacunada dos semanas despu\u00e9s de recibir la \u00faltima dosis requerida de una vacuna.<\/p>\n<\/p><\/div>\n\n<p><em> &#8221; Fuentes www.chicagotribune.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De acuerdo con los CDC, cerca de 100 millones de personas en Estados Unidos, o alrededor del 30% de la poblaci\u00f3n, han recibido al menos una dosis de la vacuna contra el coronavirus. Se considera que una persona est\u00e1 totalmente vacunada dos semanas despu\u00e9s de recibir la \u00faltima dosis requerida de una vacuna. &#8221; Fuentes [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":108719,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-108718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/108718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=108718"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/108718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/108719"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=108718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=108718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=108718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}