{"id":108365,"date":"2021-04-06T13:49:28","date_gmt":"2021-04-06T13:49:28","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=108365"},"modified":"2021-04-06T13:49:28","modified_gmt":"2021-04-06T13:49:28","slug":"un-ameno-relato-de-ciencia-ficcion-ecologista-y-viajes-en-el-tiempo-que-cubre-sus-defectos-con-buenas-intenciones","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/un-ameno-relato-de-ciencia-ficcion-ecologista-y-viajes-en-el-tiempo-que-cubre-sus-defectos-con-buenas-intenciones\/","title":{"rendered":"un ameno relato de ciencia ficci\u00f3n ecologista y viajes en el tiempo que cubre sus defectos con buenas intenciones"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>T\u00e9cnico de efectos especiales en las sagas &#8216;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.espinof.com\/tag\/matrix\">The Matrix<\/a>&#8216;, &#8216;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.espinof.com\/tag\/star-wars\">Star Wars<\/a>&#8216; o &#8216;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.espinof.com\/tag\/x-men\">X-Men<\/a>&#8216;, Seth Larney debut\u00f3 en 2017 con su primera pel\u00edcula como director &#8216;Tombiro&#8217;, a\u00fan in\u00e9dita en medio mundo. Ahora el cineasta sudafricano criado en Australia vuelve con <strong>un t\u00edtulo mucho m\u00e1s ambicioso<\/strong> y de irregulares aunque interesantes resultados con &#8216;<strong>2067<\/strong>&#8216;, un drama de ciencia ficci\u00f3n sobre viajes en el tiempo con mensaje ecologista.<\/p>\n<p><!-- BREAK 1 --><\/p>\n<h2>Salvando el planeta verde<\/h2>\n<p><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.espinof.com\/tag\/kodi-smit-mcphee\">Kodi Smit-McPhee<\/a> es el mayor reclamo de un plantel que colidera junto a Ryan Kwanten conocido por su papel en &#8216;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.espinof.com\/tag\/true-blood\">True Blood<\/a>&#8216;. En &#8216;2067&#8217; tenemos un thriller de ciencia ficci\u00f3n ambientado en un futuro dist\u00f3pico donde el cambio clim\u00e1tico ha erradicado toda <strong>la vida vegetal del planeta<\/strong>. Con la humanidad sobreviviendo gracias al ox\u00edgeno sint\u00e9tico se enfrentar\u00e1n a un precio horrible: el aire synthetic causa una enfermedad que mata a la poblaci\u00f3n restante.<\/p>\n<p><!-- BREAK 2 --> <\/p>\n<div class=\"article-asset article-asset-normal article-asset-center\">\n<div class=\"desvio-container\">\n<div class=\"desvio\">\n<div class=\"desvio-figure js-desvio-figure\">\n    <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.espinof.com\/listas\/mejores-peliculas-viajes-tiempo\"><br \/>\n     <img decoding=\"async\" alt=\"Las 19 mejores pel\u00edculas con viajes en el tiempo\" src=\"https:\/\/i.blogs.es\/e7637f\/mejores-peliculas-viajes-tiempo\/375_142.jpeg\"\/><br \/>\n    <\/a>\n   <\/div><\/div><\/div>\n<\/div>\n<p>Est\u00e1 claro que la concept principal de la pel\u00edcula, al menos la premisa, es excelente. Y la cosa mejora si adem\u00e1s a\u00f1adimos los viajes en el tiempo como soluci\u00f3n al mal del presente. Pero los acontecimientos se desarrollan con un ritmo mon\u00f3tono a medida que el personaje principal intenta asimilar los continuos golpes que le da la vida. &#8216;2067&#8217; resulta <strong>un viaje interesante y atractivo<\/strong>, pero su gusto por acentuar el drama private del h\u00e9roe termina por jugar en contra.<\/p>\n<p><!-- BREAK 3 --><\/p>\n<p>La pel\u00edcula no solo se debe a la hecatombe de la humanidad, porque principalmente gira en torno al misterio que rodea a los momentos cruciales en la vida de su protagonista, descubriendo los secretos de cada uno con miradas desde otros \u00e1ngulos a medida que las situaciones se repiten. Las preguntas sin respuesta que hacen avanzar la historia son sin duda alguna la mayor virtud de <strong>un thriller fant\u00e1stico de bajo presupuesto<\/strong> y buenas concepts.<\/p>\n<p><!-- BREAK 4 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\">\n           <img class=\"sf-lazy centro_sinmarco\" data-sf-srcset=\"https:\/\/i.blogs.es\/33911f\/2067\/450_1000.jpeg 450w, https:\/\/i.blogs.es\/33911f\/2067\/650_1200.jpeg 681w,https:\/\/i.blogs.es\/33911f\/2067\/1024_2000.jpeg 1024w, https:\/\/i.blogs.es\/33911f\/2067\/1366_2000.jpeg 1366w,\" data-sf-src=\"https:\/\/i.blogs.es\/33911f\/2067\/450_1000.jpeg\" alt=\"2067 critica\"\/><br \/>\n  <noscript><img decoding=\"async\" alt=\"2067 critica\" class=\"centro_sinmarco\" src=\"https:\/\/i.blogs.es\/33911f\/2067\/450_1000.jpeg\"\/><\/noscript><\/p><\/div>\n<\/div>\n<p>La pel\u00edcula intenta equilibrar su narrativa compleja de temas filos\u00f3ficos algo pesados con un regusto por <strong>la aventura tradicional<\/strong> que, por momentos (y decorados) puede recordar a los viejos buenos tiempos de la escotilla de &#8216;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.espinof.com\/tag\/perdidos\">Perdidos<\/a>&#8216;. Los problemas surgen cuando los personajes lidian con el costo emocional. McPhee y su compa\u00f1ero recurren con una facilidad algo cansina al drama reflejado en l\u00e1grimas. Deborah Mailman tampoco hace mucho por tomar en serio a un personaje que parece salido de una parodia del g\u00e9nero, y el padre del protagonista tambi\u00e9n adolece de una antipat\u00eda importante.<\/p>\n<p><!-- BREAK 5 --><\/p>\n<h2>Drama ficci\u00f3n<\/h2>\n<p>Pero, como digo al comienzo, &#8216;2067&#8217; tambi\u00e9n tiene muy buenas concepts. La ambientaci\u00f3n futurista, el dise\u00f1o de las ciudades del &#8220;presente&#8221; y el futuro al que es enviado el protagonista de la aventura muestran buenas intenciones a la hora de <strong>jugar con las paradojas temporales<\/strong> que este aspirante a pariente lejano de &#8216;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.espinof.com\/tag\/after-earth\">After Earth<\/a>&#8216; se puede permitir, tal vez la pel\u00edcula con la que m\u00e1s parecido pueda tener. Aunque sea por el tratamiento y el mensaje.<\/p>\n<p><!-- BREAK 6 --><\/p>\n<div class=\"article-asset-image article-asset-normal article-asset-center\">\n<div class=\"asset-content\">\n           <img class=\"sf-lazy centro_sinmarco\" data-sf-srcset=\"https:\/\/i.blogs.es\/02468c\/2067-esqueleto\/450_1000.jpeg 450w, https:\/\/i.blogs.es\/02468c\/2067-esqueleto\/650_1200.jpeg 681w,https:\/\/i.blogs.es\/02468c\/2067-esqueleto\/1024_2000.jpeg 1024w, https:\/\/i.blogs.es\/02468c\/2067-esqueleto\/1366_2000.jpeg 1366w,\" data-sf-src=\"https:\/\/i.blogs.es\/02468c\/2067-esqueleto\/450_1000.jpeg\" alt=\"2067 esqueleto\"\/><br \/>\n  <noscript><img decoding=\"async\" alt=\"2067 esqueleto\" class=\"centro_sinmarco\" src=\"https:\/\/i.blogs.es\/02468c\/2067-esqueleto\/450_1000.jpeg\"\/><\/noscript><\/p><\/div>\n<\/div>\n<p>&#8216;2067&#8217; tiene un dise\u00f1o de producci\u00f3n muy cuidado y en ello y en los efectos especiales se aprecia la amplia experiencia del director. Vemos al mundo sucumbir al desastre ecol\u00f3gico y sus consecuencias en forma de paisaje l\u00fagubre e infernal de contaminaci\u00f3n industrial, dispensadores de ox\u00edgeno y alguna que otra muerte sangrienta. Una vez que el protagonista llega al punto del tiempo en que debe comenzar su <strong>operaci\u00f3n por rescatar a la humanidad<\/strong>, la pel\u00edcula cambia de tono y colores, y el resultado es siempre agradable y, en mayor o menor medida, sorprendente.<\/p>\n<p><!-- BREAK 7 --><\/p>\n<p>Por supuesto que muchos aficionados habr\u00edan preferido evitar la inundaci\u00f3n lacrim\u00f3gena, pero el puzzle encuentra una soluci\u00f3n lo suficientemente interesante como para <strong>cerrar con \u00e9xito su arriesgada propuesta<\/strong>. La l\u00ednea entre fe y ciencia no siempre queda clara y tal vez la uni\u00f3n de ambos factores sea necesaria para lograr lo extraordinario, especialmente frente a las nefastas consecuencias del cambio clim\u00e1tico. Y ahora no estoy hablando de ficci\u00f3n.<\/p>\n<p><!-- BREAK 8 --><\/p>\n<p>&#8216;2067&#8217; est\u00e1 disponible en alquiler TVOD (alquiler) en <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/ver.movistarplus.es\/ficha\/2067?id=1867509&amp;id_perfil=NODTH&amp;suscripcion=PS-CVODPCFREE,PS-DO0001,PS-DO0001LI\">Movistar+<\/a>, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.filmin.es\/pelicula\/2067\">Filmin<\/a>, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/play.google.com\/store\/movies\/details\/2067?gl=ES&amp;hl=en&amp;id=YRluTatV364.P&amp;PAffiliateID=110l4uj\">Google Play<\/a>, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/rakuten.tv\/es\/movies\/2067\">Rakuten<\/a>, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.espinof.com\/redirect?url=https%3A%2F%2Fitunes.apple.com%2Fes%2Fmovie%2F2067%2Fid1556267276%3Fl%3Den%26ign-mpt%3Duo%253D4&amp;category=criticas\">Apple TV<\/a> y <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.espinof.com\/redirect?url=https%3A%2F%2Fwww.microsoft.com%2Fes-es%2Fp%2F2067%2F8d6kgwxn8b1j%3Fct%3Dmovie%26irgwc%3D1%26OCID%3DAID2000142_aff_7806_1246483%26tduid%3D%28ir__swgzunovbwkfqirykk0sohz3wu2xp9rmbxlbzgkx00%29%287806%29%281246483%29%28%283048718676ec664954b3bef627ebac96%29%2881561%29%282850890%29%282fafa179daed488fa3167f9d558dca4f%29%28%29%29%283048718676ec664954b3bef627ebac96%29%26irclickid%3D_swgzunovbwkfqirykk0sohz3wu2xp9rmbxlbzgkx00%26activetab%3Dpivot%253aoverviewtab&amp;category=criticas\">Microsoft<\/a>.<\/p>\n<p><!-- BREAK 9 -->\n <\/div>\n\n<p><em> &#8221; Fuentes www.espinof.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>T\u00e9cnico de efectos especiales en las sagas &#8216;The Matrix&#8216;, &#8216;Star Wars&#8216; o &#8216;X-Men&#8216;, Seth Larney debut\u00f3 en 2017 con su primera pel\u00edcula como director &#8216;Tombiro&#8217;, a\u00fan in\u00e9dita en medio mundo. Ahora el cineasta sudafricano criado en Australia vuelve con un t\u00edtulo mucho m\u00e1s ambicioso y de irregulares aunque interesantes resultados con &#8216;2067&#8216;, un drama de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":88122,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-108365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/108365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=108365"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/108365\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/88122"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=108365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=108365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=108365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}