{"id":108310,"date":"2021-04-06T11:02:32","date_gmt":"2021-04-06T11:02:32","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=108310"},"modified":"2021-04-06T11:02:32","modified_gmt":"2021-04-06T11:02:32","slug":"delhi-impone-toque-de-queda-nocturno-a-partir-de-hoy-comprobar-lo-que-esta-permitido-y-lo-que-no-ezanime-net","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/delhi-impone-toque-de-queda-nocturno-a-partir-de-hoy-comprobar-lo-que-esta-permitido-y-lo-que-no-ezanime-net\/","title":{"rendered":"Delhi impone toque de queda nocturno a partir de hoy; comprobar lo que est\u00e1 permitido y lo que no \u2013 EzAnime.net"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p><img decoding=\"async\" src=\"https:\/\/images.financialexpress.com\/2021\/04\/night-curfew-delhi.jpg\" alt=\"toque de queda nocturno delhi\"\/>El toque de queda nocturno entrar\u00e1 en vigor desde las 10 de la noche hasta las 5 de la ma\u00f1ana.  (Fuente de la foto: IE)<\/p>\n<p>El gobierno de Delhi ha impuesto un toque de queda nocturno en la capital nacional desde el 5 de abril hasta el 30 de abril. El toque de queda nocturno entrar\u00e1 en vigor de 10 pm a 5 am.  La decisi\u00f3n se ha tomado considerando el continuo aumento en el n\u00famero de casos de COVID-19.  El toque de queda nocturno, seg\u00fan los funcionarios, se impuso para dispersar a la multitud de restaurantes, clubes nocturnos, bares, pubs y lugares para fiestas.<\/p>\n<p>El gobierno dijo que los servicios esenciales y el movimiento de veh\u00edculos de emergencia han sido exentos del toque de queda nocturno.<\/p>\n<p>Anteriormente, el 2 de abril, el ministro principal, Arvind Kejriwal, hab\u00eda dicho que el toque de queda nocturno no es una soluci\u00f3n para controlar el aumento de los casos de COVID-19.  El gobierno del Partido Aam Aadmi, dirigido por Kejriwal, no estaba a favor del toque de queda nocturno y hab\u00eda dicho que no planea imponerlo.<\/p>\n<p><strong>A ra\u00edz del toque de queda nocturno en la capital nacional, esto es lo que se permitir\u00e1 y lo que no despu\u00e9s de las 10 de la noche.<\/strong><\/p>\n<p>Todos los mercados, restaurantes, bares y pubs cerrar\u00e1n antes de las 10 p.m. Los salones de bodas y los salones de banquetes tambi\u00e9n deben respetar el toque de queda nocturno. Los trabajadores de primera l\u00ednea y de atenci\u00f3n m\u00e9dica, los funcionarios gubernamentales y los diplom\u00e1ticos deber\u00e1n presentar tarjetas de identidad para viajar durante ese per\u00edodo. tendr\u00e1 que producir pases electr\u00f3nicos.Los servicios esenciales como tiendas m\u00e9dicas, hogares de ancianos, hospitales y otros servicios asociados permanecer\u00e1n abiertos durante el toque de queda nocturno de siete horas.Las instalaciones de nutrientes esenciales como diarios, comestibles, panader\u00edas, confiter\u00edas y tiendas de verduras permanecer\u00e1 abierta.  Pero el gobierno ha pedido a estos establecimientos que sigan todo el comportamiento adecuado de COVID-19. El private de servicios de emergencia como defensa civil, electricidad, obras de saneamiento han sido exentos de las nuevas restricciones.  Sin embargo, se les puede pedir que presenten tarjetas de identificaci\u00f3n v\u00e1lidas. Se ha permitido el funcionamiento de bancos, cajeros autom\u00e1ticos, servicios de radiodifusi\u00f3n, medios impresos y electr\u00f3nicos.  A estas personas se les puede pedir que presenten un \u2018e-pass\u2019 que se puede obtener solicitando en el sitio internet oficial del gobierno de Delhi.Todos los servicios de transporte p\u00fablico operan solo para servicios esenciales. Los servicios podr\u00e1n viajar siempre que puedan producir billetes v\u00e1lidos.<\/p>\n<p>Obtenga precios de acciones en vivo de BSE, NSE, mercado de EE. UU. Y el \u00faltimo NAV, cartera de fondos mutuos, consulte las \u00faltimas noticias de OPI, las OPI de mejor rendimiento, calcule sus impuestos con la calculadora de impuestos sobre la renta, conozca los principales ganadores del mercado, los mejores perdedores y los mejores fondos de capital  Me gusta en Fb y s\u00edguenos en Twitter.<\/p>\n<p class=\"telegram-text\"><img decoding=\"async\" loading=\"lazy\" class=\"telegrma_img\" src=\"https:\/\/images.financialexpress.com\/2020\/04\/telegram.png\" alt=\"\" width=\"24\" height=\"24\" style=\"margin: 0px 5px 4px 0px; float: left;\"\/>Monetary Categorical ahora est\u00e1 en Telegram.  Haga clic aqu\u00ed para unirse a nuestro canal y mantenerse actualizado con las \u00faltimas noticias y actualizaciones de Biz.<\/p>\n<\/p><\/div>\n\n<p><em> &#8221; Fuentes www.ezanime.net &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El toque de queda nocturno entrar\u00e1 en vigor desde las 10 de la noche hasta las 5 de la ma\u00f1ana. (Fuente de la foto: IE) El gobierno de Delhi ha impuesto un toque de queda nocturno en la capital nacional desde el 5 de abril hasta el 30 de abril. El toque de queda nocturno [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":108311,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-108310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/108310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=108310"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/108310\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/108311"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=108310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=108310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=108310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}