{"id":103985,"date":"2021-03-29T13:08:44","date_gmt":"2021-03-29T13:08:44","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=103985"},"modified":"2021-03-29T13:08:44","modified_gmt":"2021-03-29T13:08:44","slug":"india-sufre-mayor-incremento-de-infecciones-diarias-de-coronavirus-en-cinco-meses","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/india-sufre-mayor-incremento-de-infecciones-diarias-de-coronavirus-en-cinco-meses\/","title":{"rendered":"India sufre mayor incremento de infecciones diarias de coronavirus en cinco meses"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"paragraph\">NUEVA DELHI, 29 mar (Reuters) &#8211; India inform\u00f3 el lunes el mayor aumento diario de casos de coronavirus en cinco meses, en un momento en que la segunda ola de la enfermedad est\u00e1 siendo impulsada por el aumento de infecciones en el estado m\u00e1s rico del pa\u00eds, Maharastra.<\/p>\n<p class=\"paragraph\">En complete se reportaron 68.020 nuevos casos de coronavirus en las \u00faltimas 24 horas, dijo el Ministerio de Salud. Fue el alza diaria m\u00e1s alta desde el 11 de octubre, seg\u00fan un recuento de Reuters.<\/p>\n<p class=\"paragraph\">India ha estado reportando un aumento de casos -por encima de la marca de 60.000- durante tres d\u00edas consecutivos, aunque el aumento del lunes todav\u00eda es inferior al pico de septiembre de m\u00e1s de 90.000 casos por d\u00eda.<\/p>\n<p><span data-error=\"No dfp-path found.\"\/><\/p>\n<p class=\"paragraph\">El n\u00famero complete de casos desde que comenz\u00f3 la epidemia hace un a\u00f1o super\u00f3 los 12 millones, lo que convierte a India en el pa\u00eds m\u00e1s afectado del mundo fuera de Estados Unidos y Brasil. Algunos expertos creen que la cifra m\u00e1s actual ser\u00eda de m\u00e1s de 300 millones debido a pruebas insuficientes, aunque eso ha mejorado.<\/p>\n<p class=\"paragraph\">Las muertes diarias aumentaron en 291 el lunes y el virus ha acabado con la vida de 161.843 personas hasta la fecha en el pa\u00eds. Maharastra, el estado occidental donde se encuentra la capital financiera del pa\u00eds, Mumbai, registr\u00f3 su mayor aumento diario de casos, con 40.414.<\/p>\n<p class=\"paragraph\">El estado est\u00e1 considerando imponer un bloqueo estricto esta semana. Ya ha endurecido las restricciones de viaje e impuesto el toque de queda nocturno en un intento por poner freno a los crecientes casos de infecciones.<\/p>\n<p><span data-error=\"No dfp-path found.\"\/><\/p>\n<p class=\"paragraph\">Varios estados impusieron restricciones a las reuniones p\u00fablicas en el competition hind\u00fa Holi y el Shab-e-Barat o D\u00eda del Perd\u00f3n musulm\u00e1n, que se celebraron durante el fin de semana.<\/p>\n<p class=\"paragraph\">El Holi, que marca la llegada de la primavera boreal, es uno de los festivales m\u00e1s grandes de India. La gente suele celebrarlo unt\u00e1ndose unos a otros con polvos de diferentes colores y cantando.<\/p>\n<p><span data-error=\"No dfp-path found.\"\/><\/p>\n<p class=\"paragraph\">(Reporte de Aftab Ahmed y Chandini Monnappa en Bengaluru; editado en espa\u00f1ol por Carlos Serrano)<\/p>\n<\/div>\n<p><script defer=\"\">!function(f,b,e,v,n,t,s) {if(f.fbq)return;n=f.fbq=function(){n.callMethod? n.callMethod.apply(n,arguments):n.queue.push(arguments)}; if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0'; n.queue=[];t=b.createElement(e);t.async=!0; t.src=v;s=b.getElementsByTagName(e)[0]; s.parentNode.insertBefore(t,s)}(window, document,'script', 'https:\/\/connect.facebook.net\/en_US\/fbevents.js'); fbq('init', '336383993555320'); fbq('track', 'PageView'); fbq('track', 'ViewContent');<\/script><br \/>\n<br \/><\/p>\n<p><em> &#8221; Fuentes www.infobae.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NUEVA DELHI, 29 mar (Reuters) &#8211; India inform\u00f3 el lunes el mayor aumento diario de casos de coronavirus en cinco meses, en un momento en que la segunda ola de la enfermedad est\u00e1 siendo impulsada por el aumento de infecciones en el estado m\u00e1s rico del pa\u00eds, Maharastra. En complete se reportaron 68.020 nuevos casos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":102777,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[40],"tags":[],"class_list":["post-103985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industria"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/103985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=103985"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/103985\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/102777"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=103985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=103985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=103985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}