{"id":103713,"date":"2021-03-28T22:52:49","date_gmt":"2021-03-28T22:52:49","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=103713"},"modified":"2021-03-28T22:52:50","modified_gmt":"2021-03-28T22:52:50","slug":"concanaco-estima-65-de-ocupacion-hotelera-en-semana-santa","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/concanaco-estima-65-de-ocupacion-hotelera-en-semana-santa\/","title":{"rendered":"Concanaco estima 65 % de ocupaci\u00f3n hotelera en Semana Santa"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>La industria tur\u00edstica le apuesta a las vacaciones de <strong>Semana Santa<\/strong> y <strong>Pascua<\/strong> para salir a flote, por lo que anunciaron que para evitar la tercera ola de contagios de<strong> Covid-19<\/strong> aplicar\u00e1n de forma estricta las <strong>medidas sanitarias<\/strong> en los centros tur\u00edsticos del pa\u00eds al instrumentar el c\u00f3digo \u201cdestinos seguros y establecimientos certificados\u201d.<\/p>\n<p>El presidente de la Confederaci\u00f3n de C\u00e1maras Nacionales de Comercio, Servicios y Turismo,<strong> Jos\u00e9 Manuel L\u00f3pez Campos,<\/strong> estim\u00f3 que registrar\u00e1n una ocupaci\u00f3n hotelera del 65 por ciento con la llegada de m\u00e1s de 7 millones de turistas nacionales y extranjeros a destinos de sol y playa, pueblos m\u00e1gicos, ciudades coloniales, zonas arqueol\u00f3gicas y centros religiosos.<\/p>\n<p>Informaci\u00f3n relacionada: <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/mvsnoticias.com\/noticias\/economia\/preven-que-semana-santa-deje-derrama-economica-de-26-mmdp\/\">Prev\u00e9n que Semana Santa deje derrama econ\u00f3mica de 26 mmdp<\/a><\/p>\n<p>El presidente de la<strong> Concanaco,<\/strong> calcul\u00f3 que 5.35 millones de mexicanos saldr\u00e1n a visitar alg\u00fan destino del pa\u00eds y que 1.67 turistas extranjeros llegar\u00e1n a M\u00e9xico, en su mayor\u00eda estadounidense que aprovechar\u00e1n que ya est\u00e1n vacunados y del hecho de que no hay restricciones de viaje en nuestra naci\u00f3n .<\/p>\n<p>L\u00f3pez Campos, se\u00f1al\u00f3 que las vacaciones de <strong>Semana Santa<\/strong> y Pascua ser\u00e1n un gran reto, ya que a nadie le conviene una tercera ola de contagios, por ello la relevancia de contar con destinos tur\u00edsticos seguros y turistas responsables.<\/p>\n<p>Asimismo, la Profeco puso en marcha el \u201c<strong>Operativo Semana Santa 2021<\/strong>\u201d, vigilara y verificar\u00e1 hoteles, agencias de viajes, aerol\u00edneas, centrales camioneras, tiempos compartidos, restaurantes, centrales de abasto, mercados de mariscos, bares, balnearios, parques de diversiones y comercio electr\u00f3nico.<\/p>\n<\/p><\/div>\n\n<p><em> &#8221; Fuentes mvsnoticias.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La industria tur\u00edstica le apuesta a las vacaciones de Semana Santa y Pascua para salir a flote, por lo que anunciaron que para evitar la tercera ola de contagios de Covid-19 aplicar\u00e1n de forma estricta las medidas sanitarias en los centros tur\u00edsticos del pa\u00eds al instrumentar el c\u00f3digo \u201cdestinos seguros y establecimientos certificados\u201d. El presidente [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":103714,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[40],"tags":[],"class_list":["post-103713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industria"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/103713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=103713"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/103713\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/103714"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=103713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=103713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=103713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}