{"id":103696,"date":"2021-03-28T21:58:09","date_gmt":"2021-03-28T21:58:09","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=103696"},"modified":"2021-03-28T21:58:09","modified_gmt":"2021-03-28T21:58:09","slug":"pedro-sanchez-permite-viajes-con-pasaportes-vencidos-entre-cuba-y-espana","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/pedro-sanchez-permite-viajes-con-pasaportes-vencidos-entre-cuba-y-espana\/","title":{"rendered":"Pedro S\u00e1nchez permite viajes con pasaportes vencidos entre Cuba y Espa\u00f1a"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<figure id=\"attachment_332295\" style=\"width: 700px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-332295 size-full\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=\" http:=\"\" alt=\"Cuba, Espa\u00f1a, Pedro S\u00e1nchez, pasaportes\" width=\"700\" height=\"525\" data-lazy-srcset=\"https:\/\/cdn.panampost.com\/wp-content\/uploads\/DsrtrRRW0AE2la5.jpg 700w, https:\/\/cdn.panampost.com\/wp-content\/uploads\/DsrtrRRW0AE2la5-300x225.jpg 300w\" data-lazy-sizes=\"(max-width: 700px) 100vw, 700px\" data-lazy-src=\"https:\/\/cdn.panampost.com\/wp-content\/uploads\/DsrtrRRW0AE2la5.jpg\"\/><noscript><img decoding=\"async\" class=\"wp-image-332295 size-full\" src=\"https:\/\/cdn.panampost.com\/wp-content\/uploads\/DsrtrRRW0AE2la5.jpg\" alt=\"Cuba, Espa\u00f1a, Pedro S\u00e1nchez, pasaportes\" width=\"700\" height=\"525\" srcset=\"https:\/\/cdn.panampost.com\/wp-content\/uploads\/DsrtrRRW0AE2la5.jpg 700w, https:\/\/cdn.panampost.com\/wp-content\/uploads\/DsrtrRRW0AE2la5-300x225.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\"\/><\/noscript><figcaption class=\"wp-caption-text\">Pedro S\u00e1nchez, presidente del Gobierno Espa\u00f1ol en su encuentro hace dos a\u00f1os con el dictador cubano Miguel D\u00edaz-Canel. (<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/JuantonioFdez\/status\/1065925598349004801\">Twitter<\/a>)<\/figcaption><\/figure>\n<p>Mantener el flujo de viajeros de Cuba a Espa\u00f1a sin contratiempos comprueban las estrechas relaciones del Gobierno socialista de Pedro S\u00e1nchez con la dictadura cubana.<\/p>\n<p>El Consulado de Espa\u00f1a en La Habana anunci\u00f3 que permite viajar con el pasaporte espa\u00f1ol caducado a Espa\u00f1a \u201csin ning\u00fan problema\u201d, divulga <em><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.directoriocubano.info\/panorama\/consulado-de-espana-en-cuba-informa-sobre-posibilidad-de-viajar-con-pasaporte-espanol-caducado\/\">Directorio Cubano.\u00a0<\/a><\/em>Adem\u00e1s, ofrece la emisi\u00f3n de\u00a0un salvoconducto para un solo viaje a Espa\u00f1a, sin necesidad de cita previa.<\/p>\n<p>Y si a los espa\u00f1oles se les vencieron sus documentos cubanos tampoco hay problema. La Direcci\u00f3n de Identificaci\u00f3n, Inmigraci\u00f3n y Extranjer\u00eda (DIIE) en Cuba determin\u00f3 que hasta el 12 de octubre de 2021 se exime del requisito de extensi\u00f3n de la permanencia en el exterior a los cubanos residentes en Cuba, si salieron de Cuba posterior a marzo de 2018 y los extranjeros residentes permanentes en Cuba si salieron posterior a marzo de 2019.<\/p>\n<p>Unas medidas que encajan con la intenci\u00f3n de la campa\u00f1a #SpainforSure (Espa\u00f1a por supuesto) lanzada recientemente por el Ministerio de Relaciones Exteriores de S\u00e1nchez, la cual se comparte a trav\u00e9s del Twitter del Consulado espa\u00f1ol en La Habana, donde se apela a una catarata de elogios para lavar la reputaci\u00f3n de Espa\u00f1a en el exterior con la voz de extranjeros.<\/p>\n<div class=\"jeg_ad jeg_ad_article jnews_content_inline_ads \">\n<div class=\"ads-wrapper align-right \"><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/bit.ly\/jnewsio\" class=\"adlink ads_image align-right\"> <img decoding=\"async\" class=\"lazyload\" src=\"https:\/\/pre.panampost.com\/wp-content\/uploads\/ad_300x250.jpg\" alt=\"\" data-pin-no-hover=\"true\"\/> <\/a><\/div>\n<\/div>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\"><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/SpainForSure?src=hash&amp;ref_src=twsrc%5Etfw\">#SpainForSure<\/a><br \/>Rebeca Grynspan, Secretaria basic iberoamericana:<br \/>&#8220;En cada lugar de Espa\u00f1a&#x1f1ea;&#x1f1e6; al que voy, encuentro algo de mi identidad latinoamericana&#8221; &#x1f30e; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/RGrynspan?ref_src=twsrc%5Etfw\">@RGrynspan<\/a><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/SbhtJRXayM\">pic.twitter.com\/SbhtJRXayM<\/a> <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/EspanaGlobal?ref_src=twsrc%5Etfw\">@EspanaGlobal<\/a><\/p>\n<p>\u2014 Consulado Espa\u00f1a Caracas (@ConsEspCaracas) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/ConsEspCaracas\/status\/1374330100255186952?ref_src=twsrc%5Etfw\">March 23, 2021<\/a><\/p>\n<\/blockquote>\n<h4><strong>Del lado contrario<\/strong><\/h4>\n<p>Pese a la campa\u00f1a para proyectar una imagen positiva, es imposible esconder que Pedro S\u00e1nchez avala al r\u00e9gimen castrista. \u201cMuchos gestos, buenas palabras y dos acuerdos de segunda divisi\u00f3n\u201d entre su gesti\u00f3n con\u00a0Cuba\u00a0confirman en el tiempo que el viaje hace dos a\u00f1os del presidente espa\u00f1ol a la \u201cperla de las Antillas\u201d evidencia que las \u201crelaciones con Cuba son prioritarias\u00bb.<\/p>\n<p>S\u00e1nchez y Miguel D\u00edaz-Canel, actual dictador de la isla, mantienen una \u201csinton\u00eda personal\u201d incluso S\u00e1nchez subray\u00f3 que vio un \u201cimpulso reformista\u00bb durante sus conversaciones y, por ello, \u00abEspa\u00f1a quiere contribuir activamente en el proceso\u201d, relata <em><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.elmundo.es\/espana\/2018\/11\/24\/5bf86b1422601dcc4d8b4670.html\">El Mundo<\/a>.<\/em><\/p>\n<p>Una pol\u00edtica que va en direcci\u00f3n opuesta a la de Estados Unidos, que mediante el<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/cl.usembassy.gov\/es\/estados-unidos-anuncia-la-designacion-de-cuba-como-estado-patrocinador-del-terrorismo\/\"> Departamento de Estado<\/a> calific\u00f3 a Cuba como \u201cEstado patrocinador del terrorismo por brindar reiteradamente apoyo a actos de terrorismo internacional al ofrecer un refugio seguro a terroristas\u201d.<\/p>\n<p>Para la Casa Blanca, el r\u00e9gimen de La Habana \u201calimenta, alberga y brinda atenci\u00f3n m\u00e9dica a homicidas, fabricantes de explosivos y secuestradores, mientras muchos cubanos pasan hambre, no tienen vivienda y carecen de medicamentos b\u00e1sicos\u201d, entre estos terroristas est\u00e1n miembros del Ej\u00e9rcito de Liberaci\u00f3n Nacional (ELN) -designado como Organizaci\u00f3n Terrorista Extranjera- y varios fugitivos de la justicia de EE. UU. que son buscados o han sido condenados por cargos de violencia pol\u00edtica.<\/p>\n<p>Adem\u00e1s el r\u00e9gimen cubano participa en \u201cuna variedad de comportamientos perniciosos en la regi\u00f3n. Su aparato de inteligencia y seguridad se ha infiltrado en las fuerzas de seguridad y militares de Venezuela y ha ayudado a Nicol\u00e1s Maduro a mantener el control f\u00e9rreo sobre su poblaci\u00f3n, al tiempo que permite que operen organizaciones terroristas\u201d.<\/p>\n<h4><strong>M\u00e1s posibilidades<\/strong><\/h4>\n<p>Los argumentos de Washington se ignoran en la Moncloa, cuya pol\u00edtica versatile que ya suma 140.000\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/panampost.com\/gabriela-moreno\/2021\/03\/22\/inteligencia-cubana-espia-espana-izquierda\/\">cubanos en su territorio<\/a> \u2013la misma cantidad de espa\u00f1oles en Cuba\u2013 tambi\u00e9n permite homologar hasta t\u00edtulos de estudios desde las tierra de Jos\u00e9 Mart\u00ed.<\/p>\n<p>El graduado s\u00f3lo debe presentar la solicitud telem\u00e1ticamente al Ministerio de Universidades y esto genera un n\u00famero de seguimiento.<\/p>\n<p>En los siguientes 15 d\u00edas se revisa la solicitud y se demandara la subsanaci\u00f3n de errores (en caso de que existan) y contar\u00e1n 15 d\u00edas para las enmiendas.<\/p>\n<p>Luego una comisi\u00f3n de homologaciones verifica en dos meses el resultado, redacta un informe y lo emite al interesado. Para las profesiones reguladas \u2015m\u00e9dico, veterinario, abogado o juez\u2015 se pedir\u00e1 un informe al colegio correspondiente que se termita en 10 d\u00edas.<\/p>\n<p>Si la respuesta es positiva, se expedir\u00e1 un t\u00edtulo en apenas 10 d\u00edas y, si es negativa, el interesado contar\u00e1 con 15 d\u00edas para reclamar, y la Comisi\u00f3n tendr\u00e1 otros 15 para responderle, rese\u00f1a <em><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.directoriocubano.info\/actualidad\/migrantes-en-espana-podran-homologar-su-titulo-en-seis-meses\/\">Directorio Cubano<\/a>.<\/em><\/p>\n<h4><strong>Paquetes con servicio <\/strong><\/h4>\n<p>La cercan\u00eda de <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/panampost.com\/gabriela-moreno\/2021\/03\/25\/asociaciones-cubanas-financian-dictadura-con-fondos-publicos-de-espana\/\">Cuba con Espa\u00f1a en manos de S\u00e1nchez<\/a> tambi\u00e9n provoc\u00f3 que la isla en noviembre restableciera el servicio de paqueter\u00eda internacional desde Madrid.<\/p>\n<p>Correos de Espa\u00f1a es la empresa responsable de las entregas, y el importe depende del tipo de env\u00edo elegido<em>. <\/em>Su funci\u00f3n es <em>\u201c<\/em>facilitar el enlace de las tarifas y productos para elegir el que m\u00e1s convenga\u201d.<\/p>\n<p>En su\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.correos.es\/es\/es\/atencion-al-cliente\/especial-covid-19\/admision-internacional-de-correspondencia-y-paqueteria\">lista de admisi\u00f3n\u00a0<\/a>disponible de correspondencia y paqueter\u00eda aparece La Habana.<\/p>\n<p>Sobre las\u00a0tarifas de Correos de Espa\u00f1a enmarca a Cuba en la \u201czona C\u201d por corresponder a Am\u00e9rica y ofrece tres categor\u00edas desde la econ\u00f3mica, pasando por la est\u00e1ndar hasta la <em>premium<\/em> con costos que oscilan de 30 euros por un kilogramo hasta 75 euros por el mismo peso en \u201ccondiciones preferentes\u201d.<\/p>\n<p>Todo ello arriba a las manos del Correos de Cuba por v\u00eda mar\u00edtima, y por v\u00eda a\u00e9rea s\u00f3lo se despacha a Cuba desde Espa\u00f1a la mensajer\u00eda expresa.<\/p>\n<p>Las cargas de paqueter\u00eda llegan a Cuba \u201cfundamentalmente por v\u00eda mar\u00edtima, tramitadas en su mayor\u00eda por la Agencia Fern\u00e1ndez de Sola (AFS)\u201d.<\/p>\n<p>A ra\u00edz de la pandemia, los env\u00edos tardan 21 d\u00edas en la traves\u00eda, y al llegar a Cuba son procesados por las transitarias cubanas que generalmente demoran menos de 30 d\u00edas m\u00e1s en consignarlas a sus destinatarios.<\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><\/p>\n<p><em> &#8221; Fuentes panampost.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pedro S\u00e1nchez, presidente del Gobierno Espa\u00f1ol en su encuentro hace dos a\u00f1os con el dictador cubano Miguel D\u00edaz-Canel. (Twitter) Mantener el flujo de viajeros de Cuba a Espa\u00f1a sin contratiempos comprueban las estrechas relaciones del Gobierno socialista de Pedro S\u00e1nchez con la dictadura cubana. El Consulado de Espa\u00f1a en La Habana anunci\u00f3 que permite viajar [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":103697,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[39],"tags":[],"class_list":["post-103696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-viajes"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/103696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=103696"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/103696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/103697"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=103696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=103696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=103696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}