{"id":103592,"date":"2021-03-28T15:02:14","date_gmt":"2021-03-28T15:02:14","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=103592"},"modified":"2021-03-28T15:02:14","modified_gmt":"2021-03-28T15:02:14","slug":"piden-priorizar-a-trabajadores-de-transporte-maritimo-y-aereo-para-vacuna-covid-19","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/piden-priorizar-a-trabajadores-de-transporte-maritimo-y-aereo-para-vacuna-covid-19\/","title":{"rendered":"Piden priorizar a trabajadores de transporte mar\u00edtimo y a\u00e9reo para vacuna COVID-19"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p>Aunque son esenciales en el engranaje de la econom\u00eda y la vida moderna, <strong>los trabajadores de transportes mar\u00edtimos y a\u00e9reos carecen de la protecci\u00f3n adecuada para los riesgos que asumen<\/strong>. Cinco agencias de la ONU urgen a los pa\u00edses a incluirlos en la lista prioritaria para recibir la <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.televisa.com\/noticias\/tag\/coronavirus\/\"><strong>vacuna COVID-19<\/strong><\/a>.<\/p>\n<p><strong><span style=\"color: #ff0000;\">Te recomendamos:<\/span> <a rel=\"nofollow noopener\" target=\"_blank\" class=\"row-title\" href=\"https:\/\/www.televisa.com\/noticias\/como-afecta-a-tu-bolsillo-el-cierre-del-canal-de-suez\/\" aria-label=\"\u201c\u00bfC\u00f3mo afecta a tu bolsillo el cierre del canal de Suez?\u201d (Editar)\">\u00bfC\u00f3mo afecta a tu bolsillo el cierre del canal de Suez?<\/a><\/strong><\/p>\n<p>Los transportes mar\u00edtimo y a\u00e9reo <strong>son cruciales para el comercio y la movilidad del mundo de hoy. De su buen funcionamiento dependen las cadenas globales de suministro de bienes y servicios<\/strong>, as\u00ed como la ayuda humanitaria. Aunque son esenciales en el engranaje de la econom\u00eda y la vida moderna, los trabajadores de estos sectores carecen de la protecci\u00f3n adecuada para los riesgos que asumen.<\/p>\n<p><strong>M\u00e1s del 80% del comercio mundial es posible gracias a la labor de dos millones de marinos que operan la flota de buques mercantes<\/strong>, mientras que el <strong>transporte a\u00e9reo representa el 35% del valor de las mercanc\u00edas<\/strong> enviadas en todos los modos combinados y hasta 2019 empleaba a 887.000 profesionales con licencia: pilotos, controladores de tr\u00e1fico a\u00e9reo y t\u00e9cnicos de mantenimiento.<\/p>\n<p>Todos estos empleados son <strong>trabajadores esenciales<\/strong> porque sin ellos el comercio y la econom\u00eda del mundo globalizado de hoy se paralizar\u00eda con consecuencias que agudizar\u00edan la disaster derivada de la pandemia de COVID-19.<\/p>\n<p>Adem\u00e1s, <strong>su labor es elementary para la recuperaci\u00f3n socioecon\u00f3mica<\/strong>, afirmaron cinco agencias de la ONU, conminando a todos los pa\u00edses a incluir a este colectivo en las listas prioritarias de vacunaci\u00f3n contra el COVID-19.<\/p>\n<p>En una declaraci\u00f3n conjunta, la Organizaci\u00f3n de Aviaci\u00f3n Civil Internacional (OACI), la Organizaci\u00f3n Internacional del Trabajo (OIT), la Organizaci\u00f3n Mar\u00edtima Internacional (OMI), la Organizaci\u00f3n Internacional para las Migraciones (OIM) y la Organizaci\u00f3n Mundial de la Salud (OMS) r<strong>ecordaron que el transporte por mar y por aire depende de la gente de mar y la tripulaci\u00f3n a\u00e9rea.<\/strong><\/p>\n<h2>A trav\u00e9s de las fronteras<\/h2>\n<blockquote>\n<p>\u201cSon trabajadores clave que deben viajar a trav\u00e9s de las fronteras en todo momento, lo que puede resultar en la necesidad de que presenten prueba de una vacuna COVID-19 como condici\u00f3n para la entrada en algunos pa\u00edses\u201d, apuntaron, aclarando que la OMS ha desaconsejado ese requerimiento porque todav\u00eda no se conoce con precisi\u00f3n la eficacia de la vacunaci\u00f3n para reducir la transmisi\u00f3n y por la disponibilidad limitada de vacunas.<\/p>\n<\/blockquote>\n<div style=\"width: 1290px\" class=\"wp-caption alignnone\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/scontent.ftlc1-1.fna.fbcdn.net\/v\/t1.15752-9\/164472034_1090843011412814_8381833762148804990_n.jpg?_nc_cat=110&amp;_nc_map=test-rt&amp;ccb=1-3&amp;_nc_sid=ae9488&amp;_nc_eui2=AeEVqegHlc8-611yI3lsvnU5XelH1ptAeXxd6UfWm0B5fP-bFJ8R81A4bd2BKqlobeUb4jLfLnKH42ExO8W4sur_&amp;_nc_ohc=I0HZ_dSZk2gAX-Hcg7Q&amp;_nc_ht=scontent.ftlc1-1.fna&amp;oh=d17fe52c3feafad284931c4a5809ac58&amp;oe=6085C7A1\" alt=\"Sin descripci\u00f3n disponible.\" width=\"1280\" height=\"720\"\/><\/p>\n<p class=\"wp-caption-text\">El sector a\u00e9reo fue muy afectado por las restricciones derivadas de la pandemia. FOTO: Pixabay.<\/p>\n<\/div>\n<p>Para que los sectores mar\u00edtimo y a\u00e9reo sigan operando de forma segura, <strong>se debe facilitar el movimiento transfronterizo seguro de la gente de mar y la tripulaci\u00f3n a\u00e9rea<\/strong>, por ello, los organismos del sistema de las Naciones Unidas urgieron a los pa\u00edses a sumar a estos trabajadores a la categor\u00eda de esenciales.<\/p>\n<blockquote>\n<p>\u201cUrgimos a los gobiernos a que prioricen a la gente de mar y a la tripulaci\u00f3n a\u00e9rea en sus programas nacionales de vacunaci\u00f3n contra COVID-19 junto con otros trabajadores esenciales, de acuerdo con el consejo de la OMS para determinar el uso de esas inmunizaciones en el contexto de oferta limitada\u201d, recalcaron, refiri\u00e9ndose a la Hoja de Ruta SAGE de la OMS publicada en noviembre pasado.<\/p>\n<p>\u201cLa gente de mar y la tripulaci\u00f3n a\u00e9rea deben estar protegidos mediante la vacunaci\u00f3n lo antes posible, para facilitar su movimiento seguro a trav\u00e9s de las fronteras\u201d, a\u00f1adieron las agencias.<\/p>\n<\/blockquote>\n<h2>Estrategias adecuadas<\/h2>\n<p>Asimismo,<strong> recomendaron a los gobiernos que identifiquen los desaf\u00edos de la inmunizaci\u00f3n de la gente de mar y la tripulaci\u00f3n a\u00e9rea<\/strong>, en specific de los marineros que pasan periodos largos fuera de su pa\u00eds de origen, y que dise\u00f1en estrategias adecuadas.<\/p>\n<blockquote>\n<p>\u201cNuestras organizaciones apoyan plenamente el desarrollo oportuno de un marco internacional armonizado para los certificados de vacunaci\u00f3n con el fin de facilitar los viajes internacionales de la gente de mar y la tripulaci\u00f3n a\u00e9rea\u201d, declararon.<\/p>\n<\/blockquote>\n<p>La <strong>gente de mar ha sido muy afectada por las restricciones de viaje impuestas durante la pandemia<\/strong>. En enero de 2021 se calcul\u00f3 que unos <strong>400 mil marinos est\u00e1n varados a bordo de buques comerciales,<\/strong> mucho despu\u00e9s de la expiraci\u00f3n de sus contratos, sin poder ser repatriados. Un n\u00famero comparable de marinos necesita con urgencia unirse a los barcos para reemplazarlos.<\/p>\n<p>Por su parte, <strong>la tripulaci\u00f3n a\u00e9rea padeci\u00f3 la aplicaci\u00f3n de estrictas reglas de salud p\u00fablica<\/strong>, incluida la cuarentena, lo que cre\u00f3 problemas de conectividad, complejidad operativa y costos significativos para el sector. El sector a\u00e9reo de pasajeros transport\u00f3 alrededor de 5,700 millones de pasajeros en 2019.<\/p>\n<p><em>Con informaci\u00f3n de ONU Noticias<\/em><\/p>\n<p>DMGS<\/p>\n<\/p><\/div>\n\n<p><em> &#8221; Fuentes www.televisa.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aunque son esenciales en el engranaje de la econom\u00eda y la vida moderna, los trabajadores de transportes mar\u00edtimos y a\u00e9reos carecen de la protecci\u00f3n adecuada para los riesgos que asumen. Cinco agencias de la ONU urgen a los pa\u00edses a incluirlos en la lista prioritaria para recibir la vacuna COVID-19. Te recomendamos: \u00bfC\u00f3mo afecta a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":103593,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[40],"tags":[],"class_list":["post-103592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industria"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/103592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=103592"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/103592\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/103593"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=103592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=103592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=103592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}