{"id":103589,"date":"2021-03-28T14:54:00","date_gmt":"2021-03-28T14:54:00","guid":{"rendered":"https:\/\/dimensionturistica.com\/es\/?p=103589"},"modified":"2021-03-28T14:54:01","modified_gmt":"2021-03-28T14:54:01","slug":"mato-a-un-agente-de-la-dea-y-hoy-es-uno-de-los-profugos-mas-buscados-que-sabemos-de-la-ubicacion-de-caro-quintero-el-narco-de-narcos","status":"publish","type":"post","link":"https:\/\/dimensionturistica.com\/es\/mato-a-un-agente-de-la-dea-y-hoy-es-uno-de-los-profugos-mas-buscados-que-sabemos-de-la-ubicacion-de-caro-quintero-el-narco-de-narcos\/","title":{"rendered":"Mat\u00f3 a un agente de la DEA y hoy es uno de los pr\u00f3fugos m\u00e1s buscados: qu\u00e9 sabemos de la ubicaci\u00f3n de Caro Quintero, el \u201cNarco de narcos\u201d"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<div class=\"visual__image  image_container\"><img decoding=\"async\" alt=\"El gobierno de Estados Unidos ubic\u00f3 a Rafael Caro Quintero como su principal objetivo (Foto: PFP\/Cuartoscuro)\" height=\"1080\" width=\"1920\" src=\"https:\/\/www.infobae.com\/new-resizer\/Xq2FHZ5vu-wsDuHpj_KGbDTMNzk=\/420x236\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/BSBUISLPSJCH3G34H6CUTMSAGE.jpg\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/Xq2FHZ5vu-wsDuHpj_KGbDTMNzk=\/420x236\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/BSBUISLPSJCH3G34H6CUTMSAGE.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/6KjGe5P4AxUC-g6fIaMbXqzWF-8=\/768x432\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/BSBUISLPSJCH3G34H6CUTMSAGE.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/pu4YQJrieggyHQ2U3GBGPIiguNM=\/992x558\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/BSBUISLPSJCH3G34H6CUTMSAGE.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/Nzm32J86f-mJxNaoEvDfgSvP280=\/1200x675\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/BSBUISLPSJCH3G34H6CUTMSAGE.jpg 1200w\" sizes=\"(min-width: 800px) 50vw, 90vw\"\/><figcaption>El gobierno de Estados Unidos ubic\u00f3 a Rafael Caro Quintero como su principal objetivo (Foto: PFP\/Cuartoscuro)<\/figcaption><\/div>\n<p class=\"paragraph\">Cuando nadie pensaba en \u00e9l, la noticia apareci\u00f3. El gobierno de Estados Unidos ubic\u00f3 a <b>Rafael Caro Quintero<\/b> como su principal objetivo: baj\u00f3 del primer lugar de su lista de los diez fugitivos m\u00e1s buscados a<b> Nemesio Oseguera, <\/b><i><b>El Mencho<\/b><\/i> \u2014l\u00edder del <b>C\u00e1rtel Jalisco Nueva Generaci\u00f3n <\/b>(CJNG)\u2014 y coloc\u00f3 en su lugar al <i><b>Narco de Narcos<\/b><\/i>.<\/p>\n<p class=\"paragraph\">Caro Quintero o <i>Rafail <\/i>\u2014como es conocido en<b> Badiraguato, Sinaloa<\/b>, seg\u00fan el semanario <i>R\u00edo Doce<\/i>\u2014 tiene una cita en EEUU a la que no quiere ir. Hace 35 a\u00f1os, el capo fue aprehendido por la tortura y asesinato del agente de la DEA, <b>Enrique <\/b><i><b>Kiki<\/b><\/i><b> Camarena<\/b>.<\/p>\n<p class=\"paragraph\">Como se sabe, pas\u00f3 28 a\u00f1os en una prisi\u00f3n mexicana, hasta el 8 de agosto de 2013 cuando fue liberado gracias a un amparo firmado por un Tribunal Colegiado en Materia Penal del Tercer Circuito del Estado de Jalisco.<\/p>\n<div class=\"visual__image  image_container\"><img decoding=\"async\" alt=\"Rafael Caro Quintero se convirti\u00f3 en el narco m\u00e1s buscado por la Agencia de Administraci\u00f3n de Control de Drogas de Estados Unidos (Foto: dea.gov\/fugitives)\" height=\"527\" width=\"978\" src=\"https:\/\/www.infobae.com\/new-resizer\/j5eCTk9cFxhxDC7RPmNWlhAfGtA=\/420x236\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/NEOVO7XQ2BHJHLXOI2AUAXKXN4.png\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/j5eCTk9cFxhxDC7RPmNWlhAfGtA=\/420x236\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/NEOVO7XQ2BHJHLXOI2AUAXKXN4.png 420w,https:\/\/www.infobae.com\/new-resizer\/OUj2gOcP8yKu6acutq1k_GXVpOQ=\/768x432\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/NEOVO7XQ2BHJHLXOI2AUAXKXN4.png 768w,https:\/\/www.infobae.com\/new-resizer\/9hg2z8Of_1Jb8m55IwBO33g_0aA=\/992x558\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/NEOVO7XQ2BHJHLXOI2AUAXKXN4.png 992w,https:\/\/www.infobae.com\/new-resizer\/nRJ4IeBi1EM6rvT7m3V4gRNNgEo=\/1200x675\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/NEOVO7XQ2BHJHLXOI2AUAXKXN4.png 1200w\" sizes=\"(min-width: 800px) 50vw, 90vw\"\/><figcaption>Rafael Caro Quintero se convirti\u00f3 en el narco m\u00e1s buscado por la Agencia de Administraci\u00f3n de Management de Drogas de Estados Unidos (Foto: dea.gov\/fugitives)<\/figcaption><\/div>\n<p class=\"paragraph\">Ese d\u00eda,<b> Caro abord\u00f3 una camioneta oscura y desapareci\u00f3<\/b>. Aunque pronto ofreci\u00f3 una entrevista y mand\u00f3 a decir que \u201cquer\u00eda vivir en paz\u201d, el <i>Narco de narcos<\/i> habr\u00eda enviado fuertes se\u00f1ales de su regreso al hampa de M\u00e9xico.<\/p>\n<p class=\"paragraph\"><b>Por su captura, la DEA ofrece USD 20 millones<\/b>. Esa medida, junto con otras sequence de acciones, tienen a\u00f1os ocurriendo en el pa\u00eds vecino del norte, incluyendo arrestos de al menos seis hom\u00f3nimos del l\u00edder del <b>C\u00e1rtel de Sinaloa<\/b>, quienes tras probar que no eran el Rafael Caro Quintero que buscaban los estadounidenses, fueron puestos en libertad.<\/p>\n<p class=\"paragraph\">En 2019, la determinaci\u00f3n por capturar a <i>Rafa<\/i> lleg\u00f3 a trav\u00e9s de una moci\u00f3n judicial, que actualmente se encuentra en proceso, para<b> asegurar ocho propiedades que el capo adquiri\u00f3 en Jalisco<\/b> tras salir de prisi\u00f3n. Seg\u00fan las autoridades estadounidenses, los inmuebles fueron adquiridos con dinero de sus actividades del narcotr\u00e1fico.<\/p>\n<div class=\"visual__image  image_container\"><img decoding=\"async\" alt=\"Con informaci\u00f3n del semanario R\u00edo Doce, el viaje ex profeso que habr\u00eda realizado Caro Quintero el pasado mes de mayo (Mapa: Infobae M\u00e9xico)\" height=\"1080\" width=\"1920\" src=\"https:\/\/www.infobae.com\/new-resizer\/xoGZzMzphUw77tStAeT0oNhefiA=\/420x236\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ODCNKVUEP5DDFDMBSAULY5DG3E.gif\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/xoGZzMzphUw77tStAeT0oNhefiA=\/420x236\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ODCNKVUEP5DDFDMBSAULY5DG3E.gif 420w,https:\/\/www.infobae.com\/new-resizer\/DILDHksplVDhCfN1AF2ONEC5bHo=\/768x432\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ODCNKVUEP5DDFDMBSAULY5DG3E.gif 768w,https:\/\/www.infobae.com\/new-resizer\/Td8PKa4YsL4_hyTB_LhAh1pPb0k=\/992x558\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ODCNKVUEP5DDFDMBSAULY5DG3E.gif 992w,https:\/\/www.infobae.com\/new-resizer\/GWDxkGS4qe7Uy3NKNYd9G3gfpIw=\/1200x675\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/ODCNKVUEP5DDFDMBSAULY5DG3E.gif 1200w\" sizes=\"(min-width: 800px) 50vw, 90vw\"\/><figcaption>Con informaci\u00f3n del semanario R\u00edo Doce, el viaje ex profeso que habr\u00eda realizado Caro Quintero el pasado mes de mayo (Mapa: Infobae M\u00e9xico)<\/figcaption><\/div>\n<p class=\"paragraph\">El gobierno de Estados Unidos no ha escatimado esfuerzos en atrapar a su enemigo p\u00fablico n\u00famero uno. Adem\u00e1s de la DEA, las agencias del FBI, ICE, ATF, Interpol, y Homeland Safety han encabezado una cacer\u00eda contra Caro Quintero.<\/p>\n<p class=\"paragraph\"><mark class=\"hl_orange\"><b>Tras los pasos del <\/b><i><b>Narco de narcos<\/b><\/i><\/mark><\/p>\n<p class=\"paragraph\">Seg\u00fan investigaciones del semanario de Sinaloa, <i>R\u00edo Doce<\/i>, luego de su salida de la c\u00e1rcel, <b>el legendario capo mantuvo vivos sus intereses en la frontera norte de M\u00e9xico y conserv\u00f3 el management en un territorio<\/b>:<b> Sonora<\/b>.<\/p>\n<p class=\"paragraph\">Fue en ese estado, en el <b>municipio de Caborca<\/b>, donde Caro Quintero habr\u00eda viajado a mediados de mayo pasado, seg\u00fan detalla <i>R\u00edo Doce<\/i>. Posteriormente, el fundador del extinto C\u00e1rtel de Guadalajara, se habr\u00eda dirigido a <b>San Luis R\u00edo Colorado, Sonora<\/b>, y finalmente a <b>Tijuana, Baja California, <\/b>para reunirse con capos del narco que operan en la zona.<\/p>\n<div class=\"visual__image  image_container\"><img decoding=\"async\" alt=\"Imagen del municipio de Caborca: el &quot;Narco de Narcos&quot; conserv\u00f3 el control de un territorio que le perteneci\u00f3 desde siempre (Foto: Twitter\/@PespSonora)&#10;\" height=\"1080\" width=\"1920\" src=\"https:\/\/www.infobae.com\/new-resizer\/3HhfMnojLpki5wVhH4TNbSiDmx0=\/420x236\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/353OZDHCXJFLLGTFU2RFBJIEKQ.jpg\" srcset=\"https:\/\/www.infobae.com\/new-resizer\/3HhfMnojLpki5wVhH4TNbSiDmx0=\/420x236\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/353OZDHCXJFLLGTFU2RFBJIEKQ.jpg 420w,https:\/\/www.infobae.com\/new-resizer\/1VBfH6JBwBrsnfwGmOG5eZjM0Rc=\/768x432\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/353OZDHCXJFLLGTFU2RFBJIEKQ.jpg 768w,https:\/\/www.infobae.com\/new-resizer\/l4IWZ9l9at66EWOIvj0e5jW4Ru0=\/992x558\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/353OZDHCXJFLLGTFU2RFBJIEKQ.jpg 992w,https:\/\/www.infobae.com\/new-resizer\/3Qg17L5ZxE9K3MPQ3i-Yj9NWfe8=\/1200x675\/filters:format(jpg):quality(85)\/cloudfront-us-east-1.images.arcpublishing.com\/infobae\/353OZDHCXJFLLGTFU2RFBJIEKQ.jpg 1200w\" sizes=\"(min-width: 800px) 50vw, 90vw\"\/><figcaption>Imagen del municipio de Caborca: el &#8220;Narco de Narcos&#8221; conserv\u00f3 el management de un territorio que le perteneci\u00f3 desde siempre (Foto: Twitter\/@PespSonora)<br \/>\n<\/figcaption><\/div>\n<p class=\"paragraph\"><b>Su objetivo<\/b>, de acuerdo con el semanario, <b>period establecer rutas de narcotr\u00e1fico, adquisici\u00f3n y forma de traslado de armamento de la frontera con Estados Unidos a Sinaloa<\/b>.<\/p>\n<p class=\"paragraph\">El viaje de Caro Quintero tambi\u00e9n obedec\u00eda a un importante inter\u00e9s: <b>destrabar conflictos que exist\u00edan entre su gente<\/b> \u2014 refiri\u00e9ndose a <b>Rodrigo P\u00e1ez Quintero, <\/b><i><b>El R<\/b><\/i>, su primo\u2014 y <b>Jos\u00e9 Crisp\u00edn Salazar Zamorano<\/b>, uno de los l\u00edderes de <b>Los Salazar<\/b> y presunto operador de <b>Los Chapitos<\/b>.<\/p>\n<p class=\"paragraph\">Contrario a lo que relata la prensa mexicana e investigaciones de car\u00e1cter federal, <i>Rafa<\/i>, <i>Rafail<\/i>,<i> Don Rafa<\/i> y\/o el <i>Narco de Narcos<\/i>, no se encuentra en disputa ni con los hijos de <b>Joaqu\u00edn <\/b><i><b>El Chapo<\/b><\/i><b> Guzm\u00e1n<\/b>, ni con su socio <b>Ismael Zambada Garc\u00eda, <\/b><i><b>El Mayo,<\/b><\/i> por el contrario, el capo regres\u00f3 para encargarse de su propia facci\u00f3n.<\/p>\n<p class=\"paragraph\"><mark class=\"hl_orange\"><b>M\u00c1S SOBRE OTROS TEMAS:<\/b><\/mark><\/p>\n<div class=\"text-element\"><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.infobae.com\/america\/mexico\/2021\/02\/13\/un-juez-dicto-un-auto-de-formal-prision-miss-oaxaca-2018\/\"><i><b>Un juez dict\u00f3 un auto de formal prisi\u00f3n a Miss Oaxaca 2018<\/b><\/i><\/a><\/div>\n<div class=\"text-element\"><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.infobae.com\/america\/mundo\/2021\/02\/14\/una-pareja-tiene-once-hijos-pero-no-se-conforma-suenan-con-llegar-a-105-y-ser-la-familia-mas-numerosa-del-mundo\/\"><i><b>Una pareja tiene once hijos pero no se conforma: sue\u00f1an con llegar a 105 y ser la familia m\u00e1s numerosa del mundo<\/b><\/i><\/a><\/div>\n<div class=\"text-element\"><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.infobae.com\/america\/deportes\/2021\/02\/14\/mike-tyson-revelo-como-fue-la-maraton-sexual-que-provoco-la-primera-derrota-de-su-carrera\/\"><i><b>Mike Tyson revel\u00f3 c\u00f3mo fue la marat\u00f3n sexual que provoc\u00f3 la primera derrota de su carrera<\/b><\/i><\/a><\/div>\n<div class=\"text-element\"><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.infobae.com\/america\/mexico\/2021\/02\/14\/moringa-estudio-de-la-unam-revela-los-beneficios-reales-del-arbol-mexicano\/\"><i><b>Moringa: estudio de la UNAM revela los beneficios reales del \u00e1rbol mexicano<\/b><\/i><\/a><\/div>\n<\/div>\n<p><script defer=\"\">!function(f,b,e,v,n,t,s) {if(f.fbq)return;n=f.fbq=function(){n.callMethod? n.callMethod.apply(n,arguments):n.queue.push(arguments)}; if(!f._fbq)f._fbq=n;n.push=n;n.loaded=!0;n.version='2.0'; n.queue=[];t=b.createElement(e);t.async=!0; t.src=v;s=b.getElementsByTagName(e)[0]; s.parentNode.insertBefore(t,s)}(window, document,'script', 'https:\/\/connect.facebook.net\/en_US\/fbevents.js'); fbq('init', '336383993555320'); fbq('track', 'PageView'); fbq('track', 'ViewContent');<\/script><br \/>\n<br \/><\/p>\n<p><em> &#8221; Fuentes www.infobae.com &#8221; <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno de Estados Unidos ubic\u00f3 a Rafael Caro Quintero como su principal objetivo (Foto: PFP\/Cuartoscuro) Cuando nadie pensaba en \u00e9l, la noticia apareci\u00f3. El gobierno de Estados Unidos ubic\u00f3 a Rafael Caro Quintero como su principal objetivo: baj\u00f3 del primer lugar de su lista de los diez fugitivos m\u00e1s buscados a Nemesio Oseguera, El [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":103590,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"jnews-multi-image_gallery":[],"jnews_single_post":[],"jnews_primary_category":[],"jnews_social_meta":[],"footnotes":""},"categories":[40],"tags":[],"class_list":["post-103589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-industria"],"_links":{"self":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/103589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/comments?post=103589"}],"version-history":[{"count":0,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/posts\/103589\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media\/103590"}],"wp:attachment":[{"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/media?parent=103589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/categories?post=103589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimensionturistica.com\/es\/wp-json\/wp\/v2\/tags?post=103589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}